{"id":98016,"date":"2026-09-02T15:19:18","date_gmt":"2026-09-02T18:19:18","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=98016"},"modified":"2026-09-02T15:19:19","modified_gmt":"2026-09-02T18:19:19","slug":"estado-convoca-369-tecnicos-de-nivel-medio-aprovados-em-processo-seletivo","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/estado-convoca-369-tecnicos-de-nivel-medio-aprovados-em-processo-seletivo\/","title":{"rendered":"Estado convoca 369 t\u00e9cnicos de n\u00edvel m\u00e9dio aprovados em processo seletivo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy \u2013 BEC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#x1f4f2;\u00a0<a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Siga o canal do BEC no WhatsApp<\/mark><\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/09\/Secretaria-de-Educacao-da-Bahia-SEC.png\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/09\/Secretaria-de-Educacao-da-Bahia-SEC.png?resize=768%2C512\" alt=\"\" class=\"wp-image-98017\" style=\"width:663px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/09\/Secretaria-de-Educacao-da-Bahia-SEC.png?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/09\/Secretaria-de-Educacao-da-Bahia-SEC.png?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>&#x1f4f7; Secretaria de Educa\u00e7\u00e3o da Bahia (SEC)<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria da Educa\u00e7\u00e3o do Estado (SEC) publicou, no Di\u00e1rio Oficial do Estado desta quarta-feira (2), a convoca\u00e7\u00e3o de 369 candidatos aprovados no Processo Seletivo Simplificado REDA, referente ao Edital SEC\/SUDEPE n\u00ba 004\/2026, que selecionou t\u00e9cnicos de n\u00edvel m\u00e9dio. A convoca\u00e7\u00e3o decorre da necessidade de recomposi\u00e7\u00e3o e fortalecimento do quadro funcional da pasta para assegurar a continuidade das atividades administrativas e t\u00e9cnicas essenciais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta \u00e9 a primeira de uma s\u00e9rie de convoca\u00e7\u00f5es a serem realizadas ao longo do ano para preencher as 2.500 vagas divulgadas no edital. Os convocados ser\u00e3o distribu\u00eddos entre diferentes Territ\u00f3rios de Identidade do Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00ednculo contratual ter\u00e1 dura\u00e7\u00e3o de 36 meses, prorrog\u00e1vel por igual per\u00edodo. A jornada \u00e9 de 40 horas semanais. A remunera\u00e7\u00e3o ser\u00e1 estabelecida de acordo com o Edital n\u00b0 004\/2026 e ser\u00e1 composta por vencimento b\u00e1sico no valor de R$ 1.532,58, acrescido de Gratifica\u00e7\u00e3o de Fun\u00e7\u00e3o Tempor\u00e1ria, no valor de R$ 1.484,76, perfazendo o total de R$ 3.017,34.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os convocados devem entregar a documenta\u00e7\u00e3o necess\u00e1ria no per\u00edodo de 3 a 17 de setembro. Alguns dos documentos solicitados s\u00e3o o diploma de forma\u00e7\u00e3o compat\u00edvel com a fun\u00e7\u00e3o, carteira de identidade, CPF, comprovante de resid\u00eancia, declara\u00e7\u00e3o de inexist\u00eancia de ac\u00famulo de cargos p\u00fablicos e certid\u00f5es negativas. Para uma an\u00e1lise preliminar conduzida pela Coordena\u00e7\u00e3o de Provimento e Movimenta\u00e7\u00e3o (CPM), os documentos devem ser enviados digitalizados para o e-mail <a href=\"mailto:ingressocpm.sec@enova.educacao.ba.gov.br\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">ingressocpm.sec@enova.educacao.ba.gov.br<\/mark><\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s esta etapa, a documenta\u00e7\u00e3o original precisar\u00e1 ser entregue presencialmente nas sedes dos N\u00facleos Territoriais de Educa\u00e7\u00e3o (NTEs), acompanhada de c\u00f3pias para confer\u00eancia. Em Salvador, os convocados dever\u00e3o comparecer \u00e0 sede da SEC, no Centro Administrativo da Bahia (CAB), das 8h30 \u00e0s 11h, e das 14h \u00e0s 17h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog do Eloilton Cajuhy \u2013 BEC &#x1f4f2;\u00a0Siga o canal do BEC no WhatsApp A Secretaria da Educa\u00e7\u00e3o do Estado (SEC) publicou, no Di\u00e1rio Oficial do Estado desta quarta-feira (2), a convoca\u00e7\u00e3o de 369 candidatos aprovados no Processo Seletivo Simplificado REDA, referente ao Edital SEC\/SUDEPE n\u00ba 004\/2026, que selecionou t\u00e9cnicos de n\u00edvel m\u00e9dio. A convoca\u00e7\u00e3o decorre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":98017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[],"class_list":["post-98016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/09\/Secretaria-de-Educacao-da-Bahia-SEC.png?fit=768%2C512&ssl=1","_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/98016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=98016"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/98016\/revisions"}],"predecessor-version":[{"id":98018,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/98016\/revisions\/98018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/98017"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=98016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=98016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=98016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}