{"id":96916,"date":"2026-07-15T13:27:29","date_gmt":"2026-07-15T16:27:29","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=96916"},"modified":"2026-07-15T13:27:31","modified_gmt":"2026-07-15T16:27:31","slug":"prefeitura-de-riachao-do-jacuipe-abre-concurso-com-mais-de-90-vagas-salarios-chegam-a-r-25-mil","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/prefeitura-de-riachao-do-jacuipe-abre-concurso-com-mais-de-90-vagas-salarios-chegam-a-r-25-mil\/","title":{"rendered":"Prefeitura de Riach\u00e3o do Jacu\u00edpe abre concurso com mais de 90 vagas; sal\u00e1rios chegam a R$ 2,5 mil"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Inscri\u00e7\u00f5es para certame podem ser feitas at\u00e9 o dia 13 de agosto, exclusivamente pela internet<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy \u2013 BEC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">&#x1f4f2; Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg?resize=800%2C534\" alt=\"\" class=\"wp-image-91273\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>&#x1f4f7; Freepik<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Prefeitura de Riach\u00e3o do Jacu\u00edpe abriu um concurso p\u00fablico com 92 vagas para cargos de n\u00edveis m\u00e9dio e superior, al\u00e9m de 108 oportunidades para forma\u00e7\u00e3o de cadastro de reserva. Os sal\u00e1rios variam entre R$ 1,8 e R$ 2,5 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es poder\u00e3o ser feitas at\u00e9 o dia 13 de agosto, <a href=\"https:\/\/flemconcursos.org.br\/home.php?pagina=principal\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">exclusivamente pela internet<\/mark><\/strong><\/a>. As taxas custam entre R$ 120 e R$ 150. Candidatos inscritos no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico) poder\u00e3o solicitar isen\u00e7\u00e3o da taxa at\u00e9 21 de julho.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-87b9645ebe9e23fd86e2039f9f75e640 wp-block-paragraph\"><strong>As oportunidades s\u00e3o para os seguintes cargos:<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-eae4eeab3e977792242dd70013acff70 wp-block-paragraph\"><strong>N\u00edvel m\u00e9dio<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Agente de Tr\u00e2nsito (3 vagas);<\/li>\n\n\n\n<li>Fiscal de Postura e Obras (3);<\/li>\n\n\n\n<li>Fiscal de Tributos (3);<\/li>\n\n\n\n<li>Guarda Civil Municipal masculino (25);<\/li>\n\n\n\n<li>Guarda Civil Municipal feminino (5).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-caf1aba8b1a12bd8a2dcad0703e732fb wp-block-paragraph\"><strong>N\u00edvel superior<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Professor de Braille (1);<\/li>\n\n\n\n<li>Professor de Ci\u00eancias Biol\u00f3gicas (1);<\/li>\n\n\n\n<li>Professor de Educa\u00e7\u00e3o F\u00edsica (2);<\/li>\n\n\n\n<li>Professor de Geografia (1);<\/li>\n\n\n\n<li>Professor de Ingl\u00eas (2);<\/li>\n\n\n\n<li>Professor de Hist\u00f3ria (1);<\/li>\n\n\n\n<li>Professor de Matem\u00e1tica (3);<\/li>\n\n\n\n<li>Professor de S\u00e9ries Iniciais (40);<\/li>\n\n\n\n<li>Professor de Atendimento Educacional Especializado (AEE) (1);<\/li>\n\n\n\n<li>Fonoaudi\u00f3logo (1).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a prefeitura, a carga hor\u00e1ria \u00e9 de 40 horas semanais para os cargos de n\u00edvel m\u00e9dio e de 20 horas para os de n\u00edvel superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sele\u00e7\u00e3o ser\u00e1 feita atrav\u00e9s de prova objetiva para todos os cargos, prevista para 30 de agosto. Os candidatos aos cargos de n\u00edvel superior e \u00e0 Guarda Civil Municipal tamb\u00e9m passar\u00e3o por avalia\u00e7\u00e3o de t\u00edtulos. Para a Guarda Civil, o concurso ainda prev\u00ea teste de aptid\u00e3o f\u00edsica, avalia\u00e7\u00e3o psicol\u00f3gica e curso de forma\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso ter\u00e1 validade de dois anos podendo ser prorrogado pelo mesmo per\u00edodo. O edital completo e o cronograma est\u00e3o dispon\u00edveis no <a href=\"https:\/\/flemconcursos.org.br\/home.php?pagina=principal\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">site da organizadora do certame<\/mark><\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es para certame podem ser feitas at\u00e9 o dia 13 de agosto, exclusivamente pela internet Blog do Eloilton Cajuhy \u2013 BEC &#x1f4f2; Siga o canal do BEC no WhatsApp A Prefeitura de Riach\u00e3o do Jacu\u00edpe abriu um concurso p\u00fablico com 92 vagas para cargos de n\u00edveis m\u00e9dio e superior, al\u00e9m de 108 oportunidades para forma\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[32],"tags":[],"class_list":["post-96916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprego"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/11\/Enem-Concursos-Foto-Freepik.jpg?fit=1000%2C667&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/96916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=96916"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/96916\/revisions"}],"predecessor-version":[{"id":96917,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/96916\/revisions\/96917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/91273"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=96916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=96916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=96916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}