{"id":95916,"date":"2026-05-28T15:30:33","date_gmt":"2026-05-28T18:30:33","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=95916"},"modified":"2026-05-28T15:30:35","modified_gmt":"2026-05-28T18:30:35","slug":"luto-morre-o-empresario-bonfinense-costinha-aos-76-anos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/luto-morre-o-empresario-bonfinense-costinha-aos-76-anos\/","title":{"rendered":"Luto: Morre o empres\u00e1rio bonfinense &#8216;Costinha&#8217;, aos 76 anos"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Figura muito querida em Senhor do Bonfim, Costinha construiu trajet\u00f3ria de trabalho, amizade e dedica\u00e7\u00e3o ao com\u00e9rcio local<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Blog do Eloilton Cajuhy \u2013 BEC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">>> Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-01.jpeg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-01.jpeg?resize=768%2C512&#038;ssl=1\" alt=\"\" class=\"wp-image-95917\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-01.jpeg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-01.jpeg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Empres\u00e1rio Costinha sendo homenageado como destaque, ao lado do ex-prefeito Carlos Brasileiro &#8211; Foto: Arquivo da fam\u00edlia<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Faleceu na tarde desta quinta-feira (28), aos 76 anos, o empres\u00e1rio <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Jos\u00e9 Gon\u00e7alves da Costa<\/mark><\/strong>, carinhosamente conhecido como <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">\u201cCostinha\u201d<\/mark><\/strong>. Natural de Canudos, ele estava radicado em Senhor do Bonfim h\u00e1 muitos anos, cidade onde construiu uma hist\u00f3ria marcada pelo trabalho, empreendedorismo e forte liga\u00e7\u00e3o com a comunidade bonfinense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Costinha era propriet\u00e1rio da tradicional <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Bonfim Pneus<\/mark><\/strong>, empresa bastante conhecida no munic\u00edpio e na regi\u00e3o. Ao longo de d\u00e9cadas de atua\u00e7\u00e3o no com\u00e9rcio, conquistou o respeito, a admira\u00e7\u00e3o e a amizade de in\u00fameras pessoas, sendo reconhecido como um empres\u00e1rio atuante e muito querido em Senhor do Bonfim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele tamb\u00e9m era primo do saudoso ex-prefeito Jonas Costa, mantendo uma liga\u00e7\u00e3o hist\u00f3rica com fam\u00edlias tradicionais da cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com informa\u00e7\u00f5es, Costinha estava internado h\u00e1 cerca de um m\u00eas em um hospital de Feira de Santana, onde faleceu nesta quinta-feira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A not\u00edcia de sua morte traz um forte sentimento de pesar entre familiares e amigos de Senhor do Bonfim, que lamentam a partida de uma personalidade bastante conhecida e respeitada no munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste momento de dor, familiares e amigos recebem as condol\u00eancias e solidariedade de toda a comunidade bonfinense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>BEC<\/strong> manifesta neste momento sua mais sincera solidariedade aos familiares e amigos de Costinha.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-02.jpeg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"596\" height=\"637\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-02.jpeg?resize=596%2C637&#038;ssl=1\" alt=\"\" class=\"wp-image-95918\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-02.jpeg?w=596&amp;ssl=1 596w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-02.jpeg?resize=281%2C300&amp;ssl=1 281w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Arquivo da fam\u00edlia<\/sub><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Figura muito querida em Senhor do Bonfim, Costinha construiu trajet\u00f3ria de trabalho, amizade e dedica\u00e7\u00e3o ao com\u00e9rcio local Por Blog do Eloilton Cajuhy \u2013 BEC >> Siga o canal do BEC no WhatsApp Faleceu na tarde desta quinta-feira (28), aos 76 anos, o empres\u00e1rio Jos\u00e9 Gon\u00e7alves da Costa, carinhosamente conhecido como \u201cCostinha\u201d. Natural de Canudos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-95916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Costinha-02.jpeg?fit=596%2C637&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=95916"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95916\/revisions"}],"predecessor-version":[{"id":95919,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95916\/revisions\/95919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/95918"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=95916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=95916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=95916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}