{"id":95587,"date":"2026-05-13T08:49:27","date_gmt":"2026-05-13T11:49:27","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=95587"},"modified":"2026-05-13T08:49:29","modified_gmt":"2026-05-13T11:49:29","slug":"manifestantes-se-mobilizam-pela-proibicao-do-abate-de-jumentos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/manifestantes-se-mobilizam-pela-proibicao-do-abate-de-jumentos\/","title":{"rendered":"Manifestantes se mobilizam pela proibi\u00e7\u00e3o do abate de jumentos"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>Projeto est\u00e1 em tramita\u00e7\u00e3o na C\u00e2mara desde 2022<\/strong><\/p>\n\n\n\n<p><strong>Por Madson Euler\/R\u00e1dio Nacional<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">>> Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"452\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?resize=800%2C452&#038;ssl=1\" alt=\"\" class=\"wp-image-95588\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?resize=300%2C170&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?resize=768%2C434&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Prote\u00e7\u00e3o Mundial Animal<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Um jumento infl\u00e1vel de tr\u00eas metros foi instalado em Salvador, Bahia, como s\u00edmbolo de uma mobiliza\u00e7\u00e3o p\u00fablica em defesa da preserva\u00e7\u00e3o desses animais e pela aprova\u00e7\u00e3o do projeto de lei que pro\u00edbe, de maneira definitiva, o abate em territ\u00f3rio nacional. O PL 2387\/2022 est\u00e1 em tramita\u00e7\u00e3o na C\u00e2mara desde 2022, mas nunca foi levado \u00e0 pauta para vota\u00e7\u00e3o. No dia 13 de abril, a Justi\u00e7a Federal determinou a suspens\u00e3o do abate.<\/p>\n\n\n\n<p>O infl\u00e1vel ficou por dois dias no Largo do Pelourinho e em frente \u00e0 Assembleia Legislativa da Bahia. A Assembleia recebeu, na semana passada, o Workshop Internacional Jumentos do Brasil, reunindo especialistas, representantes do poder p\u00fablico e organiza\u00e7\u00f5es da sociedade civil para discutir o futuro da esp\u00e9cie no pa\u00eds.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o \u00e9 uma iniciativa de entidades como a Frente Nacional de Defesa dos Jumentos e o F\u00f3rum Nacional de Prote\u00e7\u00e3o e Defesa Animal.<\/p>\n\n\n\n<p>O Brasil perdeu 94% da popula\u00e7\u00e3o de jumentos entre 1996 e 2024, segundo dados de entidades de defesa animal. Ou seja, neste per\u00edodo, de cada 100 animais existentes na d\u00e9cada de 90, restam apenas seis hoje.<\/p>\n\n\n\n<p>Segundo pesquisadores, a diminui\u00e7\u00e3o est\u00e1 ligada principalmente ao abate dos jumentos para a extra\u00e7\u00e3o da pele, que \u00e9 exportada para a China. O pa\u00eds asi\u00e1tico utiliza o col\u00e1geno deste bicho para a produ\u00e7\u00e3o de um produto chamado ejiao, uma subst\u00e2ncia que, mesmo sem comprova\u00e7\u00e3o cient\u00edfica, \u00e9 utilizada como rem\u00e9dio para retardar o envelhecimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Projeto est\u00e1 em tramita\u00e7\u00e3o na C\u00e2mara desde 2022 Por Madson Euler\/R\u00e1dio Nacional >> Siga o canal do BEC no WhatsApp Um jumento infl\u00e1vel de tr\u00eas metros foi instalado em Salvador, Bahia, como s\u00edmbolo de uma mobiliza\u00e7\u00e3o p\u00fablica em defesa da preserva\u00e7\u00e3o desses animais e pela aprova\u00e7\u00e3o do projeto de lei que pro\u00edbe, de maneira definitiva, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-95587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/05\/Jumentos-130526-Foto-Protecao-Mundial-Animal-E.png?fit=900%2C509&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=95587"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95587\/revisions"}],"predecessor-version":[{"id":95589,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/95587\/revisions\/95589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/95588"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=95587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=95587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=95587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}