{"id":94541,"date":"2026-03-26T08:27:50","date_gmt":"2026-03-26T11:27:50","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=94541"},"modified":"2026-03-26T08:32:23","modified_gmt":"2026-03-26T11:32:23","slug":"agentes-de-saude-e-endemias-de-senhor-do-bonfim-rejeitam-proposta-salarial-da-prefeitura","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/agentes-de-saude-e-endemias-de-senhor-do-bonfim-rejeitam-proposta-salarial-da-prefeitura\/","title":{"rendered":"Agentes de Sa\u00fade e Endemias de Senhor do Bonfim rejeitam proposta salarial da Prefeitura"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>Categoria pede reajuste de 5% e cobra valoriza\u00e7\u00e3o diante das perdas inflacion\u00e1rias<\/strong><\/p>\n\n\n\n<p><strong>Por Blog do Eloilton Cajuhy \u2013 BEC<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">&gt;&gt; Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"411\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?resize=800%2C411&#038;ssl=1\" alt=\"\" class=\"wp-image-94542\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?w=982&amp;ssl=1 982w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?resize=300%2C154&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?resize=768%2C394&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>A Associa\u00e7\u00e3o dos Agentes Comunit\u00e1rios de Sa\u00fade (AMACS-SB) e a Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias (AACE-SB) informaram oficialmente \u00e0 Prefeitura a decis\u00e3o tomada em assembleia geral da categoria, realizada na \u00faltima quarta-feira (25).<\/p>\n\n\n\n<p>O posicionamento reflete a delibera\u00e7\u00e3o soberana dos 126 servidores presentes no encontro. Na ocasi\u00e3o, os profissionais analisaram a proposta da gest\u00e3o municipal que previa o reajuste do piso salarial nacional, conforme a Emenda Constitucional n\u00ba 120, al\u00e9m de uma reposi\u00e7\u00e3o salarial de 2% em parcela \u00fanica, com efeito retroativo a janeiro de 2026.<\/p>\n\n\n\n<p>Ap\u00f3s amplo debate, a categoria decidiu, de forma un\u00e2nime, rejeitar a proposta apresentada pela Prefeitura. Segundo os representantes, o percentual oferecido n\u00e3o atende \u00e0s necessidades da classe, sendo considerado insuficiente diante das perdas inflacion\u00e1rias acumuladas.<\/p>\n\n\n\n<p>Os agentes reivindicam um reajuste de 5% sobre o piso atual, defendendo que o percentual est\u00e1 em conformidade com o direito \u00e0 revis\u00e3o geral anual da remunera\u00e7\u00e3o, previsto tanto na Lei Org\u00e2nica do Munic\u00edpio quanto no Estatuto dos Servidores P\u00fablicos Municipais.<\/p>\n\n\n\n<p>Em nota, os profissionais destacaram a import\u00e2ncia do trabalho desempenhado pelos Agentes Comunit\u00e1rios de Sa\u00fade e pelos Agentes de Combate \u00e0s Endemias, ressaltando que a atua\u00e7\u00e3o desses servidores \u00e9 fundamental para a promo\u00e7\u00e3o da sa\u00fade p\u00fablica, preven\u00e7\u00e3o de doen\u00e7as e prote\u00e7\u00e3o da popula\u00e7\u00e3o de Senhor do Bonfim.<\/p>\n\n\n\n<p>A categoria tamb\u00e9m reafirmou a disposi\u00e7\u00e3o para o di\u00e1logo com a administra\u00e7\u00e3o municipal, esperando que uma nova proposta seja apresentada e contemple, de forma mais justa, os direitos e a valoriza\u00e7\u00e3o dos servidores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Categoria pede reajuste de 5% e cobra valoriza\u00e7\u00e3o diante das perdas inflacion\u00e1rias Por Blog do Eloilton Cajuhy \u2013 BEC &gt;&gt; Siga o canal do BEC no WhatsApp A Associa\u00e7\u00e3o dos Agentes Comunit\u00e1rios de Sa\u00fade (AMACS-SB) e a Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias (AACE-SB) informaram oficialmente \u00e0 Prefeitura a decis\u00e3o tomada em assembleia geral [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-94541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/03\/Agentes-Bonfim.png?fit=982%2C504&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/94541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=94541"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/94541\/revisions"}],"predecessor-version":[{"id":94544,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/94541\/revisions\/94544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/94542"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=94541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=94541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=94541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}