{"id":93834,"date":"2026-02-23T20:49:19","date_gmt":"2026-02-23T23:49:19","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=93834"},"modified":"2026-02-23T20:49:21","modified_gmt":"2026-02-23T23:49:21","slug":"dobradinha-de-michelle-e-nikolas-irrita-eduardo-bolsonaro-e-expoe-racha-na-direita","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/dobradinha-de-michelle-e-nikolas-irrita-eduardo-bolsonaro-e-expoe-racha-na-direita\/","title":{"rendered":"Dobradinha de Michelle e Nikolas irrita Eduardo Bolsonaro e exp\u00f5e racha na direita"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Racha entre filhos e ex-primeira-dama sobre o apoio \u00e0 pr\u00e9-candidatura de Fl\u00e1vio Bolsonaro \u00e0 presid\u00eancia divide apoio de aliados<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Andr\u00e9ia Sadi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">>> Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Michelle-e-Eduardo-Bolsonaro-%E2%80%94-Foto-Isac-Nobrega-PR-Gil-Cohen-Magen-AFP.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"428\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Michelle-e-Eduardo-Bolsonaro-%E2%80%94-Foto-Isac-Nobrega-PR-Gil-Cohen-Magen-AFP.jpg?resize=768%2C428&#038;ssl=1\" alt=\"\" class=\"wp-image-93835\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Michelle-e-Eduardo-Bolsonaro-%E2%80%94-Foto-Isac-Nobrega-PR-Gil-Cohen-Magen-AFP.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Michelle-e-Eduardo-Bolsonaro-%E2%80%94-Foto-Isac-Nobrega-PR-Gil-Cohen-Magen-AFP.jpg?resize=300%2C167&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Michelle e Eduardo Bolsonaro \u2014 Foto: Isac N\u00f3brega\/PR; Gil Cohen-Magen\/AFP<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O racha entre membros da fam\u00edlia Bolsonaro sobre o apoio \u00e0 pr\u00e9-candidatura de Fl\u00e1vio \u00e0 presid\u00eancia est\u00e1 mais evidente e envolve tamb\u00e9m aliados do cl\u00e3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Michelle Bolsonaro e o deputado Nikolas Ferreira (PL-MG) queriam que o candidato da direita fosse Tarc\u00edsio de Freitas (Republicanos). Com o governador de S\u00e3o Paulo fora da disputa presidencial, a dupla n\u00e3o se engajou na campanha do filho mais velho do ex-presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A escolha de se manterem afastados e n\u00e3o demonstrarem publicamente apoio a Fl\u00e1vio tem irritado seu irm\u00e3o Eduardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos Estados Unidos desde fevereiro do ano passado e sem possibilidade de concorrer neste ano, Eduardo v\u00ea que seu capital pol\u00edtico depende da manuten\u00e7\u00e3o do esp\u00f3lio deixado pelo pai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A tens\u00e3o p\u00fablica na fam\u00edlia escalou ainda mais recentemente, ap\u00f3s novas declara\u00e7\u00f5es de Eduardo a respeito da madrasta e do deputado mineiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O filho 03 de Bolsonaro criticou Michelle e Nikolas, dizendo que eles est\u00e3o com &#8220;amn\u00e9sia&#8221; e &#8220;jogando o mesmo jogo\u201d em rela\u00e7\u00e3o a Fl\u00e1vio, que em dezembro anunciou ter sido o escolhido pelo pai para disputar a presid\u00eancia como seu sucessor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nikolas, que neste fim de semana visitou Bolsonaro na Papudinha, aproveitou para responder o ex-deputado dizendo que nem ele, nem Michelle, t\u00eam amn\u00e9sia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDiscordo que eu tenha amn\u00e9sia e que a Michelle tem amn\u00e9sia. Diante das situa\u00e7\u00f5es que est\u00e3o acontecendo, n\u00f3s temos o pai dele preso, sofrendo dificuldades de sa\u00fade. E a prioridade \u00e9 nos atacar. Ent\u00e3o, isso diz muito mais sobre eles do que sobre mim&#8221;, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, o racha \u00e9 agora uma fratura exposta no campo da direita.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Andreia-Sadi-Foto-Reproducao-Instagram.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"768\" height=\"426\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Andreia-Sadi-Foto-Reproducao-Instagram.png?resize=768%2C426&#038;ssl=1\" alt=\"\" class=\"wp-image-93836\" style=\"aspect-ratio:1.8028909329829172;width:444px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Andreia-Sadi-Foto-Reproducao-Instagram.png?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Andreia-Sadi-Foto-Reproducao-Instagram.png?resize=300%2C166&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><sub>Andr\u00e9ia Sadi &#8211; Apresentadora do Est\u00fadio i, na GloboNews<br>Foto: Reprodu\u00e7\u00e3o \/ Instagram<\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Racha entre filhos e ex-primeira-dama sobre o apoio \u00e0 pr\u00e9-candidatura de Fl\u00e1vio Bolsonaro \u00e0 presid\u00eancia divide apoio de aliados Por Andr\u00e9ia Sadi >> Siga o canal do BEC no WhatsApp O racha entre membros da fam\u00edlia Bolsonaro sobre o apoio \u00e0 pr\u00e9-candidatura de Fl\u00e1vio \u00e0 presid\u00eancia est\u00e1 mais evidente e envolve tamb\u00e9m aliados do cl\u00e3. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-93834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Michelle-e-Eduardo-Bolsonaro-%E2%80%94-Foto-Isac-Nobrega-PR-Gil-Cohen-Magen-AFP.jpg?fit=768%2C428&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=93834"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93834\/revisions"}],"predecessor-version":[{"id":93837,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93834\/revisions\/93837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/93835"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=93834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=93834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=93834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}