{"id":93827,"date":"2026-02-23T14:55:30","date_gmt":"2026-02-23T17:55:30","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=93827"},"modified":"2026-02-23T14:55:32","modified_gmt":"2026-02-23T17:55:32","slug":"oab-ba-repudia-decisao-que-absolveu-homem-de-35-anos-por-estupro-de-vulneravel-contra-menina-de-12-anos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/oab-ba-repudia-decisao-que-absolveu-homem-de-35-anos-por-estupro-de-vulneravel-contra-menina-de-12-anos\/","title":{"rendered":"OAB-BA repudia decis\u00e3o que absolveu homem de 35 anos por estupro de vulner\u00e1vel contra menina de 12 anos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy \u2013 BEC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">>> Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/10\/Fachada-OAB-Bahia_Foto-Angelino-de-Jesus.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"760\" height=\"506\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/10\/Fachada-OAB-Bahia_Foto-Angelino-de-Jesus.jpg?resize=760%2C506\" alt=\"\" class=\"wp-image-90547\" style=\"width:601px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/10\/Fachada-OAB-Bahia_Foto-Angelino-de-Jesus.jpg?w=760&amp;ssl=1 760w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/10\/Fachada-OAB-Bahia_Foto-Angelino-de-Jesus.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Pr\u00e9dio OAB-Bahia &#8211; Foto: Angelino de Jesus<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A OAB Bahia repudiou a decis\u00e3o da 9\u00aa c\u00e2mara Criminal Especializada do TJ-MG que, por maioria, absolveu um homem de 35 anos condenado em 1\u00aa inst\u00e2ncia a nove anos de pris\u00e3o por estupro de vulner\u00e1vel contra uma menina de 12 anos, com quem vivia como casal em Indian\u00f3polis, no Tri\u00e2ngulo Mineiro. A Comiss\u00e3o da Mulher Advogada e o Comit\u00ea de Acompanhamento e Capacita\u00e7\u00e3o do Protocolo para Julgamento com Perspectiva de G\u00eanero da OAB-BA criticaram a absolvi\u00e7\u00e3o do homem e os argumentos que embasaram a decis\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thais Bandeira, presidente da Comiss\u00e3o da Mulher Advogada da OAB-BA, declarou que &#8220;a OAB Bahia repudia a recente decis\u00e3o proferida pela 9\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a de Minas Gerais, que excluiu a tipicidade do crime de estupro de vulner\u00e1vel, diante de caso de rela\u00e7\u00e3o sexual mantida por homem de 35 contra menina de 12 anos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Com base no Protocolo para Julgamento com Perspectiva de G\u00eanero, podemos dizer que a decis\u00e3o \u00e9 uma manifesta viol\u00eancia institucional contra crian\u00e7as e adolescentes, autorizando a sexualiza\u00e7\u00e3o precoce de seus corpos ao tempo em que flexibiliza o dever de tutela de um bem jur\u00eddico indispon\u00edvel, que \u00e9 a dignidade sexual de menores de 14 anos&#8221;, completou Thais Bandeira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joana Rodrigues, conselheira seccional e coordenadora do Comit\u00ea de Acompanhamento e Capacita\u00e7\u00e3o do Protocolo para Julgamento com Perspectiva de G\u00eanero da OAB-BA, destacou que &#8220;os argumentos centrais utilizados pelo Tribunal para a absolvi\u00e7\u00e3o do agente foram a exist\u00eancia de concord\u00e2ncia dos pais da adolescente, o v\u00ednculo afetivo entre o acusado e v\u00edtima, e o objetivo de constitui\u00e7\u00e3o de fam\u00edlia, j\u00e1 que o r\u00e9u mantinha uma esp\u00e9cie de \u201ccasamento de fato\u201d com a ofendida&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daniela Portugal, secret\u00e1ria-geral da Comiss\u00e3o da Mulher Advogada, ressaltou que &#8220;diferentemente do crime de estupro do art. 213, o art. 217-A, do C\u00f3digo Penal, ao tipificar o crime de estupro de vulner\u00e1vel, estabelece que a sua incid\u00eancia independe do consentimento da v\u00edtima, uma vez que considera todo menor de 14 anos ainda uma pessoa em forma\u00e7\u00e3o, cuja vulnerabilidade \u00e9 legalmente presumida&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog do Eloilton Cajuhy \u2013 BEC >> Siga o canal do BEC no WhatsApp A OAB Bahia repudiou a decis\u00e3o da 9\u00aa c\u00e2mara Criminal Especializada do TJ-MG que, por maioria, absolveu um homem de 35 anos condenado em 1\u00aa inst\u00e2ncia a nove anos de pris\u00e3o por estupro de vulner\u00e1vel contra uma menina de 12 anos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":90547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-93827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2025\/10\/Fachada-OAB-Bahia_Foto-Angelino-de-Jesus.jpg?fit=760%2C506&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=93827"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93827\/revisions"}],"predecessor-version":[{"id":93828,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93827\/revisions\/93828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/90547"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=93827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=93827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=93827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}