{"id":93818,"date":"2026-02-23T08:54:29","date_gmt":"2026-02-23T11:54:29","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=93818"},"modified":"2026-02-23T08:54:30","modified_gmt":"2026-02-23T11:54:30","slug":"acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-bahia\/","title":{"rendered":"Acidente entre 13 ve\u00edculos deixa seis feridos em rodovia na Bahia"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Batida ocorreu na BR-324, em trecho de Sim\u00f5es Filho, neste domingo (22). Pista chegou a ser interditada, mas j\u00e1 foi liberada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por g1 BA e TV Bahia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029VaAT7tDLI8Yfj5y9Z50Z\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">>> Siga o canal do BEC no WhatsApp<\/mark><\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-Bahia-%E2%80%94-Foto-Reproducao-Redes-Sociais.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"481\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-Bahia-%E2%80%94-Foto-Reproducao-Redes-Sociais.jpg?resize=768%2C481&#038;ssl=1\" alt=\"\" class=\"wp-image-93819\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-Bahia-%E2%80%94-Foto-Reproducao-Redes-Sociais.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-Bahia-%E2%80%94-Foto-Reproducao-Redes-Sociais.jpg?resize=300%2C188&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Acidente entre 13 ve\u00edculos deixa seis feridos em rodovia na Bahia \u2014 Foto: Reprodu\u00e7\u00e3o\/Redes Sociais<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Um acidente entre 13 ve\u00edculos deixou seis feridos neste domingo (22), na BR-324, em Sim\u00f5es Filho, na Regi\u00e3o Metropolitana de Salvador (RMS). As informa\u00e7\u00f5es s\u00e3o da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), que registrou a ocorr\u00eancia por volta de 13h20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pista chegou a ser totalmente interditada ap\u00f3s o acidente, mas foi liberada \u00e0s 15h. At\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, n\u00e3o foram divulgadas informa\u00e7\u00f5es sobre o que causou a batida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Equipes da PRF, do Corpo de Bombeiros e do Departamento Nacional de Infraestrutura de Transportes (DNIT) atuaram na ocorr\u00eancia. Mas tamb\u00e9m n\u00e3o foram divulgados detalhes sobre o estado de sa\u00fade dos feridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A PRF informou apenas que uma pessoa ficou em estado grave, enquanto as cinco demais foram encontradas com ferimentos leves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imagens feitas no local mostram a colis\u00e3o entre dois carros, com a parte traseira de um deles destru\u00edda, e um terceiro ve\u00edculo sob inspe\u00e7\u00e3o dos bombeiros, tamb\u00e9m com a traseira destru\u00edda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Batida ocorreu na BR-324, em trecho de Sim\u00f5es Filho, neste domingo (22). Pista chegou a ser interditada, mas j\u00e1 foi liberada Por g1 BA e TV Bahia >> Siga o canal do BEC no WhatsApp Um acidente entre 13 ve\u00edculos deixou seis feridos neste domingo (22), na BR-324, em Sim\u00f5es Filho, na Regi\u00e3o Metropolitana de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-93818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2026\/02\/Acidente-entre-13-veiculos-deixa-seis-feridos-em-rodovia-na-Bahia-%E2%80%94-Foto-Reproducao-Redes-Sociais.jpg?fit=768%2C481&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=93818"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93818\/revisions"}],"predecessor-version":[{"id":93820,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/93818\/revisions\/93820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/93819"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=93818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=93818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=93818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}