{"id":9129,"date":"2016-04-20T09:54:41","date_gmt":"2016-04-20T12:54:41","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=9129"},"modified":"2016-04-20T09:54:41","modified_gmt":"2016-04-20T12:54:41","slug":"andorinha-campeonato-municipal-de-futebol-amador-comeca-neste-domingo-24","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/andorinha-campeonato-municipal-de-futebol-amador-comeca-neste-domingo-24\/","title":{"rendered":"Andorinha: Campeonato Municipal de Futebol Amador come\u00e7a neste domingo (24)"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-9130\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?resize=800%2C600\" alt=\"campeonato 2016\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Na manh\u00e3 de domingo, 24, a bola vai rolar pelo Campeonato Municipal de Futebol de Andorinha 2016. Esse ano, a competi\u00e7\u00e3o ter\u00e1 a participa\u00e7\u00e3o de oito clubes: Vila Peixe, Salgado, Medrado, Morro Branco, Sitio, Riacho Seco, Teixeira e a equipe do China. Os jogos v\u00e3o acontecer sempre aos domingos e a grande final ser\u00e1 no dia 12 de junho (semana de comemora\u00e7\u00e3o de emancipa\u00e7\u00e3o pol\u00edtico-administrativa do munic\u00edpio).<\/p>\n<p>\u201cA administra\u00e7\u00e3o busca com esse tipo de incentiva promover o esporte amador no munic\u00edpio. Estamos nos empenhando para que este seja um grande campeonato\u201d, disse a prefeita Dourineide Concei\u00e7\u00e3o.<\/p>\n<p>No domingo vai acontecer um torneio envolvendo todas as equipes da competi\u00e7\u00e3o \u2013 no total, quase 180 jogadores participar\u00e3o do certame. A abertura oficial da competi\u00e7\u00e3o est\u00e1 marcada para \u00e0s 8h, no campo de Caldeir\u00e3o da Vaca. O evento est\u00e1 sendo realizado pela prefeitura de Andorinha por meio do Departamento de Esportes.<\/p>\n<p>\u201cA competi\u00e7\u00e3o al\u00e9m de integrar as comunidades, valoriza o nosso futebol amador\u201d, falou Lucinete Antunes, diretora do Departamento de Esportes . Uma premia\u00e7\u00e3o de R$ 6 mil reais ser\u00e1 dividida entre o campe\u00e3o, vice\u2013campe\u00e3o, artilheiro e melhor goleiro da competi\u00e7\u00e3o.<\/p>\n<p><em>*ASCOM ANDORINHA<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 de domingo, 24, a bola vai rolar pelo Campeonato Municipal de Futebol de Andorinha 2016. Esse ano, a competi\u00e7\u00e3o ter\u00e1 a participa\u00e7\u00e3o de oito clubes: Vila Peixe, Salgado, Medrado, Morro Branco, Sitio, Riacho Seco, Teixeira e a equipe do China. Os jogos v\u00e3o acontecer sempre aos domingos e a grande final ser\u00e1 no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,1,11],"tags":[],"class_list":["post-9129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/04\/campeonato-2016.jpg?fit=800%2C600&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/9129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=9129"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/9129\/revisions"}],"predecessor-version":[{"id":9131,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/9129\/revisions\/9131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/9130"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=9129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=9129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=9129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}