{"id":81227,"date":"2024-06-07T00:10:00","date_gmt":"2024-06-07T03:10:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=81227"},"modified":"2024-06-06T20:13:10","modified_gmt":"2024-06-06T23:13:10","slug":"codevasf-antecipa-acoes-de-irrigacao-e-do-canal-do-sertao-na-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/codevasf-antecipa-acoes-de-irrigacao-e-do-canal-do-sertao-na-bahia\/","title":{"rendered":"Codevasf antecipa a\u00e7\u00f5es de irriga\u00e7\u00e3o e do Canal do Sert\u00e3o na Bahia"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Em visita ao Grupo A TARDE, o presidente Marcelo Moreira detalhou agricultura de irriga\u00e7\u00e3o no estado e citou novidades.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por A Tarde<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Presidente-Marcelo-Moreira-Foto-Olga-Leiria-Ag.-A-Tarde.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"760\" height=\"504\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Presidente-Marcelo-Moreira-Foto-Olga-Leiria-Ag.-A-Tarde.jpg?resize=760%2C504&#038;ssl=1\" alt=\"\" class=\"wp-image-81228\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Presidente-Marcelo-Moreira-Foto-Olga-Leiria-Ag.-A-Tarde.jpg?w=760&amp;ssl=1 760w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Presidente-Marcelo-Moreira-Foto-Olga-Leiria-Ag.-A-Tarde.jpg?resize=300%2C199&amp;ssl=1 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Marcelo Moreira, Presidente da Codevasf &#8211; Foto: Olga Leiria \/ Ag. A Tarde<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente da Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e do Parna\u00edba (Codevasf), Marcelo Moreira, fez um balan\u00e7o, em entrevista exclusiva ao Portal A TARDE, na manh\u00e3 desta quinta-feira, 6, das principais a\u00e7\u00f5es realizadas pela empresa p\u00fablica nos \u00faltimos 50 anos e antecipou medidas que j\u00e1 est\u00e3o em andamento principalmente na Bahia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O gestor detalhou que a principal medida da empresa no estado \u00e9 a agricultura de Irec\u00ea, que est\u00e1 em constru\u00e7\u00e3o. \u201cEsse vai ser um novo vetor de crescimento de desenvolvimento que n\u00f3s estamos trabalhando\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO Baixio de Irec\u00ea \u00e9 um projeto que j\u00e1 tem mais de R$ 1 bilh\u00e3o investidos pelo Governo Federal. J\u00e1 temos a\u00ed 42 km de canais prontos, que j\u00e1 est\u00e3o produzindo cerca de quase 2 mil hectares. J\u00e1 houve produ\u00e7\u00e3o de ab\u00f3bora, de lim\u00e3o, de soja, \u00e9 um projeto que est\u00e1 em constante crescimento e em curto prazo. N\u00f3s tamb\u00e9m teremos um investimento de R$ 1 bilh\u00e3o pela empresa privada, fomentando a cria\u00e7\u00e3o desses 350 mil empregos\u201d, declarou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Baixio est\u00e1 localizado entre a regi\u00e3o de Irec\u00ea, Xique-Xique e Itagua\u00e7u da Bahia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente tamb\u00e9m antecipou que haver\u00e1 projetos semelhantes, ligados \u00e0 agricultura irrigada, nos munic\u00edpios de Iui\u00fa e Santa Br\u00edgida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTemos o Projeto do Iui\u00fa, na divisa de Minas Gerais. N\u00f3s vamos seguir na mesma linha , mas est\u00e1 em fase anterior. Vamos come\u00e7ar as audi\u00eancias p\u00fablicas, j\u00e1 temos a empresa contratada para fazer o estudo de viabilidade t\u00e9cnica e a modelagem econ\u00f4mica financeira. Tamb\u00e9m temos a proposta de Santa Br\u00edgida, que vai seguir a mesma linha do Iui\u00fa e j\u00e1 devemos contratar a empresa at\u00e9 o final do ano\u201d, citou.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Canal-do-Sertao_Reproducao.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"760\" height=\"419\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Canal-do-Sertao_Reproducao.jpg?resize=760%2C419&#038;ssl=1\" alt=\"\" class=\"wp-image-81229\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Canal-do-Sertao_Reproducao.jpg?w=760&amp;ssl=1 760w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Canal-do-Sertao_Reproducao.jpg?resize=300%2C165&amp;ssl=1 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Reprodu\u00e7\u00e3o<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-7f5d5e723d45f3dfd8d21c3aa6b304c5 wp-block-paragraph\"><strong>Canal do Sert\u00e3o baiano<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m das medidas relacionadas \u00e0 irriga\u00e7\u00e3o, Moreira tamb\u00e9m falou sobre as obras de estruturantes e adiantou o processo do Canal do Sert\u00e3o, conhecido inicialmente como Eixo Sul da Transposi\u00e7\u00e3o do S\u00e3o Francisco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;N\u00f3s j\u00e1 conclu\u00edmos o projeto para iniciar essa tratativa. \u00c9 uma obra que j\u00e1 est\u00e1 no PAC [Programa de Acelera\u00e7\u00e3o do Crescimento]. \u00c9 o eixo sul da transposi\u00e7\u00e3o e est\u00e1 pronta para sair, eu acredito que, entre esse ano e in\u00edcio do pr\u00f3ximo ano, devemos estar iniciando essa obra fant\u00e1stica que vai trazer \u00e1gua l\u00e1 do Salitre e Juazeiro at\u00e9 o Centro-Oeste da Bahia, at\u00e9 a barragem de S\u00e3o Jos\u00e9 do Jacu\u00edpe. J\u00e1 conclu\u00edmos os projetos j\u00e1 est\u00e1 cadastrada no PAC ent\u00e3o \u00e9 uma obra que temos a expectativa grande&#8221;, iniciou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNaturalmente \u00e9 uma obra muito longa, s\u00e3o 300 km de canal, de uma obra entre R$ 4 e R$ 5 bilh\u00f5es, mas que vai ser feita de forma faseada. A primeira fase a gente est\u00e1 estimando que seja algo em torno de R$ 400 e R$ 600 milh\u00f5es\u201d, revelou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em visita ao Grupo A TARDE, o presidente Marcelo Moreira detalhou agricultura de irriga\u00e7\u00e3o no estado e citou novidades. Por A Tarde O presidente da Companhia de Desenvolvimento dos Vales do S\u00e3o Francisco e do Parna\u00edba (Codevasf), Marcelo Moreira, fez um balan\u00e7o, em entrevista exclusiva ao Portal A TARDE, na manh\u00e3 desta quinta-feira, 6, das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":81229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-81227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Codevasf_Canal-do-Sertao_Reproducao.jpg?fit=760%2C419&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=81227"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81227\/revisions"}],"predecessor-version":[{"id":81230,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81227\/revisions\/81230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/81229"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=81227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=81227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=81227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}