{"id":81113,"date":"2024-06-01T09:24:28","date_gmt":"2024-06-01T12:24:28","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=81113"},"modified":"2024-06-01T09:24:31","modified_gmt":"2024-06-01T12:24:31","slug":"o-forro-e-tao-forte-que-aguenta-tudo-diz-flavio-jose","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/o-forro-e-tao-forte-que-aguenta-tudo-diz-flavio-jose\/","title":{"rendered":"\u201cO forr\u00f3 \u00e9 t\u00e3o forte que aguenta tudo\u201d, diz Fl\u00e1vio Jos\u00e9"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Cantor admite n\u00e3o reconhecer uma evolu\u00e7\u00e3o no forr\u00f3 e afirma que o forr\u00f3 universit\u00e1rio n\u00e3o existe.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"517\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?resize=780%2C517&#038;ssl=1\" alt=\"\" class=\"wp-image-81114\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?w=780&amp;ssl=1 780w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?resize=768%2C509&amp;ssl=1 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Artista disse que h\u00e1 uma diminui\u00e7\u00e3o dos shows do \u201cforr\u00f3 aut\u00eantico&#8221; nas festas juninas &#8211; Foto: Rafaela Ara\u00fajo | Ag. A TARDE<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos maiores nomes do forr\u00f3 no pa\u00eds, Fl\u00e1vio Jos\u00e9 falou sobre a perda de espa\u00e7o que o g\u00eanero vem enfrentando nas festas juninas pelo pa\u00eds. No ano passado, ele fez um desabafo ap\u00f3s ter seu show reduzido no S\u00e3o Jo\u00e3o de Campina Grande, na Para\u00edba.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n<\/blockquote>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O compositor disse que h\u00e1 uma diminui\u00e7\u00e3o dos shows do \u201cforr\u00f3 aut\u00eantico&#8221; nas festas juninas e comentou o quanto sente falta de ver seus amigos forrozeiros ocupando esse espa\u00e7o. \u201cEu n\u00e3o vou citar o nome aqui, mas tem cidades que eu vou cantar que, de forr\u00f3, s\u00f3 tem eu. Parece que \u00e9 como se dissesse assim, vamos colocar para dar uma satisfa\u00e7\u00e3o, n\u00e9, para dizer assim, \u2018n\u00e3o, tinha forr\u00f3, tinha Fl\u00e1vio Jos\u00e9\u2019&#8221;, declarou, em entrevista ao &#8220;Isso \u00e9 Bahia&#8221;, da A TARDE FM, na ter\u00e7a-feira, 28.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Eu sinto falta de outros colegas, n\u00e9, de v\u00e1rios deles que sempre fizeram tudo por essa m\u00fasica. Est\u00e3o sendo totalmente esquecidos, sem esquecer de v\u00e1rios artistas que j\u00e1 jogaram a toalha, porque por falta de apoio, por n\u00e3o tocar nas emissoras de r\u00e1dio, por n\u00e3o fazer parte das principais cidades, pra\u00e7as de cidades importantes durante o m\u00eas de junho, enfim, s\u00e3o essas coisas que as pessoas se desiludem e v\u00e3o procurar outra profiss\u00e3o, seguir a vida\u201d, completou ele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre a disputa que o forr\u00f3 enfrenta com outros g\u00eaneros musicais no S\u00e3o Jo\u00e3o, Fl\u00e1vio Jos\u00e9 contou um epis\u00f3dio vivido com o amigo Santanna, O Cantador, e pontuou que sabe que ainda h\u00e1 p\u00fablico para o forr\u00f3 \u201csem modismos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Recentemente, eu e o meu amigo Santanna, n\u00f3s fizemos um show na Casa Rio, em Petrolina, foi superlotado e n\u00e3o tinha nenhum modismo. Ent\u00e3o, faltam essas pessoas acreditarem, n\u00e9? E outra coisa, se o nosso S\u00e3o Jo\u00e3o fosse coroado de m\u00fasica aut\u00eantica, ele seria outro\u201d, disparou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cantor admite n\u00e3o reconhecer uma evolu\u00e7\u00e3o no forr\u00f3 e afirma que o forr\u00f3 universit\u00e1rio n\u00e3o existe, sendo apenas um outro modismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cN\u00e3o, o forr\u00f3 \u00e9 t\u00e3o forte que ele aguenta tudo, at\u00e9 nomes de outras coisas que n\u00e3o t\u00eam nada a ver sendo chamados de forr\u00f3. Ent\u00e3o, o forr\u00f3 que eu conhe\u00e7o \u00e9 o forr\u00f3 de Luiz Gonzaga, do Trio Nordestino, das tradi\u00e7\u00f5es, isso a\u00ed sim, foi como eu falei anteriormente. N\u00e3o teve renova\u00e7\u00e3o porque v\u00e1rios artistas desiludidos desistiram e jogaram a toalha. Agora, modismos que est\u00e3o sendo chamados de forr\u00f3, tem um monte, mas na minha concep\u00e7\u00e3o n\u00e3o t\u00eam nada a ver com forr\u00f3\u201d, completou o forrozeiro.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-1cd52e34703ef12e33028ed75cfa3224 wp-block-paragraph\"><strong>De volta a Para\u00edba<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 200 km de Caruaru, onde fez a declara\u00e7\u00e3o que repercutiu nacionalmente em 2023, est\u00e1 a cidade de Monteiro, terra natal do artista. Na entrevista, ele falou sobre a emo\u00e7\u00e3o de ir tocar na sua cidade natal, no pr\u00f3ximo dia 19 de junho, ap\u00f3s dezesseis anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOlha, \u00e9 muito importante porque, depois desse an\u00fancio da nossa participa\u00e7\u00e3o na abertura do S\u00e3o Jo\u00e3o, in\u00fameras pessoas de Monteiro que residem fora, Jo\u00e3o Pessoa, Campina, Natal, Rio, S\u00e3o Paulo, essas pessoas est\u00e3o vindo exatamente pra viver essa noite e n\u00e3o esquec\u00ea-la. E, pra mim, eu tenho uma gratid\u00e3o tamb\u00e9m por essas pessoas que se manifestam nas redes sociais apoiando o nosso retorno,\u201d afirmou.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-753435ec861aefd1a0d2dbd423475156 wp-block-paragraph\"><strong>Assista ao Isso \u00e9 Bahia com Fl\u00e1vio Jos\u00e9<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Fl\u00e1vio Jos\u00e9 retorna ao S\u00e3o Jo\u00e3o de Monteiro-PB ap\u00f3s 16 anos e alerta sobre a preserva\u00e7\u00e3o\u00a0do\u00a0forr\u00f3\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/cXd4HmRReGA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cantor admite n\u00e3o reconhecer uma evolu\u00e7\u00e3o no forr\u00f3 e afirma que o forr\u00f3 universit\u00e1rio n\u00e3o existe. Um dos maiores nomes do forr\u00f3 no pa\u00eds, Fl\u00e1vio Jos\u00e9 falou sobre a perda de espa\u00e7o que o g\u00eanero vem enfrentando nas festas juninas pelo pa\u00eds. No ano passado, ele fez um desabafo ap\u00f3s ter seu show reduzido no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":81114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-81113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/06\/Flavio-Jose-Foto-Rafaela-Araujo-Ag.-A-TARDE.jpg?fit=780%2C517&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=81113"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81113\/revisions"}],"predecessor-version":[{"id":81115,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81113\/revisions\/81115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/81114"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=81113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=81113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=81113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}