{"id":81101,"date":"2024-05-31T00:10:00","date_gmt":"2024-05-31T03:10:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=81101"},"modified":"2024-05-30T19:22:29","modified_gmt":"2024-05-30T22:22:29","slug":"pesquisa-aponta-sp-rio-e-bahia-como-estados-com-mais-pessoas-rudes-no-transito","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/pesquisa-aponta-sp-rio-e-bahia-como-estados-com-mais-pessoas-rudes-no-transito\/","title":{"rendered":"Pesquisa aponta SP, Rio e Bahia como estados com mais pessoas rudes no tr\u00e2nsito"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>S\u00e3o Paulo est\u00e1 no topo dos mais rudes, com 36,2%, seguido de Rio de Janeiro (20%), Bahia (6,6%), Cear\u00e1 (3,2%) e Pernambuco (3,2%).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bahia.ba<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Transalvador-agente-transito-Salvador5.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"420\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Transalvador-agente-transito-Salvador5.jpg?resize=600%2C420&#038;ssl=1\" alt=\"\" class=\"wp-image-81102\" style=\"width:700px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Transalvador-agente-transito-Salvador5.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Transalvador-agente-transito-Salvador5.jpg?resize=300%2C210&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Transalvador<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A olho nu, n\u00e3o s\u00e3o raros os registros de casos de imprud\u00eancia, brigas e xingamentos nas estradas, ruas e avenidas baianas. Agora, no entanto, uma pesquisa explicitou esta realidade em n\u00fameros, colocando a Bahia na terceira posi\u00e7\u00e3o do ranking da grosseria no tr\u00e2nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com dados da plataforma Preply, que recentemente investigou a comunica\u00e7\u00e3o entre condutores e pedestres de diferentes regi\u00f5es do Brasil, o estado de S\u00e3o Paulo est\u00e1 no topo dos mais rudes, com 36,2%, seguido de Rio de Janeiro (20%), Bahia (6,6%), Cear\u00e1 (3,2%) e Pernambuco (3,2%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se por um lado estes estados lideram o p\u00f3dio no quesito dos bate-bocas excessivos, gestos obscenos e buzinas exageradas, os condutores e pedestres de Santa Catarina (13,4%), Rio Grande do Sul (12,6%), Minas Gerais (10,8%), Distrito Federal (9%) e Paran\u00e1 (10,8%) v\u00e3o na contram\u00e3o \u2013 o que neste caso \u00e9 algo a se comemorar -, como os mais gentis do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00e2mbito nacional, o levantamento mostrou que 73,6% dos entrevistados j\u00e1 presenciaram alguma agress\u00e3o verbal no tr\u00e2nsito, enquanto 48,4% j\u00e1 viram agress\u00e3o f\u00edsica. Para al\u00e9m de observar as diversas formas de viol\u00eancia, 40,8% disseram j\u00e1 ter sido v\u00edtimas de insultos, e 8,4% de agress\u00f5es f\u00edsicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para investigar detalhes sobre a comunica\u00e7\u00e3o dos brasileiros no tr\u00e2nsito, durante o m\u00eas de maio, foram entrevistados 500 brasileiros residentes em todas as regi\u00f5es do pa\u00eds. Ao todo, os respondentes tiveram acesso ao total de 10 quest\u00f5es, que exploraram experi\u00eancias envolvendo agress\u00e3o verbal e f\u00edsica, o uso de palavr\u00f5es nas ruas e estradas e as atitudes que costumam estimular conflitos entre condutores e pedestres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Paulo est\u00e1 no topo dos mais rudes, com 36,2%, seguido de Rio de Janeiro (20%), Bahia (6,6%), Cear\u00e1 (3,2%) e Pernambuco (3,2%). Bahia.ba A olho nu, n\u00e3o s\u00e3o raros os registros de casos de imprud\u00eancia, brigas e xingamentos nas estradas, ruas e avenidas baianas. Agora, no entanto, uma pesquisa explicitou esta realidade em n\u00fameros, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":81102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-81101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Transalvador-agente-transito-Salvador5.jpg?fit=600%2C420&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=81101"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81101\/revisions"}],"predecessor-version":[{"id":81103,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/81101\/revisions\/81103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/81102"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=81101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=81101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=81101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}