{"id":80899,"date":"2024-05-17T00:10:00","date_gmt":"2024-05-17T03:10:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=80899"},"modified":"2024-05-16T19:27:55","modified_gmt":"2024-05-16T22:27:55","slug":"nao-eram-so-bens-materiais","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/nao-eram-so-bens-materiais\/","title":{"rendered":"N\u00e3o eram s\u00f3 bens materiais"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"526\" height=\"526\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?resize=526%2C526&#038;ssl=1\" alt=\"\" class=\"wp-image-80900\" style=\"width:568px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?w=526&amp;ssl=1 526w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>N\u00e3o eram s\u00f3 bens materiais<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;V\u00e3o-se os an\u00e9is e ficam os dedos&#8221;, mas n\u00e3o, n\u00e3o eram s\u00f3 bens materiais. Era aquela smart tv que o pai  com sacrif\u00edcio comprou para que, junto com os filhos, pudessem assistir a final da libertadores. Era o jogo de sof\u00e1 que aquela m\u00e3e namorou o ano inteiro, que economizou todos os centavos e se esfor\u00e7ou para comprar s\u00f3 para, ao chegar em casa, depois de um cansativo dia, n\u00e3o encontrasse a filha sentada no ch\u00e3o frio da sala assistindo TV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o eram s\u00f3 bens materiais\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era aquele carro, era aquela moto, que o rapaz ou a mo\u00e7a conquistou, trocando viagens e baladas por dias e noites de trabalho. Era aquele \u00e1lbum de fotografias que imprimiam hist\u00f3rias de uma gera\u00e7\u00e3o inteira\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o eram s\u00f3 bens materiais\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eram sonhos realizados depois de muito suor naquela loja, naquele consult\u00f3rio, naquele escrit\u00f3rio, naquela oficina, naquele atelier\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era a compra do m\u00eas\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O material escolar\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A roupa nova que ganhou no Natal\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A boneca preferida\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O carrinho que passou do pai para o filho\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o eram s\u00f3 bens materiais\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era a casa que abrigava uma fam\u00edlia\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;V\u00e3o-se os an\u00e9is e ficam os dedos&#8221;. Eu at\u00e9 posso concordar com este &#8220;ditado&#8221; no sentido pleno da gratid\u00e3o, mas s\u00f3 quem PERDEU TUDO \u00e9 que sabe o pre\u00e7o que cada anel lhe custou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um sentimento que n\u00e3o se explica!<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-0472cbf67459a4b9f6264943b4f3dfee wp-block-paragraph\"><strong>Texto postado no Facebook por v\u00e1rios internautas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog do Eloilton Cajuhy &#8220;V\u00e3o-se os an\u00e9is e ficam os dedos&#8221;, mas n\u00e3o, n\u00e3o eram s\u00f3 bens materiais. Era aquela smart tv que o pai com sacrif\u00edcio comprou para que, junto com os filhos, pudessem assistir a final da libertadores. Era o jogo de sof\u00e1 que aquela m\u00e3e namorou o ano inteiro, que economizou todos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-80899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/05\/Imagem_Nao-eram-so-bens-materiais_Facebook.jpeg?fit=526%2C526&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=80899"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80899\/revisions"}],"predecessor-version":[{"id":80901,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80899\/revisions\/80901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80900"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=80899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=80899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=80899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}