{"id":80616,"date":"2024-05-01T00:10:00","date_gmt":"2024-05-01T03:10:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=80616"},"modified":"2024-04-30T16:59:11","modified_gmt":"2024-04-30T19:59:11","slug":"projeto-comida-no-prato-e-lancado-na-bahia-para-distribuir-22-milhoes-de-refeicoes","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/projeto-comida-no-prato-e-lancado-na-bahia-para-distribuir-22-milhoes-de-refeicoes\/","title":{"rendered":"Projeto Comida no Prato \u00e9 lan\u00e7ado na Bahia para distribuir 2,2 milh\u00f5es de refei\u00e7\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Secom-BA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida01.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida01.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" class=\"wp-image-80617\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida01.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida01.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida01.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Feij\u00e3o Almeida\/GOVBA<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O governador Jer\u00f4nimo Rodrigues lan\u00e7ou, na manh\u00e3 desta ter\u00e7a-feira (30), o projeto Comida no Prato, em evento realizado na Par\u00f3quia Divino Esp\u00edrito Santo, no Vale dos Lagos, em Salvador. A iniciativa, fruto do programa Bahia Sem Fome em parceria com 50 organiza\u00e7\u00f5es sociais, ir\u00e1 distribuir 2,2 milh\u00f5es de refei\u00e7\u00f5es para pessoas em situa\u00e7\u00e3o de vulnerabilidade e inseguran\u00e7a alimentar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O chefe do executivo baiano celebrou a oportunidade de disponibilizar or\u00e7amento para o combate \u00e0 fome e afirmou que outras etapas ser\u00e3o elaboradas nesse intuito. \u201cO programa n\u00e3o se encerra apenas com distribui\u00e7\u00e3o de comida. O combate \u00e0 fome \u00e9 permanente, na gera\u00e7\u00e3o de emprego e no fortalecimento das atividades econ\u00f4micas, gera\u00e7\u00e3o de renda, seja na agricultura, seja na economia solid\u00e1ria ou nos empreendedores e n\u00f3s teremos outras etapas\u201d, ressaltou Jer\u00f4nimo Rodrigues.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" class=\"wp-image-80619\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Feij\u00e3o Almeida\/GOVBA<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">No evento estiveram presentes o vice-governador Geraldo J\u00fanior, o coordenador do Programa Bahia Sem Fome, Tiago Pereira, as secret\u00e1rias de Assist\u00eancia e Desenvolvimento Social (Seades), Fabya Reis, do Desenvolvimento Urbano (Sedur), Jusmari Oliveira, al\u00e9m do secret\u00e1rio Osni Cardoso, do Desenvolvimento Rural (SDR) e o procurador Geral do Estado, Pedro Maia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tiago Pereira explicou que a primeira parcela dos investimentos j\u00e1 ser\u00e1 liberada. \u201cVamos repassar essa semana para essas 50 organiza\u00e7\u00f5es sociais. Elas j\u00e1 trabalham com produ\u00e7\u00e3o de comida, o Estado est\u00e1 fazendo um aporte financeiro para que elas ampliem o n\u00famero de atendimentos porque, de fato, a gente precisa alcan\u00e7ar quem est\u00e1 em situa\u00e7\u00e3o de fome\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida03.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida03.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" class=\"wp-image-80620\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida03.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida03.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida03.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Feij\u00e3o Almeida\/GOVBA<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O padre Jaciel Bezerra da Par\u00f3quia Divino Esp\u00edrito Santo, uma das organiza\u00e7\u00f5es beneficiadas, expressou a alegria em poder aumentar o p\u00fablico assistido pela institui\u00e7\u00e3o. \u201cO programa conta com a b\u00ean\u00e7\u00e3o da igreja para ser um sucesso. Atualmente, acolhemos 300 fam\u00edlias na Par\u00f3quia, e com o projeto, ser\u00e3o mais 200, totalizando 500 fam\u00edlias.\u201d<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-edf2787d8130a5ce7fde838211f4fba5 wp-block-paragraph\"><strong>Outras a\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na ocasi\u00e3o, o governador autorizou outras a\u00e7\u00f5es dentro da agenda de combate \u00e0 fome, como hortas rurais e urbanas, investimentos nos munic\u00edpios para fortalecer o sistema de seguran\u00e7a alimentar e nutricional. Foi publicado o Edital de Chamada P\u00fablica Comida no Prato, visando ampliar a rede de equipamentos integrados no combate \u00e0 fome no estado. Al\u00e9m disso, recursos foram repassados para 70 munic\u00edpios que integram a Rede de Seguran\u00e7a Alimentar e Nutricional, por meio do Alimenta Suas, ap\u00f3s ades\u00e3o ao Sistema de Seguran\u00e7a Alimentar e ao Programa Bahia Sem Fome.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida04.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida04.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" class=\"wp-image-80622\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida04.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida04.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida04.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Feij\u00e3o Almeida\/GOVBA<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m foi autorizada a assinatura de quatro Termos de Colabora\u00e7\u00e3o do Projeto Viva Horta, com um investimento total de mais R$ 4,1 milh\u00f5es, beneficiando agricultores familiares, comunidades quilombolas, povos tradicionais e associa\u00e7\u00f5es vinculadas a projetos residenciais. Al\u00e9m disso, a implanta\u00e7\u00e3o de hortas comunit\u00e1rias em 70 munic\u00edpios, com uma \u00e1rea de 2,0 hectares, foi autorizada, envolvendo um investimento de R$ 6,7 milh\u00f5es.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-0ab2a4ce3c9d26f940631a757cdb90ce wp-block-paragraph\"><strong>Programa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O edital \u201cComida no Prato\u201d faz parte da estrat\u00e9gia do Programa Estadual Bahia Sem Fome e ser\u00e1 executado pela Companhia de Desenvolvimento e A\u00e7\u00e3o Regional (CAR), vinculada \u00e0 Secretaria de Desenvolvimento Rural (SDR). Com um investimento de mais de R$ 24 milh\u00f5es, o governo ir\u00e1 alimentar fam\u00edlias em vulnerabilidade social, incluindo pessoas em situa\u00e7\u00e3o de rua, trabalhadores\/as de baixa renda, desempregados\/as, pessoas idosas, crian\u00e7as e m\u00e3es solo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secom-BA O governador Jer\u00f4nimo Rodrigues lan\u00e7ou, na manh\u00e3 desta ter\u00e7a-feira (30), o projeto Comida no Prato, em evento realizado na Par\u00f3quia Divino Esp\u00edrito Santo, no Vale dos Lagos, em Salvador. A iniciativa, fruto do programa Bahia Sem Fome em parceria com 50 organiza\u00e7\u00f5es sociais, ir\u00e1 distribuir 2,2 milh\u00f5es de refei\u00e7\u00f5es para pessoas em situa\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-80616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/GOVBA_Comida-no-Prato_Foto-Feijao-Almeida02.jpg?fit=900%2C600&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=80616"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80616\/revisions"}],"predecessor-version":[{"id":80623,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80616\/revisions\/80623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80619"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=80616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=80616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=80616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}