{"id":80592,"date":"2024-04-29T20:00:00","date_gmt":"2024-04-29T23:00:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=80592"},"modified":"2024-04-29T18:20:19","modified_gmt":"2024-04-29T21:20:19","slug":"caminhando-na-verdadeira-liberdade","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/caminhando-na-verdadeira-liberdade\/","title":{"rendered":"Caminhando na verdadeira liberdade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Imagem_Pexels-825336902-19447921.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Imagem_Pexels-825336902-19447921.jpg?resize=640%2C427&#038;ssl=1\" alt=\"\" class=\"wp-image-80593\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Imagem_Pexels-825336902-19447921.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Imagem_Pexels-825336902-19447921.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Imagem: Pexels<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tolo \u00e9 quem briga por espa\u00e7o, lugar, superioridade, notoriedade ou vive pela concorr\u00eancia ferindo, enganado e desfazendo la\u00e7os afetivos por nada. A gente tem que brigar \u00e9 pra ser livre, ser s\u00e1bio, ser inteligente, honesto e capacitado. A gente tem que manter \u00e9 o car\u00e1ter, a personalidade, a transpar\u00eancia. A gente tem que ser o que \u00e9, e viver pelo que gosta e pelo que nos faz bem sem for\u00e7ar tanto o riso ou querer tanto ser notado pelo que a gente n\u00e3o \u00e9, ou pelo que a gente n\u00e3o tem.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f0a582c1257b06efd89f23b8a259475f wp-block-paragraph\"><strong>Cec\u00edlia Sfalsin<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog do Eloilton Cajuhy Tolo \u00e9 quem briga por espa\u00e7o, lugar, superioridade, notoriedade ou vive pela concorr\u00eancia ferindo, enganado e desfazendo la\u00e7os afetivos por nada. A gente tem que brigar \u00e9 pra ser livre, ser s\u00e1bio, ser inteligente, honesto e capacitado. A gente tem que manter \u00e9 o car\u00e1ter, a personalidade, a transpar\u00eancia. A gente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-80592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Imagem_Pexels-825336902-19447921.jpg?fit=640%2C427&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=80592"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80592\/revisions"}],"predecessor-version":[{"id":80594,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80592\/revisions\/80594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80593"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=80592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=80592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=80592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}