{"id":80513,"date":"2024-04-25T00:05:00","date_gmt":"2024-04-25T03:05:00","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=80513"},"modified":"2024-04-24T19:40:43","modified_gmt":"2024-04-24T22:40:43","slug":"opa-apresenta-abril-da-danca-na-praca-candido-felix-em-igara","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/opa-apresenta-abril-da-danca-na-praca-candido-felix-em-igara\/","title":{"rendered":"OPA apresenta: &#8216;Abril da Dan\u00e7a&#8217; na Pra\u00e7a C\u00e2ndido Felix em Igara"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Igara vai celebrar a diversidade e o talento da dan\u00e7a em uma noite inesquec\u00edvel.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"393\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?resize=780%2C393&#038;ssl=1\" alt=\"\" class=\"wp-image-80514\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?w=780&amp;ssl=1 780w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?resize=300%2C151&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?resize=768%2C387&amp;ssl=1 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto Ilustrativa (Grupo de Dan\u00e7a de Osasco-SP\/Imagem de Marcelo Deck)<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Organiza\u00e7\u00e3o OPA est\u00e1 preparando um evento imperd\u00edvel para os amantes da dan\u00e7a e da cultura em geral. No pr\u00f3ximo dia 28 de abril, a partir das 20h30, a Pra\u00e7a C\u00e2ndido Felix, localizada em Igara, no interior de Senhor do Bonfim, ser\u00e1 palco de um grande espet\u00e1culo: o &#8220;Abril da Dan\u00e7a&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com curadoria art\u00edstica de Keitiane do Nascimento e assist\u00eancia de curadoria de Alesandro Evangelista, o evento promete oferecer uma experi\u00eancia enriquecedora, trazendo diferentes estilos de dan\u00e7a para o p\u00fablico apreciar e se encantar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A produ\u00e7\u00e3o do evento est\u00e1 a cargo de Kaique Xavier, que tem trabalhado incansavelmente para garantir que cada detalhe seja cuidadosamente planejado, proporcionando uma noite memor\u00e1vel para todos os presentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A OPA, uma organiza\u00e7\u00e3o cultural dedicada a promover o desenvolvimento art\u00edstico e cultural dos jovens do distrito de Igara, tem se destacado por seu compromisso em oferecer oportunidades de express\u00e3o e crescimento para a comunidade local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O &#8220;Abril da Dan\u00e7a&#8221; na Pra\u00e7a C\u00e2ndido Felix \u00e9 mais uma iniciativa da OPA para celebrar a arte e a diversidade cultural, reafirmando o papel fundamental que a dan\u00e7a desempenha na vida das pessoas e na constru\u00e7\u00e3o de uma sociedade mais plural e inclusiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Igara vai celebrar a diversidade e o talento da dan\u00e7a em uma noite inesquec\u00edvel. Blog do Eloilton Cajuhy A Organiza\u00e7\u00e3o OPA est\u00e1 preparando um evento imperd\u00edvel para os amantes da dan\u00e7a e da cultura em geral. No pr\u00f3ximo dia 28 de abril, a partir das 20h30, a Pra\u00e7a C\u00e2ndido Felix, localizada em Igara, no interior [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-80513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Grupo-de-danca-de-Osasco-SP_Foto-Marcelo-Deck.jpeg?fit=780%2C393&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=80513"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80513\/revisions"}],"predecessor-version":[{"id":80515,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80513\/revisions\/80515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80514"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=80513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=80513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=80513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}