{"id":80133,"date":"2024-04-06T20:18:14","date_gmt":"2024-04-06T23:18:14","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=80133"},"modified":"2024-04-06T20:18:16","modified_gmt":"2024-04-06T23:18:16","slug":"bonfim-estudantes-de-licenciatura-em-teatro-denunciam-agressao-moral-contra-professora-em-universidade","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/bonfim-estudantes-de-licenciatura-em-teatro-denunciam-agressao-moral-contra-professora-em-universidade\/","title":{"rendered":"Bonfim: Estudantes de Licenciatura em Teatro denunciam agress\u00e3o moral contra professora em universidade"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Incidente no Centro de Artes anexo ao Col\u00e9gio Estadual, causa indigna\u00e7\u00e3o e pedidos por ambiente acad\u00eamico seguro e respeitoso.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Blog do Eloilton Cajuhy<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?resize=800%2C530&#038;ssl=1\" alt=\"\" class=\"wp-image-80135\" style=\"width:749px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?w=830&amp;ssl=1 830w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?resize=768%2C509&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto Ilustrativa \/ Getty Images<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em nota que circula nas redes sociais, estudantes, professores e t\u00e9cnicos do curso de Licenciatura em Teatro da Uneb em Bonfim, denunciam agress\u00e3o moral sofrida pela professora \u00c9rica Souza, fato ocorrido no Centro de Artes Professor Marcos F\u00e1bio de Oliveira, que fica no interior do Col\u00e9gio Estadual Senhor do Bonfim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a nota, a agress\u00e3o teria acontecido na noite desta sexta-feira (05), e teria como autores estudantes do curso de Licenciatura em Matem\u00e1tica. Ainda segundo a mesma nota, as supostas agress\u00f5es tiveram &#8220;teor racista, mis\u00f3gino e desrespeitoso para com a docente em exerc\u00edcio de seu of\u00edcio em ambiente universit\u00e1rio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao tempo em que solidarizam-se com a professora \u00c9rica Souza, os respons\u00e1veis pela nota pedem &#8220;que as institui\u00e7\u00f5es educacionais ajam com rigor para garantir um ambiente seguro e respeitoso para todos os membros da comunidade acad\u00eamica&#8221;.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Veja a seguir a \u00edntegra da nota:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Nota-de-repudio_professores-Uneb_Bonfim.jpeg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Nota-de-repudio_professores-Uneb_Bonfim.jpeg?resize=700%2C700&#038;ssl=1\" alt=\"\" class=\"wp-image-80134\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Nota-de-repudio_professores-Uneb_Bonfim.jpeg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Nota-de-repudio_professores-Uneb_Bonfim.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Nota-de-repudio_professores-Uneb_Bonfim.jpeg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Incidente no Centro de Artes anexo ao Col\u00e9gio Estadual, causa indigna\u00e7\u00e3o e pedidos por ambiente acad\u00eamico seguro e respeitoso. Blog do Eloilton Cajuhy Em nota que circula nas redes sociais, estudantes, professores e t\u00e9cnicos do curso de Licenciatura em Teatro da Uneb em Bonfim, denunciam agress\u00e3o moral sofrida pela professora \u00c9rica Souza, fato ocorrido no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-80133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Violencia-escolar_racismo_professora-agressao-moral_Foto-Getty-Images.png?fit=830%2C550&ssl=1","_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=80133"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80133\/revisions"}],"predecessor-version":[{"id":80136,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/80133\/revisions\/80136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80135"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=80133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=80133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=80133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}