{"id":79971,"date":"2024-03-30T08:46:11","date_gmt":"2024-03-30T11:46:11","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=79971"},"modified":"2024-03-30T08:46:14","modified_gmt":"2024-03-30T11:46:14","slug":"programa-petrobras-jovem-aprendiz-vai-abrir-mais-de-mil-vagas","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/programa-petrobras-jovem-aprendiz-vai-abrir-mais-de-mil-vagas\/","title":{"rendered":"Programa Petrobras Jovem Aprendiz vai abrir mais de mil vagas"},"content":{"rendered":"\n<p><strong>Por Isto \u00c9<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/petrobras-jovem-aprendiz_reproducao.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"395\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/petrobras-jovem-aprendiz_reproducao.jpg?resize=700%2C395&#038;ssl=1\" alt=\"\" class=\"wp-image-79972\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/petrobras-jovem-aprendiz_reproducao.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/petrobras-jovem-aprendiz_reproducao.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Reprodu\u00e7\u00e3o \/ Internet<\/sub><\/figcaption><\/figure>\n\n\n\n<p>A Petrobras vai lan\u00e7ar a maior edi\u00e7\u00e3o do Programa Petrobras Jovem Aprendiz, com n\u00famero recorde de vagas dispon\u00edveis. Ser\u00e3o mais de mil vagas em 13 estados e no Distrito Federal, abrangendo todas as regi\u00f5es do Brasil, o que representa aumento superior a 50%, em rela\u00e7\u00e3o ao oferecido na \u00faltima edi\u00e7\u00e3o. As inscri\u00e7\u00f5es poder\u00e3o ser feitas de 5 a 12 de abril, <a href=\"https:\/\/trabalheconosco.vagas.com.br\/jovemaprendizpetrobras\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">neste link<\/mark><\/strong><\/a>.<\/p>\n\n\n\n<p>Segundo a companhia, um diferencial desta edi\u00e7\u00e3o \u00e9 oferecer duas modalidades de aprendizado: a aprendizagem profissional b\u00e1sica, que tem dura\u00e7\u00e3o de 15 meses, ou o curso t\u00e9cnico, com dura\u00e7\u00e3o de 20 meses, ambas realizadas pelo Servi\u00e7o Nacional de Aprendizagem Industrial (Senai) com aulas te\u00f3ricas e pr\u00e1ticas. A iniciativa tamb\u00e9m inclui viv\u00eancias de aprendizagem em unidades da Petrobras. Assim, os jovens aprendizes podem obter, ao final do programa, um diploma de forma\u00e7\u00e3o t\u00e9cnico-profissional, podendo concorrer a vagas de n\u00edvel t\u00e9cnico no mercado de trabalho.<\/p>\n\n\n\n<p>O programa tem cota de 10% para pessoas com defici\u00eancia (PCD), 15% para adolescentes egressos de trabalho infantil, e 10% para adolescentes em situa\u00e7\u00e3o de acolhimento institucional, como abrigos, casas de passagem e resid\u00eancias inclusivas. Em car\u00e1ter experimental, tamb\u00e9m ser\u00e3o contemplados 20 aprendizes cumprindo medidas socioeducativas.<\/p>\n\n\n\n<p>As vagas ser\u00e3o destinadas a Manaus, Salvador, S\u00e3o Sebasti\u00e3o do Pass\u00e9 (BA), Fortaleza, Bras\u00edlia, Vit\u00f3ria, Betim (MG), Tr\u00eas Lagoas (MS), Ipojuca (PE), Recife, Curitiba, Natal, Canoas (RS), Aracaju, Cubat\u00e3o (SP), Mau\u00e1 (SP), Paul\u00ednia (SP), Santos (SP), S\u00e3o Jos\u00e9 dos Campos (SP), S\u00e3o Paulo, Duque de Caxias (RJ), Maca\u00e9 (RJ), Rio de Janeiro e S\u00e3o Gon\u00e7alo (RJ).<\/p>\n\n\n\n<p>O programa oferece oportunidades para jovens aprendizes em diversos cursos de aprendizagem, como assistente administrativo, auxiliar de caldeireiro, assistente de opera\u00e7\u00f5es log\u00edsticas, mec\u00e2nico de bombas, motores, compressores e equipamentos de transmiss\u00e3o, encanador hidr\u00e1ulico, instrumenta\u00e7\u00e3o, eletricista industrial, eletricista predial, mec\u00e2nico industrial, operador de suporte t\u00e9cnico em tecnologia da informa\u00e7\u00e3o, t\u00e9cnico em desenvolvimento de sistemas, t\u00e9cnico em automa\u00e7\u00e3o industrial, t\u00e9cnico em eletrot\u00e9cnica, soldador, entre outros.<\/p>\n\n\n\n<p>Tamb\u00e9m inclui, pela primeira vez, um curso t\u00e9cnico em sistemas de energias renov\u00e1veis, buscando preparar jovens para as novas demandas que surgem com a transi\u00e7\u00e3o energ\u00e9tica.<\/p>\n\n\n\n<p>Os aprendizes contratados pela Petrobras ter\u00e3o como benef\u00edcios sal\u00e1rio m\u00ednimo, vale-transporte, d\u00e9cimo terceiro sal\u00e1rio, f\u00e9rias, recolhimento de Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) e possibilidade de ades\u00e3o ao benef\u00edcio de sa\u00fade (Gympass).<\/p>\n\n\n\n<p>Para se candidatarem ao curso de aprendizagem b\u00e1sica, os jovens devem ter idade entre 14 anos e 22 anos e 8 meses. J\u00e1 para o curso de t\u00e9cnico, a idade exigida vai de 14 anos at\u00e9 22 anos e 3 meses. A idade m\u00e1xima n\u00e3o se aplica aos candidatos PCD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Isto \u00c9 A Petrobras vai lan\u00e7ar a maior edi\u00e7\u00e3o do Programa Petrobras Jovem Aprendiz, com n\u00famero recorde de vagas dispon\u00edveis. Ser\u00e3o mais de mil vagas em 13 estados e no Distrito Federal, abrangendo todas as regi\u00f5es do Brasil, o que representa aumento superior a 50%, em rela\u00e7\u00e3o ao oferecido na \u00faltima edi\u00e7\u00e3o. As inscri\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":79972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[],"class_list":["post-79971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprego"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/petrobras-jovem-aprendiz_reproducao.jpg?fit=700%2C395&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=79971"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79971\/revisions"}],"predecessor-version":[{"id":79973,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79971\/revisions\/79973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/79972"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=79971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=79971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=79971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}