{"id":79889,"date":"2024-03-24T20:11:50","date_gmt":"2024-03-24T23:11:50","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=79889"},"modified":"2024-03-24T20:11:53","modified_gmt":"2024-03-24T23:11:53","slug":"com-gleisi-hoffmann-ato-em-defesa-da-democracia-reune-militancia-e-movimentos-sociais-em-salvador","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/com-gleisi-hoffmann-ato-em-defesa-da-democracia-reune-militancia-e-movimentos-sociais-em-salvador\/","title":{"rendered":"Com Gleisi Hoffmann, ato em defesa da democracia re\u00fane milit\u00e2ncia e movimentos sociais em Salvador"},"content":{"rendered":"\n<p><strong>Ascom PT Bahia<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/PT-BA_Ato-Salvador-230324.jpeg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"526\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/PT-BA_Ato-Salvador-230324.jpeg?resize=700%2C526&#038;ssl=1\" alt=\"\" class=\"wp-image-79890\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/PT-BA_Ato-Salvador-230324.jpeg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/PT-BA_Ato-Salvador-230324.jpeg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Jo\u00e3o Valadares<\/sub><\/figcaption><\/figure>\n\n\n\n<p>O ato pol\u00edtico e cultural em defesa da democracia, realizado no Dia Nacional de Mobiliza\u00e7\u00e3o, neste s\u00e1bado, 23, no Pelourinho, em Salvador, contou com l\u00edderes pol\u00edticos, como a presidente nacional do Partido dos Trabalhadores, Gleisi Hoffmann, o presidente do PT Bahia, \u00c9den Valadares, de parlamentares petistas, secret\u00e1rios de Estado, movimentos sociais e de outros partidos pol\u00edticos. A mobiliza\u00e7\u00e3o foi promovida para reafirmar a prote\u00e7\u00e3o \u00e0 democracia e pedir a n\u00e3o anistia aos respons\u00e1veis pelas tentativas de golpe no Brasil em janeiro de 2023, ap\u00f3s a elei\u00e7\u00e3o do presidente Lula, al\u00e9m de relembrar os 60 anos da ditadura militar no pa\u00eds.<\/p>\n\n\n\n<p>A presidente nacional do PT, Gleisi Hoffman, defendeu que a democracia brasileira deva ser preservada continuamente e destacou que \u00e9 preciso estar atento para que n\u00e3o ocorram novas tentativas de golpe.<\/p>\n\n\n\n<p>&#8220;E para a gente relembrar o que foi 64 para a gente nunca mais ter ditadura no Brasil. Acho que a luta pela democracia \u00e9 essencial no nosso campo, sem democracia a gente n\u00e3o tem conquistas, a gente n\u00e3o tem espa\u00e7o para luta, para a fala. Ent\u00e3o relembrar que n\u00f3s tivemos em um passado recente, de 40 anos na ditadura, foi ruim para o Brasil do ponto de vista da democracia, \u00e9 importante. E tamb\u00e9m para relembrar os atos recentes, porque a nossa democracia foi atacada. O governo de Bolsonaro foi um governo que atacou o tempo inteiro a democracia, e quando o presidente Lula se elegeu, que ele n\u00e3o queria isso, n\u00e3o pretendiam isso, criaram uma ofensiva&#8221;, disse Gleisi, ao se referir \u00e0 tentativa de golpe em 8 de janeiro de 2023 e criticar duramente os pedidos de anistia aos respons\u00e1veis.<\/p>\n\n\n\n<p>Sobre os pedidos de anistia, o deputado federal pelo PT, Valmir Assun\u00e7\u00e3o, destacou que os ataques \u00e0s sedes dos tr\u00eas poderes foram planejados.<\/p>\n\n\n\n<p>&#8220;Acredito que quem participou que foi identificado, quem dirigiu, quem participou indiretamente, quem financiou, essas pessoas est\u00e3o sendo julgadas, est\u00e3o sendo condenadas. N\u00e3o cabe \u00e0 C\u00e2mara Federal fazer um projeto de anistia para essas pessoas, n\u00e3o cabe porque vai dar um mal exemplo para a sociedade. Ou seja, se isso acontecer, dar anistia significa que qualquer cidad\u00e3o pode cometer qualquer crime, em qualquer momento, que o parlamento brasileiro vai dar anistia? N\u00e3o pode isso. \u00c9 uma regra do jogo estabelecido, ter a Constitui\u00e7\u00e3o Federal estabelecida, n\u00f3s n\u00e3o podemos abrir m\u00e3o&#8221;.<\/p>\n\n\n\n<p>O parlamentar petista ressaltou que a retomada de fazer atos unificados \u00e9 fundamental para a democracia. &#8220;Porque em uma democracia voc\u00ea precisa de um governo que seja democr\u00e1tico, como n\u00f3s temos com o presidente Lula e o governador Jer\u00f4nimo, mas tamb\u00e9m \u00e9 preciso que os movimentos sociais, populares e sindicais sejam fortes, e quando unifica um ato desse com diversos, isso fortalece tamb\u00e9m os movimentos. Ou seja, fortalece a democracia. Agora n\u00f3s temos que entender que democracia significa o povo ter direito a trabalho, ao sal\u00e1rio, \u00e0 educa\u00e7\u00e3o, \u00e0 sa\u00fade, a oportunidades. E isso n\u00f3s temos constru\u00eddo todos os dias, e o governo Lula est\u00e1 fazendo um esfor\u00e7o muito grande para isso, mas \u00e9 preciso do povo nas ruas para concretizar isso&#8221;, disse Valmir.<\/p>\n\n\n\n<p>Estiveram presentes no ato em Salvador, neste s\u00e1bado, mais de 40 movimentos sociais, como o de mulheres, negro, LGBTQIA+, de moradia, de terra, representa\u00e7\u00f5es sindicais, associa\u00e7\u00f5es. A prefeita de Lauro Freitas, Moema Gramacho, falou sobre a uni\u00e3o dos partidos, da milit\u00e2ncia, dos movimentos e da sociedade civil para fortalecer a democracia. \u201c\u00c9 essa resist\u00eancia que nos fez sobreviver \u00e0 ditadura, que nos fez sobreviver a todos os golpes, \u00e9 essa resist\u00eancia que vai nos fazer n\u00e3o arredar um mil\u00edmetro de exigir a puni\u00e7\u00e3o dos respons\u00e1veis pelos golpes, inclusive por esse \u00faltimo golpe. E, portanto, companheiros e companheiras, n\u00f3s temos que estar juntos contra toda e qualquer forma de genoc\u00eddio, de opress\u00e3o, de tentativa de acabar com a democracia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ascom PT Bahia O ato pol\u00edtico e cultural em defesa da democracia, realizado no Dia Nacional de Mobiliza\u00e7\u00e3o, neste s\u00e1bado, 23, no Pelourinho, em Salvador, contou com l\u00edderes pol\u00edticos, como a presidente nacional do Partido dos Trabalhadores, Gleisi Hoffmann, o presidente do PT Bahia, \u00c9den Valadares, de parlamentares petistas, secret\u00e1rios de Estado, movimentos sociais e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":79890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-79889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/03\/PT-BA_Ato-Salvador-230324.jpeg?fit=700%2C526&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=79889"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79889\/revisions"}],"predecessor-version":[{"id":79891,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79889\/revisions\/79891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/79890"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=79889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=79889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=79889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}