{"id":79371,"date":"2024-02-23T12:01:06","date_gmt":"2024-02-23T15:01:06","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=79371"},"modified":"2024-02-23T12:01:08","modified_gmt":"2024-02-23T15:01:08","slug":"ex-piloto-wilson-fittipaldi-morre-em-sp-aos-80-anos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/ex-piloto-wilson-fittipaldi-morre-em-sp-aos-80-anos\/","title":{"rendered":"Ex-piloto Wilson Fittipaldi morre em SP aos 80 anos"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>Ele estava internado no Hospital Prevent Senior, na Zona Sul da capital paulista, desde o dia 25 de dezembro, ap\u00f3s se engasgar com peda\u00e7o de carne e ter uma parada card\u00edaca durante o almo\u00e7o de Natal.<\/strong><\/p>\n\n\n\n<p><strong>Por g1 SP<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilson-Fittipaldi-80-anos-%E2%80%94-Foto_Reproducao-Instagram.jpg?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"680\" height=\"537\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilson-Fittipaldi-80-anos-%E2%80%94-Foto_Reproducao-Instagram.jpg?resize=680%2C537&#038;ssl=1\" alt=\"\" class=\"wp-image-79372\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilson-Fittipaldi-80-anos-%E2%80%94-Foto_Reproducao-Instagram.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilson-Fittipaldi-80-anos-%E2%80%94-Foto_Reproducao-Instagram.jpg?resize=300%2C237&amp;ssl=1 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Wilson Fittipaldi, 80 anos \u2014 Foto: Reprodu\u00e7\u00e3o\/Instagram<\/sub><\/figcaption><\/figure>\n\n\n\n<p>O ex-piloto de F\u00f3rmula 1 Wilson Fittipaldi morreu nesta sexta-feira (23), aos 80 anos, em S\u00e3o Paulo. Ele estava internado no Hospital Prevent Senior, na Zona Sul da capital, desde dezembro do ano passado.<\/p>\n\n\n\n<p>Wilson foi hospitalizado ap\u00f3s se engasgar com um peda\u00e7o de carne e sofrer parada card\u00edaca durante um almo\u00e7o de Natal. Na ocasi\u00e3o, ele tamb\u00e9m celebrava seu anivers\u00e1rio de 80 anos.<\/p>\n\n\n\n<p>No dia 23 de janeiro, ap\u00f3s ter um quadro de espasmos, ele precisou ser novamente sedado. Semanas antes, por\u00e9m, segundo relatado pela fam\u00edlia, ele tinha sido transferido da UTI para um quarto.<\/p>\n\n\n\n<p>Chegou a ser desentubado e passou por uma traqueostomia, que \u00e9 abertura frontal da traqueia com inser\u00e7\u00e3o de c\u00e2nula.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilsinho-Fittipaldi-%E2%80%94-Foto_SEBASTIAO-MOREIRA-ESTADAO-CONTEUDO.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"680\" height=\"456\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilsinho-Fittipaldi-%E2%80%94-Foto_SEBASTIAO-MOREIRA-ESTADAO-CONTEUDO.jpg?resize=680%2C456&#038;ssl=1\" alt=\"\" class=\"wp-image-79373\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilsinho-Fittipaldi-%E2%80%94-Foto_SEBASTIAO-MOREIRA-ESTADAO-CONTEUDO.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilsinho-Fittipaldi-%E2%80%94-Foto_SEBASTIAO-MOREIRA-ESTADAO-CONTEUDO.jpg?resize=300%2C201&amp;ssl=1 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Wilsinho Fittipaldi \u2014 Foto: Sebasti\u00e3o Moreira\/Estad\u00e3o Conte\u00fado<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Em dezembro, Rita Fittipaldi, esposa do ex-piloto, relatou nas redes sociais como o marido passou mal e contou que ele chegou a ser reanimado.<\/p>\n\n\n\n<p>&#8220;No almo\u00e7o de Natal o Wilsinho engasgou com um peda\u00e7o de carne e teve uma parada card\u00edaca. Foi reanimado e se encontra sedado e entubado. Estamos aguardando ele acordar. Ele tem um hist\u00f3rico p\u00f3s-cir\u00fargico dif\u00edcil de retorno p\u00f3s-sedativo. Um dia por vez, vamos aguardar&#8221;, afirmou na \u00e9poca, na postagem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Biografia<\/mark><\/h2>\n\n\n\n<p>Wilson \u00e9 irm\u00e3o mais velho do bicampe\u00e3o mundial Emerson Fittipaldi. Foi ao lado de Emerson que ele come\u00e7ou no automobilismo na d\u00e9cada de 60.<\/p>\n\n\n\n<p>Em 1972, chegou \u00e0 F\u00f3rmula 1, onde ficou por duas temporadas como piloto. Seu melhor resultado foi um quinto lugar no GP da Alemanha em 73.<\/p>\n\n\n\n<p>Ao todo, ele participou de 38 GP\u00b4s. Seu pai, Wilson, conhecido como &#8216;Bar\u00e3o Fittipaldi&#8217;, narrava automobilismo no r\u00e1dio. Atualmente, a fam\u00edlia Fittipaldi \u00e9 representada na F1 pelo Pietro Fittipaldi, piloto reserva da Haas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ele estava internado no Hospital Prevent Senior, na Zona Sul da capital paulista, desde o dia 25 de dezembro, ap\u00f3s se engasgar com peda\u00e7o de carne e ter uma parada card\u00edaca durante o almo\u00e7o de Natal. Por g1 SP O ex-piloto de F\u00f3rmula 1 Wilson Fittipaldi morreu nesta sexta-feira (23), aos 80 anos, em S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":79372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-79371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/02\/Wilson-Fittipaldi-80-anos-%E2%80%94-Foto_Reproducao-Instagram.jpg?fit=680%2C537&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=79371"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79371\/revisions"}],"predecessor-version":[{"id":79374,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/79371\/revisions\/79374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/79372"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=79371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=79371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=79371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}