{"id":77346,"date":"2024-04-27T09:05:10","date_gmt":"2024-04-27T12:05:10","guid":{"rendered":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=77346"},"modified":"2024-04-27T09:05:13","modified_gmt":"2024-04-27T12:05:13","slug":"entenda-como-os-antidepressivos-funcionam-e-como-lidar-com-seus-efeitos-colaterais","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/entenda-como-os-antidepressivos-funcionam-e-como-lidar-com-seus-efeitos-colaterais\/","title":{"rendered":"Entenda como os antidepressivos funcionam e como lidar com seus efeitos colaterais"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Folha de S.Paulo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Shutterstock.webp?ssl=1\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Shutterstock.webp?resize=500%2C334&#038;ssl=1\" alt=\"\" class=\"wp-image-80542\" style=\"width:665px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Shutterstock.webp?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Shutterstock.webp?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Cr\u00e9dito da Imagem: Shutterstock<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em dezembro de 2021, Melina Nadale, 39, executiva do mercado financeiro, enfrentava crises ansiosas e depressivas manifestadas durante a pandemia da Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ela procurou um psiquiatra, que receitou um antidepressivo de fluoxetina, mas sofreu com os efeitos colaterais. &#8220;Eu tive muita n\u00e1usea e falta de apetite. Tamb\u00e9m sentia algumas sudoreses, redu\u00e7\u00e3o de libido e pris\u00e3o de ventre. Foi assim at\u00e9 a oitava semana ap\u00f3s o in\u00edcio do tratamento&#8221;, relata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para tentar lidar melhor com o medicamento, Nadale fez um di\u00e1rio em que anotava as sensa\u00e7\u00f5es f\u00edsicas e emocionais para depois report\u00e1-las ao m\u00e9dico e \u00e0 sua psic\u00f3loga. &#8220;Isso foi essencial para me acostumar com a medica\u00e7\u00e3o e com o tratamento no geral&#8221;, diz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante uma consulta com o psiquiatra, ela pediu para testar o medicamento gen\u00e9rico, mas, al\u00e9m de mais efeitos colaterais, teve tamb\u00e9m duas crises de epis\u00f3dios depressivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois disso, ela e o m\u00e9dico decidiram trocar a medica\u00e7\u00e3o. &#8220;Tomo cloridrato de venlafaxina desde janeiro deste ano. Nas primeiras quatro semanas, tamb\u00e9m enfrentei os mesmos efeitos colaterais, mas com intensidade bem menor&#8221;, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais uma vez, Nadale colocou em pr\u00e1tica o di\u00e1rio das sensa\u00e7\u00f5es. &#8220;Foi bem importante para eu entender quando os efeitos se manifestavam. Aprendi que, no meu caso, \u00e9 sempre melhor tomar o rem\u00e9dio de est\u00f4mago cheio para n\u00e3o sentir tanto enjoo&#8221;, observa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dois meses ap\u00f3s o in\u00edcio do novo medicamento, os efeitos colaterais cessaram e fiquei bem adaptada. J\u00e1 estou avaliando o desmame com o meu m\u00e9dico&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Telavita.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"760\" height=\"507\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Telavita.jpg?resize=760%2C507&#038;ssl=1\" alt=\"\" class=\"wp-image-80543\" style=\"width:658px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Telavita.jpg?w=760&amp;ssl=1 760w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Telavita.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Foto: Telavita<\/sub><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A psiquiatra T\u00e2nia Corr\u00eaa de Toledo Ferraz Alves, diretora de unidades interna\u00e7\u00e3o do IPq-HCFMUSP (Instituto de Psiquiatria do Hospital das Cl\u00ednicas da Faculdade de Medicina da USP) e coordenadora do Departamento de Psicogeriatra da Associa\u00e7\u00e3o Brasileira de Psiquiatria (ABP), explica que \u00e9 comum o paciente experimentar efeitos colaterais quando come\u00e7a a tomar um antidepressivo. Essas manifesta\u00e7\u00f5es, diz a m\u00e9dica, podem variar de acordo com o organismo de cada indiv\u00edduo e tamb\u00e9m com o tipo do rem\u00e9dio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Os medicamentos mais modernos, como os ISRSs (inibidores seletivos de recapta\u00e7\u00e3o de serotonina) e os duais ou ISRSNs (inibidores seletivos de recapta\u00e7\u00e3o de serotonina e de noradrenalina), t\u00eam poucos efeitos colaterais se comparados aos antidepressivos mais antigos, como os tric\u00edclicos&#8221;, afirma Alves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A serotonina e a noradrenalina s\u00e3o neurotransmissores que atuam na regula\u00e7\u00e3o do nosso humor. Os ISRSs e ISRSNs fazem com que essas subst\u00e2ncias fiquem mais tempo agindo na fenda sin\u00e1ptica, que \u00e9 o espa\u00e7o entre os neur\u00f4nios. Desse modo, melhoram os sintomas de depress\u00e3o e ansiedade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os efeitos mais comuns s\u00e3o enjoo, tontura, boca seca, constipa\u00e7\u00e3o intestinal, vis\u00e3o turva, taquicardia, sudorese, tremores e altera\u00e7\u00f5es no apetite. Essas ocorr\u00eancias duram de um a dois meses e, portanto, no in\u00edcio de tratamento, o m\u00e9dico vai avaliar a tolerabilidade do paciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Algumas pessoas t\u00eam toler\u00e2ncia menor para se adaptar. Por isso, come\u00e7amos com uma dose mais baixa e vamos aumentando gradualmente, at\u00e9 chegar na dosagem terap\u00eautica&#8221; afirma a psiquiatra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A neuropsic\u00f3loga Tammy Marchiori diz que n\u00e1usea, dor de cabe\u00e7a e ins\u00f4nia geralmente passam nas primeiras semanas. &#8220;No entanto, efeitos como ganho de peso ou disfun\u00e7\u00e3o sexual podem persistir. \u00c9 muito importante que o paciente comunique qualquer sintoma ao psiquiatra. Ele poder\u00e1 ajustar a dose, mudar de f\u00e1rmaco ou indicar outra medica\u00e7\u00e3o para gerenciar os efeitos espec\u00edficos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marchiori ressalta que fazer mudan\u00e7as no estilo de vida, como manter uma dieta saud\u00e1vel, praticar exerc\u00edcios, ioga e medita\u00e7\u00e3o, al\u00e9m de ajudar a enfrentar os efeitos colaterais, tamb\u00e9m \u00e9 indispens\u00e1vel para superar a depress\u00e3o e a ansiedade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mal-estar inicial provocado pelo uso de antidepressivos pode fazer com que o paciente acredite que o rem\u00e9dio est\u00e1 piorando o seu caso e queira abandonar o tratamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u00c9 muito importante que o profissional oriente sobre o risco dessa sensa\u00e7\u00e3o de piora inicial&#8221;, diz Alves. &#8220;Principalmente pessoas com depress\u00e3o ansiosa ou transtorno de ansiedade podem perceber aumento de sintomas no come\u00e7o do tratamento&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00e9dica ressalta que, quando bem aconselhados sobre essa possibilidade, os pacientes costumam entender que a agita\u00e7\u00e3o vai durar poucos dias, por volta de 72 horas, e conseguem administrar essa fase. O uso pontual de benzodiazep\u00ednicos, que t\u00eam a\u00e7\u00e3o calmante, pode ajudar nesse per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa orienta\u00e7\u00e3o dada aos pacientes chama-se psicoeduca\u00e7\u00e3o. \u00c9 quando o m\u00e9dico explica como os antidepressivos agem, quais s\u00e3o os efeitos colaterais, por quanto tempo duram e quando ocorre a resposta terap\u00eautica, ou seja, a melhora dos sintomas do transtorno. &#8220;A psicoeduca\u00e7\u00e3o \u00e9 fundamental para a ades\u00e3o ao tratamento&#8221;, destaca Alves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m durante a consulta, \u00e9 importante o paciente contar se j\u00e1 tomou rem\u00e9dios de uso psiqui\u00e1trico anteriormente e como se sentiu. Essa experi\u00eancia vai ajudar o m\u00e9dico a escolher o antidepressivo mais adequado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra estrat\u00e9gia para o sucesso do tratamento, conta a psiquiatra, \u00e9 tentar tirar vantagem dos efeitos colaterais. &#8220;A gente consegue escolher um antidepressivo cujo efeito colateral ajude o paciente j\u00e1 no in\u00edcio. Por exemplo, receitar um medicamento mais ativador para algu\u00e9m que est\u00e1 dormindo muito. Ou um rem\u00e9dio mais sedativo para quem est\u00e1 com ins\u00f4nia&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O hor\u00e1rio de tomar o f\u00e1rmaco tamb\u00e9m pode influenciar na adapta\u00e7\u00e3o. &#8220;Algumas medica\u00e7\u00f5es, como a mirtazapina, podem dar sono. Ent\u00e3o o indicado \u00e9 tomar \u00e0 noite. A bupropiona gera uma ativa\u00e7\u00e3o, \u00e9 recomendada para a manh\u00e3. J\u00e1 os ISRSs e duais podem dar sono ou n\u00e3o. Nesses casos, pergunto ao paciente o que ele prefere: um dia mais sonolento ou uma noite de ins\u00f4nia. A\u00ed testamos a rea\u00e7\u00e3o. Se come\u00e7amos de manh\u00e3 e ele ficou sonolento, passamos para noite e vice-versa&#8221;, explica a m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um efeito colateral que exige a suspens\u00e3o da medica\u00e7\u00e3o \u00e9 a s\u00edndrome serotonin\u00e9rgica, que ocorre quando h\u00e1 excesso de serotonina no sistema nervoso central. Os sintomas s\u00e3o agita\u00e7\u00e3o, tremores, confus\u00e3o mental e aumento da frequ\u00eancia card\u00edaca, da temperatura corporal e da press\u00e3o arterial. &#8220;\u00c9 raro, mas pode ser causada pelos antidepressivos ISRSs e duais&#8221;, conclui Alves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra manifesta\u00e7\u00e3o que requer a retirada do medicamento \u00e9 a farmacodermia, uma rea\u00e7\u00e3o al\u00e9rgica que causa manchas e bolhas pelo corpo. Nessas situa\u00e7\u00f5es, o m\u00e9dico vai substituir o antidepressivo por outro que aja de forma diferente no organismo.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Entenda como os antidepressivos funcionam<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os antidepressivos, al\u00e9m da depress\u00e3o, tratam transtornos de ansiedade, TOC (transtorno obsessivo-compulsivo), p\u00e2nico, estresse p\u00f3s-traum\u00e1tico, entre outras condi\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O uso desses medicamentos permite a redu\u00e7\u00e3o dos sintomas, ou seja, a resposta terap\u00eautica. Com a evolu\u00e7\u00e3o dos f\u00e1rmacos nas \u00faltimas d\u00e9cadas, atualmente espera-se a remiss\u00e3o completa dos sintomas e que o paciente mantenha essa recupera\u00e7\u00e3o ap\u00f3s o tratamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os antidepressivos dispon\u00edveis no mercado atuam no sistema monoamin\u00e9rgico, em que agem as monoaminas dopamina, noradrenalina e a serotonina &#8211; subst\u00e2ncias bioqu\u00edmicas que funcionam como neurotransmissores.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Antidepressivos tric\u00edclicos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os antidepressivos tric\u00edclicos (ADTs) surgiram na d\u00e9cada de 1950. S\u00e3o utilizados at\u00e9 hoje, mas costumam provocar muitos efeitos colaterais, como arritmia card\u00edaca, pris\u00e3o de ventre, reten\u00e7\u00e3o urin\u00e1ria, ganho de peso, boca seca e tontura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> imipramina, amitriptilina, clomipramina e nortriptilina.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Inibidores seletivos da recapta\u00e7\u00e3o de serotonina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os inibidores seletivos da recapta\u00e7\u00e3o de serotonina (ISRSs) foram desenvolvidos na d\u00e9cada de 1980. Atualmente, s\u00e3o os mais utilizados e considerados primeira linha de tratamento por terem bons resultados e poucos efeitos colaterais. Mesmo assim, alguns pacientes sentem n\u00e1usea, problemas intestinais, dor de cabe\u00e7a, ins\u00f4nia e redu\u00e7\u00e3o da libido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;O surgimento da fluoxetina acaba modificando bastante o tratamento. Porque com os tric\u00edclicos, a gente tinha que come\u00e7ar com uma dose baixa, de 25 mg, e ir subindo at\u00e9 a dose terap\u00eautica, de 150 mg, o que levava semanas. Mas a fluoxetina j\u00e1 se inicia na dose terap\u00eautica, de 10 mg, 20 mg&#8221;, diz a psiquiatra T\u00e2nia Corr\u00eaa de Toledo Ferraz Alves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> fluoxetina, sertralina, citalopram, escitalopram, paroxetina e fluvoxamina.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Inibidores seletivos de recapta\u00e7\u00e3o de serotonina e noradrenalina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os inibidores seletivos da recapta\u00e7\u00e3o da serotonina e da noradrenalina (ISRSNs), tamb\u00e9m chamados de duais, atuam como os ISRSs: fazem com que essas subst\u00e2ncias fiquem mais tempo agindo na fenda sin\u00e1ptica, que \u00e9 o espa\u00e7o entre os neur\u00f4nios. Desse modo, melhoram os sintomas de depress\u00e3o e ansiedade. T\u00eam efeitos semelhantes aos ISRS, mas podem aumentar a press\u00e3o arterial e a frequ\u00eancia card\u00edaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> venlafaxina, desvenlafaxina e duloxetina.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Antidepressivos tetrac\u00edclicos e unic\u00edclicos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o chamados tamb\u00e9m de at\u00edpicos, n\u00e3o sendo a primeira linha de tratamento. S\u00e3o indicados para condi\u00e7\u00f5es mais espec\u00edficas. &#8220;A mirtazapina \u00e9 uma medica\u00e7\u00e3o com efeito mais sedativo, muito interessante para os idosos. A bupropiona tem efeito sobre compuls\u00e3o, ajuda a tratar o tabagismo, por exemplo&#8221;, explica Alves. Podem causar sonol\u00eancia, tontura, boca seca, constipa\u00e7\u00e3o e ganho de peso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> mirtazapina e bupropiona.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Inibidores da monoaminoxidase<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os inibidores da monoaminoxidase (IMAO) surgiram na d\u00e9cada de 1950 e quase n\u00e3o s\u00e3o mais utilizados devido a toxidade e intera\u00e7\u00f5es medicamentosas, que podem levar \u00e0 morte. Al\u00e9m disso, tamb\u00e9m podem causar queda de press\u00e3o, ganho de peso e disfun\u00e7\u00e3o sexual. No entanto, ainda s\u00e3o uma op\u00e7\u00e3o para os pacientes que n\u00e3o respondem a outros antidepressivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> tranilcipromina e selegilina (mais usada para Parkinson).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Moduladores dos receptores 5-HT2<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m chamados de multimodais, atuam em receptores de serotonina e t\u00eam efeito sobre a aten\u00e7\u00e3o. Podem causar enjoo e tontura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Medicamentos:<\/mark><\/strong> trazodona, nefazodona e vortioxetina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Folha de S.Paulo Em dezembro de 2021, Melina Nadale, 39, executiva do mercado financeiro, enfrentava crises ansiosas e depressivas manifestadas durante a pandemia da Covid-19. Ela procurou um psiquiatra, que receitou um antidepressivo de fluoxetina, mas sofreu com os efeitos colaterais. &#8220;Eu tive muita n\u00e1usea e falta de apetite. Tamb\u00e9m sentia algumas sudoreses, redu\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-77346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2024\/04\/Antidepressivos-Foto-Telavita.jpg?fit=760%2C507&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/77346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=77346"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/77346\/revisions"}],"predecessor-version":[{"id":80544,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/77346\/revisions\/80544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/80543"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=77346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=77346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=77346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}