{"id":73240,"date":"2023-03-28T15:44:39","date_gmt":"2023-03-28T18:44:39","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=73240"},"modified":"2023-03-28T15:47:23","modified_gmt":"2023-03-28T18:47:23","slug":"pais-cobram-respostas-dois-anos-apos-garoto-desaparecer-em-itiuba-durante-as-ferias-queria-voltar-no-tempo","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/pais-cobram-respostas-dois-anos-apos-garoto-desaparecer-em-itiuba-durante-as-ferias-queria-voltar-no-tempo\/","title":{"rendered":"Pais cobram respostas dois anos ap\u00f3s garoto desaparecer em Iti\u00faba durante as f\u00e9rias: &#8216;queria voltar no tempo&#8217;"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Davi Lima, que morava com os pais em Salvador, desapareceu quando tinha 12 anos e passava f\u00e9rias com familiares. Pol\u00edcia diz que apura\u00e7\u00e3o corre em segredo de Justi\u00e7a.<\/em><\/p>\n\n\n\n<p><strong>Por Jo\u00e3o Souza e B\u00e9lit Loiane, g1 BA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/12\/Davi-e-Lilian-25122021.jpeg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"731\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/12\/Davi-e-Lilian-25122021.jpeg?resize=800%2C731\" alt=\"\" class=\"wp-image-61844\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/12\/Davi-e-Lilian-25122021.jpeg?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/12\/Davi-e-Lilian-25122021.jpeg?resize=300%2C274&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/12\/Davi-e-Lilian-25122021.jpeg?resize=768%2C702&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Davi est\u00e1 desaparecido h\u00e1 dois anos \u2014 Foto: Arquivo Pessoal<\/sub><\/figcaption><\/figure>\n\n\n\n<p>H\u00e1 dois anos a fot\u00f3grafa Lilia Lima e o marido Edson Alves sobem os tr\u00eas andares do pr\u00e9dio em que moram, no bairro do Imbu\u00ed, em Salvador, na esperan\u00e7a de que um dia voltem a fazer o mesmo trajeto ao lado do filho Davi.<\/p>\n\n\n\n<p>O garoto desapareceu aos 12 anos, no 28 de mar\u00e7o de 2021, quando saiu da casa de uma tia em dire\u00e7\u00e3o \u00e0 resid\u00eancia da av\u00f3, no povoado de Varzinha, na zona rural de Iti\u00faba, norte da Bahia.<\/p>\n\n\n\n<p>O sumi\u00e7o de Davi Lima Alves \u00e9 cercado de mist\u00e9rios. A resposta da Pol\u00edcia Civil para a fam\u00edlia sempre \u00e9 a mesma: &#8220;Falam que o caso \u00e9 complexo e que n\u00e3o tem ind\u00edcios de crime&#8221;, disse a fot\u00f3grafa.<\/p>\n\n\n\n<p>O <strong>g1<\/strong> tamb\u00e9m entrou em contato com o pol\u00edcia que, assim como aconteceu em dezembro de 2021 e mar\u00e7o de 2022 (quando Davi completou um ano desaparecido), informou que a investiga\u00e7\u00e3o est\u00e1 em segredo de Justi\u00e7a.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C600\" alt=\"\" class=\"wp-image-73241\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Pais de Davi cobram respostas dois anos ap\u00f3s o desaparecimento do filho \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Inicialmente o desaparecimento era investigado na delegacia de Iti\u00faba, munic\u00edpio em que Davi foi visto pela \u00faltima vez. No entanto, ap\u00f3s intensos pedidos dos pais do garoto, o caso foi transferido para a capital baiana.<\/p>\n\n\n\n<p>&#8220;Dizem que continuam acompanhando, que est\u00e3o dando aten\u00e7\u00e3o, mas que \u00e9 um caso complexo e que n\u00e3o tem muito o que fazer. \u00c9 sempre isso, a mesma resposta da delegada, assim como eu sempre ia l\u00e1 na delegacia de Senhor do Bonfim e a reposta era a mesma&#8221;, contou Lilia Lima.<\/p>\n\n\n\n<p>A m\u00e3e de Davi comenta que, enquanto o caso estava no interior, houve troca de delegado e foi preciso, inclusive, voltar \u00e0 cidade para contar as mesmas informa\u00e7\u00f5es. Diante disso, ela pediu ajuda para que o inqu\u00e9rito fosse transferido \u00e0 capital.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-2-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-2-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C600\" alt=\"\" class=\"wp-image-73242\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-2-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-2-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-2-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Davi tinha 12 anos quando desapareceu, em Iti\u00faba \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>O <strong>g1<\/strong> tamb\u00e9m procurou o Minist\u00e9rio P\u00fablico da Bahia (MP-BA), que informou que acompanha as investiga\u00e7\u00f5es desde as buscas iniciais e as dilig\u00eancias do inqu\u00e9rito policial. O \u00f3rg\u00e3o afirmou que quando as investiga\u00e7\u00f5es forem conclu\u00eddas, vai analisar o procedimento e tomar as provid\u00eancias necess\u00e1rias.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8220;Todo dia me pergunto onde ele est\u00e1, o que aconteceu, porque n\u00e3o saber onde ele est\u00e1 \u00e9 pior do que a morte. Voc\u00ea n\u00e3o sabe se est\u00e1 comendo, dormindo, se est\u00e1 bem&#8221;, disse a m\u00e3e de Davi.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Mesmo com as dificuldades para respostas, a fot\u00f3grafa n\u00e3o desiste.<\/p>\n\n\n\n<p>&#8220;Eu estou l\u00e1 [na delegacia] todo m\u00eas. Semana passada estive com ela [delegada] e sempre fala a mesma coisa: que \u00e9 um caso complexo, que n\u00e3o tem muito o que fazer, porque \u00e9 muita coisa que n\u00e3o faz sentido&#8221;.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8216;Queria voltar no tempo&#8217;<\/strong><\/p>\n\n\n\n<p>Lilia Lima e Edson Alves contam que ainda acreditam que v\u00e3o encontrar o filho. O triste 28 de mar\u00e7o de 2021 custa n\u00e3o terminar para eles.<\/p>\n\n\n\n<p>&#8220;Queria voltar no tempo, n\u00e3o queria ter viajado, ter ido trabalhar, queria estar com ele porque lembro o momento em que o deixei, tenho na minha mente todos os dias&#8221;, relatou.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8220;Tirei ele do carro, o deixei e ele ficou olhando para mim. Ainda olhei para ele no retrovisor, mas como eu iria imaginar que ia voltar para peg\u00e1-lo e n\u00e3o iria encontrar? Em um lugar que eu sempre deixava ele&#8221;, desabafou emocionada.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-3-Fotos-de-Davi-ficam-guardadas-no-quarto-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"646\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-3-Fotos-de-Davi-ficam-guardadas-no-quarto-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C646\" alt=\"\" class=\"wp-image-73243\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-3-Fotos-de-Davi-ficam-guardadas-no-quarto-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-3-Fotos-de-Davi-ficam-guardadas-no-quarto-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C242&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-3-Fotos-de-Davi-ficam-guardadas-no-quarto-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C620&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Fotos de Davi ficam guardadas no quarto \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>O quarto de Davi tamb\u00e9m \u00e9 o mesmo desde que deixou o c\u00f4modo para viajar. Lilia ainda n\u00e3o conseguiu lavar pe\u00e7as de roupas sujas do garoto, para sentir o cheiro do filho.<\/p>\n\n\n\n<p>&#8220;\u00c9 muito dif\u00edcil acreditar que ele n\u00e3o est\u00e1 aqui, porque est\u00e1 tudo aqui dele: as roupas, a mochila da escola, tudo est\u00e1 do mesmo jeito. Estou aqui no quarto dele todos os dias, olho as coisas dele todos os dias&#8221;, revelou.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8216;Dor que n\u00e3o tem explica\u00e7\u00e3o&#8217;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-4-Biblia-fica-exposta-no-quarto-de-Davi-com-foto-do-casal-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-4-Biblia-fica-exposta-no-quarto-de-Davi-com-foto-do-casal-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C600\" alt=\"\" class=\"wp-image-73244\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-4-Biblia-fica-exposta-no-quarto-de-Davi-com-foto-do-casal-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-4-Biblia-fica-exposta-no-quarto-de-Davi-com-foto-do-casal-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-4-Biblia-fica-exposta-no-quarto-de-Davi-com-foto-do-casal-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>B\u00edblia fica exposta no quarto de Davi, com foto do casal \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Nesses dois anos, Lilia Lima retornou para a casa dos familiares em Iti\u00faba algumas vezes e passou mal, delirou, teve febre e ficou em estado de choque.<\/p>\n\n\n\n<p>&#8220;Cheguei l\u00e1 e encontrei a casa que era o sonho dele morar, compramos porque ele queria. Me desfiz do im\u00f3vel, tive que ir at\u00e9 l\u00e1 para tirar as coisas dele e fiquei em choque&#8221;, relembrou.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-5-Davi-mora-no-bairro-do-Imbui-em-Salvador-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-5-Davi-mora-no-bairro-do-Imbui-em-Salvador-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C600\" alt=\"\" class=\"wp-image-73245\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-5-Davi-mora-no-bairro-do-Imbui-em-Salvador-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-5-Davi-mora-no-bairro-do-Imbui-em-Salvador-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-5-Davi-mora-no-bairro-do-Imbui-em-Salvador-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Davi mora no bairro do Imbu\u00ed, em Salvador, mas passava f\u00e9rias em Iti\u00faba \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Outra medida tomada pela m\u00e3e de Davi foi desativar as redes sociais devido aos trotes constantes que a fam\u00edlia recebia.<\/p>\n\n\n\n<p>&#8220;As pessoas falavam que viam algu\u00e9m parecido com ele, eu chegava a ir nos lugares, pedia a algu\u00e9m que morava pr\u00f3ximo para ir, mas quando cheg\u00e1vamos l\u00e1, era pista falsa. A gente sempre dava um jeito de ir, mas n\u00e3o era&#8221;, contou Lilia Lima.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8220;At\u00e9 hoje tenho contato com pessoas de l\u00e1, mando postar foto, cartazes e ligo para todos os orfanatos, abrigos, j\u00e1 fui em v\u00e1rios hospitais, fiquei um tempo procurando ele na rua. No lockdown, eu andava no meio da rua \u00e0s 0h sozinha procurando ele&#8221;.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>J\u00e1 o pai de Davi, Edson Alves lembra que assistia ao jogo entre Bahia e Altos, pela Copa do Nordeste, quando soube da not\u00edcia do desaparecimento do filho e n\u00e3o acreditou.<\/p>\n\n\n\n<p>&#8220;Achei que era uma brincadeira, pensei: &#8216;Davi deve estar se escondendo&#8217;. Quando cheguei l\u00e1 tinham muitas motos e o irm\u00e3o dela que achou a sand\u00e1lia me disse: &#8216;seu filho sumiu, mas eu chamei os ca\u00e7adores&#8217;, mas minha ficha n\u00e3o tinha ca\u00eddo ainda&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=800%2C600\" alt=\"\" class=\"wp-image-73246\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Davi ainda n\u00e3o conheceu o irm\u00e3o \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Nesse per\u00edodo de dois anos, a dor pelo desaparecimento do menino trouxe grandes preju\u00edzos ao casal, que chegou a se separar, mas reatou o relacionamento e teve um filho, Ravi, de 1 ano.<\/p>\n\n\n\n<p>&#8220;A gente acabou se separando, eu fiquei doida. Eles me davam calmante, porque eu n\u00e3o parava, eu dormia dentro da mata. Ficava preocupada porque l\u00e1 tem espinho, cobra, e Davi n\u00e3o podia ver um espinho que saia do lugar&#8221;, disse Lilia Lima.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>Falta de den\u00fancias<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-7-banner-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-7-banner-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C1024\" alt=\"\" class=\"wp-image-73248\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-7-banner-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-7-banner-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-7-banner-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?w=1008&amp;ssl=1 1008w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Banner com n\u00fameros para fazer den\u00fancias \u2014 Foto: B\u00e9lit Loiane\/g1 BA<\/sub><\/figcaption><\/figure>\n\n\n\n<p>Os pais do garoto acreditam que den\u00fancias de pessoas que possam ter visto o menino no dia do desaparecimento possam ajudar a pol\u00edcia. Iti\u00faba \u00e9 uma cidade considerada pequena, com \u00e1rea territorial de 1.650,593 km\u00b2 e popula\u00e7\u00e3o estimada em 36.140 pessoas.<\/p>\n\n\n\n<p>&#8220;\u00c9 muito dif\u00edcil mesmo e fa\u00e7o um apelo para quem souber de alguma coisa: denuncie, ligue, o sigilo \u00e9 garantido. Pe\u00e7o para que me ajudem a encontrar o meu filho e saber o que aconteceu com ele. Eu quero encontrar ele, seja vivo ou morto, mas preciso encontrar ele&#8221;, disse Edson Alves.<\/p>\n\n\n\n<p>Edson conta que, desde o desaparecimento de Davi, n\u00e3o consegue dormir e nem se alimentar direito. Disse ainda que n\u00e3o consegue trabalhar e \u00e9 como se nada mais fizesse sentido para ele.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>&#8220;\u00c9 um vazio que nada vai preencher&#8221;, refor\u00e7ou.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-8-%E2%80%94-Foto-Arquivo-Pessoal.webp\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-8-%E2%80%94-Foto-Arquivo-Pessoal.webp?resize=800%2C533\" alt=\"\" class=\"wp-image-73249\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-8-%E2%80%94-Foto-Arquivo-Pessoal.webp?w=1008&amp;ssl=1 1008w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-8-%E2%80%94-Foto-Arquivo-Pessoal.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-8-%E2%80%94-Foto-Arquivo-Pessoal.webp?resize=768%2C512&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\"><sub>Davi est\u00e1 desaparecido h\u00e1 dois anos \u2014 Foto: Arquivo Pessoal<\/sub><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Davi Lima, que morava com os pais em Salvador, desapareceu quando tinha 12 anos e passava f\u00e9rias com familiares. Pol\u00edcia diz que apura\u00e7\u00e3o corre em segredo de Justi\u00e7a. Por Jo\u00e3o Souza e B\u00e9lit Loiane, g1 BA H\u00e1 dois anos a fot\u00f3grafa Lilia Lima e o marido Edson Alves sobem os tr\u00eas andares do pr\u00e9dio em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":73246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["post-73240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2023\/03\/Itiuba-Caso-Davi-6-%E2%80%94-Foto-Belit-Loiane-g1-BA.webp?fit=1008%2C756&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/73240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=73240"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/73240\/revisions"}],"predecessor-version":[{"id":73250,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/73240\/revisions\/73250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/73246"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=73240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=73240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=73240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}