{"id":69195,"date":"2022-10-05T12:00:12","date_gmt":"2022-10-05T15:00:12","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=69195"},"modified":"2022-10-05T12:00:16","modified_gmt":"2022-10-05T15:00:16","slug":"rompimento-de-adutora-afeta-abastecimento-de-agua-em-ponto-novo-e-filadelfia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/rompimento-de-adutora-afeta-abastecimento-de-agua-em-ponto-novo-e-filadelfia\/","title":{"rendered":"Rompimento de adutora afeta abastecimento de \u00e1gua em Ponto Novo e Filad\u00e9lfia"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?resize=512%2C507\" alt=\"\" class=\"wp-image-69196\" width=\"512\" height=\"507\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?resize=1024%2C1013&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?resize=300%2C297&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?resize=768%2C760&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?w=1125&amp;ssl=1 1125w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure>\n\n\n\n<p>A Embasa necessitou interromper na manh\u00e3 desta quarta-feira (05) o abastecimento de \u00e1gua em Ponto Novo e Filad\u00e9lfia para realizar servi\u00e7os de manuten\u00e7\u00e3o em trecho de uma adutora que atende os dois munic\u00edpios. Os servi\u00e7os de manuten\u00e7\u00e3o devem ser conclu\u00eddos at\u00e9 as 22. Ap\u00f3s a conclus\u00e3o, o fornecimento de \u00e1gua ser\u00e1 reiniciado de forma gradativa. Moradores cujos im\u00f3veis possuem reserva\u00e7\u00e3o adequada e suficiente poder\u00e3o n\u00e3o sentir os efeitos da interrup\u00e7\u00e3o, mas \u00e9 recomend\u00e1vel que todos economizem \u00e1gua durante este per\u00edodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Embasa necessitou interromper na manh\u00e3 desta quarta-feira (05) o abastecimento de \u00e1gua em Ponto Novo e Filad\u00e9lfia para realizar servi\u00e7os de manuten\u00e7\u00e3o em trecho de uma adutora que atende os dois munic\u00edpios. Os servi\u00e7os de manuten\u00e7\u00e3o devem ser conclu\u00eddos at\u00e9 as 22. Ap\u00f3s a conclus\u00e3o, o fornecimento de \u00e1gua ser\u00e1 reiniciado de forma gradativa. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["post-69195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/10\/Manutencao_FiladelfiaPontoNovo_outubro-2022.jpg?fit=1125%2C1113&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/69195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=69195"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/69195\/revisions"}],"predecessor-version":[{"id":69198,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/69195\/revisions\/69198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/69196"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=69195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=69195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=69195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}