{"id":62607,"date":"2022-02-03T21:01:32","date_gmt":"2022-02-04T00:01:32","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=62607"},"modified":"2022-02-03T21:01:34","modified_gmt":"2022-02-04T00:01:34","slug":"senai-pe-oferece-370-bolsas-de-estudos-gratuitas-para-cursos-tecnicos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/senai-pe-oferece-370-bolsas-de-estudos-gratuitas-para-cursos-tecnicos\/","title":{"rendered":"SENAI-PE oferece 370 bolsas de estudos gratuitas para cursos t\u00e9cnicos"},"content":{"rendered":"\n<p><strong>Clas Comunica\u00e7\u00e3o e Marketing<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"452\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg?resize=800%2C452\" alt=\"\" class=\"wp-image-62608\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg?resize=1024%2C578&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg?resize=768%2C433&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/SENAI-PE_03022022.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Com o objetivo de atender \u00e0s demandas do setor industrial por m\u00e3o de obra qualificada, o Servi\u00e7o Nacional de Aprendizagem Industrial em Pernambuco (SENAI-PE) ir\u00e1 ofertar 370 bolsas de estudos integrais para os cursos t\u00e9cnicos oferecidos pela institui\u00e7\u00e3o. As inscri\u00e7\u00f5es para o processo seletivo s\u00e3o gratuitas e poder\u00e3o ser feitas entre os dias 4 e 8 de fevereiro. Na unidade de Petrolina, est\u00e3o sendo oferecidas 10 vagas para o curso t\u00e9cnico em Eletromec\u00e2nica, e 20 vagas para o curso t\u00e9cnico em Seguran\u00e7a do Trabalho, ambos \u00e0 dist\u00e2ncia. As aulas ter\u00e3o in\u00edcio ainda neste m\u00eas de fevereiro. O edital completo e o formul\u00e1rio para inscri\u00e7\u00e3o est\u00e3o dispon\u00edveis no <a href=\"http:\/\/www.pe.senai.br\" data-type=\"URL\" data-id=\"www.pe.senai.br\" target=\"_blank\" rel=\"noreferrer noopener\">www.pe.senai.br<\/a>.<\/p>\n\n\n\n<p>Poder\u00e3o concorrer \u00e0s bolsas de estudos pessoas de baixa renda que j\u00e1 conclu\u00edram o Ensino M\u00e9dio e que obtiveram m\u00e9dia igual ou superior a 450 pontos nas edi\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (ENEM) realizadas nos anos de 2018, 2019, 2020 ou 2021. O preenchimento das vagas ser\u00e1 feito a partir das notas dos candidatos, observando-se a quantidade de vagas dispon\u00edveis para cada curso. No momento da inscri\u00e7\u00e3o, ser\u00e1 necess\u00e1rio indicar curso, turno e escola de interesse. As vagas est\u00e3o dispon\u00edveis tamb\u00e9m para as unidades localizadas no Recife (Areias e Santo Amaro); Paulista; Cabo; Ipojuca; Goiana; Caruaru e Belo Jardim.<\/p>\n\n\n\n<p>Al\u00e9m dos cursos mais procurados na institui\u00e7\u00e3o \u2013 Eletrot\u00e9cnica, Refrigera\u00e7\u00e3o e Climatiza\u00e7\u00e3o e Manuten\u00e7\u00e3o Automotiva \u2013, tamb\u00e9m h\u00e1 oportunidades para cursos que est\u00e3o sendo oferecidos pela primeira vez, com foco na ind\u00fastria do futuro, como Cibersistemas para Automa\u00e7\u00e3o e Internet das Coisas \u2013 IOT. <em>\u201cEstamos atentos \u00e0s necessidades do setor produtivo e queremos formar profissionais capazes de atender a essas demandas, sempre garantindo a forma\u00e7\u00e3o pr\u00e1tica que \u00e9 a marca registrada do SENAI-PE\u201d<\/em>, ressalta a diretora de Educa\u00e7\u00e3o do SENAI-PE, Carla Abigail.<\/p>\n\n\n\n<p>O resultado do processo seletivo ser\u00e1 divulgado no pr\u00f3ximo dia 9 de fevereiro. Os candidatos aprovados dever\u00e3o realizar suas matr\u00edculas presencialmente na escola t\u00e9cnica indicada no ato de sua inscri\u00e7\u00e3o, nos dias 10 e 11 de fevereiro. Nesse momento, o estudante dever\u00e1 apresentar uma autodeclara\u00e7\u00e3o da condi\u00e7\u00e3o de baixa renda e comprovante com as notas do ENEM, al\u00e9m das c\u00f3pias dos seguintes documentos: certificado de conclus\u00e3o do Ensino M\u00e9dio, hist\u00f3rico escolar ou declara\u00e7\u00e3o emitida pela escola; documento de identifica\u00e7\u00e3o pessoal (RG, CNH, Passaporte ou CTPS); CPF; e comprovante de resid\u00eancia.<\/p>\n\n\n\n<p><strong>Sistema FIEPE<\/strong> &#8211; Mantido pelo setor industrial, atua no desenvolvimento de solu\u00e7\u00f5es para trazer ainda mais competitividade ao segmento. Al\u00e9m do SENAI \u2013 que atua na forma\u00e7\u00e3o profissional e oferece servi\u00e7os de metrologia e ensaios, consultorias e inova\u00e7\u00e3o \u2013 conta ainda com a FIEPE, o SESI e o IEL. A Federa\u00e7\u00e3o realiza a defesa de interesse do setor produtivo e contribui com o processo de internacionaliza\u00e7\u00e3o das ind\u00fastrias. Pelo SESI-PE, s\u00e3o oferecidos servi\u00e7os de sa\u00fade e educa\u00e7\u00e3o b\u00e1sica para os industri\u00e1rios, familiares e comunidade geral. J\u00e1 o IEL-PE foca na carreira profissional dos trabalhadores, desde a sele\u00e7\u00e3o de estagi\u00e1rios e profissionais, at\u00e9 a capacita\u00e7\u00e3o deles realizada pela sua Escola de Neg\u00f3cios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clas Comunica\u00e7\u00e3o e Marketing Com o objetivo de atender \u00e0s demandas do setor industrial por m\u00e3o de obra qualificada, o Servi\u00e7o Nacional de Aprendizagem Industrial em Pernambuco (SENAI-PE) ir\u00e1 ofertar 370 bolsas de estudos integrais para os cursos t\u00e9cnicos oferecidos pela institui\u00e7\u00e3o. As inscri\u00e7\u00f5es para o processo seletivo s\u00e3o gratuitas e poder\u00e3o ser feitas entre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-62607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2021\/04\/SENAI_CursosDesconto_03.jpeg?fit=1280%2C718&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=62607"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62607\/revisions"}],"predecessor-version":[{"id":62609,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62607\/revisions\/62609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/55281"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=62607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=62607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=62607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}