{"id":62567,"date":"2022-02-01T09:23:53","date_gmt":"2022-02-01T12:23:53","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=62567"},"modified":"2022-02-01T09:23:55","modified_gmt":"2022-02-01T12:23:55","slug":"orfaos-da-covid-19-poderao-receber-pensao-ate-os-18-anos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/orfaos-da-covid-19-poderao-receber-pensao-ate-os-18-anos\/","title":{"rendered":"\u00d3rf\u00e3os da Covid 19 poder\u00e3o receber pens\u00e3o at\u00e9 os 18 anos"},"content":{"rendered":"\n<p><strong>Da R\u00e1dio C\u00e2mara, de Bras\u00edlia, Karla Alessandra<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg?resize=674%2C450\" alt=\"\" class=\"wp-image-62568\" width=\"674\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg?w=899&amp;ssl=1 899w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg?resize=768%2C513&amp;ssl=1 768w\" sizes=\"(max-width: 674px) 100vw, 674px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>A C\u00e2mara est\u00e1 analisando proposta que prev\u00ea o pagamento de pens\u00e3o para crian\u00e7as e jovens que tiverem perdido seus pais para a Covid 19. Pelo projeto, as crian\u00e7as que tiverem perdido tanto o pai quanto a m\u00e3e receber\u00e3o o valor de um sal\u00e1rio m\u00ednimo, corrigido anualmente at\u00e9 que completem 18 anos.<\/p>\n\n\n\n<p>Segundo dados do Conselho Nacional de Justi\u00e7a e do Conselho Nacional de Direitos Humanos, entre os meses de mar\u00e7o de 2020 e abril de 2021, cerca de 113 mil crian\u00e7as e adolescentes perderam o pai, a m\u00e3e ou ambos para a Covid-19.<\/p>\n\n\n\n<p>A medida est\u00e1 sendo analisada pela Comiss\u00e3o de Seguridade Social e Fam\u00edlia, e o autor da proposta, deputado Fl\u00e1vio Nogueira (PDT-PI), defende que \u00e9 preciso garantir recursos para a manuten\u00e7\u00e3o dessas crian\u00e7as, seja por parentes ou em institui\u00e7\u00f5es assistenciais.<\/p>\n\n\n\n<p><em>\u201cA pens\u00e3o ser\u00e1 entregue \u00e0 pessoa f\u00edsica e \u00e0s institui\u00e7\u00f5es que cuidam dessas crian\u00e7as \u00f3rf\u00e3s. O projeto estabelece que o Fundo Nacional de Assist\u00eancia Social seja a fonte desses recursos a serem oferecidos\u201d<\/em>.<\/p>\n\n\n\n<p>O texto determina ainda que a aplica\u00e7\u00e3o desses recursos ser\u00e1 fiscalizada pelos conselhos tutelares dos munic\u00edpios, que dever\u00e3o apresentar anualmente relat\u00f3rio sobre o uso dessas pens\u00f5es.<\/p>\n\n\n\n<p>A proposta que prev\u00ea pens\u00e3o para os \u00f3rf\u00e3os da Covid19 vai ser analisada tamb\u00e9m pelas comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o e de Constitui\u00e7\u00e3o e Justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da R\u00e1dio C\u00e2mara, de Bras\u00edlia, Karla Alessandra A C\u00e2mara est\u00e1 analisando proposta que prev\u00ea o pagamento de pens\u00e3o para crian\u00e7as e jovens que tiverem perdido seus pais para a Covid 19. Pelo projeto, as crian\u00e7as que tiverem perdido tanto o pai quanto a m\u00e3e receber\u00e3o o valor de um sal\u00e1rio m\u00ednimo, corrigido anualmente at\u00e9 que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":62568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-62567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/02\/Orfaos-da-Covid-19.jpg?fit=899%2C600&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=62567"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62567\/revisions"}],"predecessor-version":[{"id":62569,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62567\/revisions\/62569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/62568"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=62567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=62567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=62567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}