{"id":62280,"date":"2022-01-16T22:15:14","date_gmt":"2022-01-17T01:15:14","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=62280"},"modified":"2022-01-16T22:15:16","modified_gmt":"2022-01-17T01:15:16","slug":"cantora-de-brega-morre-e-pelo-menos-tres-pessoas-ficam-feridas-apos-motorista-de-kombi-bater-em-poste-em-pernambuco","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/cantora-de-brega-morre-e-pelo-menos-tres-pessoas-ficam-feridas-apos-motorista-de-kombi-bater-em-poste-em-pernambuco\/","title":{"rendered":"Cantora de brega morre e pelo menos tr\u00eas pessoas ficam feridas ap\u00f3s motorista de Kombi bater em poste em Pernambuco"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">V\u00edtima foi Jamyli Magalh\u00e3es, da Banda Adupla, que estava come\u00e7ando a carreira musical. Segundo a Pol\u00edcia Civil, condutor do ve\u00edculo fugiu sem prestar socorro.<\/p>\n\n\n\n<p><strong>Por g1 PE<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg?resize=738%2C544\" alt=\"\" class=\"wp-image-62281\" width=\"738\" height=\"544\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg?w=984&amp;ssl=1 984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg?resize=768%2C566&amp;ssl=1 768w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/a><figcaption><sub>Jamyli Magalh\u00e3es, de 18 anos, estava come\u00e7ando a carreira como cantora ao lado de Duda Morais \u2014 Foto: Reprodu\u00e7\u00e3o\/Instagram<\/sub><\/figcaption><\/figure><\/div>\n\n\n\n<p>Uma cantora de brega de 18 anos morreu e pelo menos tr\u00eas pessoas ficaram feridas ap\u00f3s um acidente com uma Kombi na PE-22, no bairro de Maranguape II, em Paulista, no Grande Recife, na noite do s\u00e1bado (15). Segundo a Pol\u00edcia Civil, o motorista perdeu o controle do ve\u00edculo, bateu em um poste e deixou o local do acidente sem prestar socorro \u00e0s v\u00edtimas.<\/p>\n\n\n\n<p>Imagens enviadas ao g1 pelo WhatsApp mostram a Kombi com amassados tamb\u00e9m na parte superior, al\u00e9m do poste quebrado. As pessoas falam que o ve\u00edculo teria capotado, mas a informa\u00e7\u00e3o n\u00e3o foi confirmada pela Pol\u00edcia Civil.<\/p>\n\n\n\n<p>A jovem foi socorrida, mas morreu no Hospital Miguel Arraes, no mesmo munic\u00edpio, afirmaram os parentes. Segundo o empres\u00e1rio Pepeu Nascimento, a v\u00edtima foi Jamyli Iali Magalh\u00e3es, que estava iniciando a carreira como cantora na Banda Adupla, com Duda Morais, do Rio Grande do Norte.<\/p>\n\n\n\n<p><em>&#8220;T\u00ednhamos acabado de gravar um DVD, onde ir\u00edamos lan\u00e7ar a primeira faixa sexta feira agora dia 21&#8221;<\/em>, contou o empres\u00e1rio (<em>saiba mais sobre a jovem ao fim da reportagem<\/em>).<\/p>\n\n\n\n<p>O cunhado de Jamyli, Jos\u00e9 J\u00fanior, contou que a jovem voltava de uma festa com quatro pessoas, quando ocorreu o acidente. <em>&#8220;O rapaz que fez o transporte tentou fazer uma manobra arriscada. A Kombi capotou v\u00e1rias vezes e se chocou com o poste&#8221;<\/em>, relatou.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/frame-00-00-04.032.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/frame-00-00-04.032.jpg?resize=738%2C569\" alt=\"\" class=\"wp-image-62282\" width=\"738\" height=\"569\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/frame-00-00-04.032.jpg?w=984&amp;ssl=1 984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/frame-00-00-04.032.jpg?resize=300%2C231&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/frame-00-00-04.032.jpg?resize=768%2C592&amp;ssl=1 768w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/a><figcaption><sub>O motorista da Kombi que capotou na PE-22 fugiu sem prestar socorro \u00e0s v\u00edtimas \u2014 Foto: Imagem enviada ao WhatsApp da TV Globo<\/sub><\/figcaption><\/figure><\/div>\n\n\n\n<p>O Corpo de Bombeiros disse ter socorrido uma pessoa para o Hospital da Restaura\u00e7\u00e3o, na \u00e1rea central do Recife e que outras tr\u00eas teriam sido atendidas pelo Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu). No entanto, a corpora\u00e7\u00e3o n\u00e3o soube precisar se, entre os quatro socorridos, j\u00e1 estava a jovem que faleceu no hospital.<\/p>\n\n\n\n<p>O <strong>g1<\/strong> tentou, mas n\u00e3o conseguiu contato para saber para quais unidades de sa\u00fade os feridos foram. Como os nomes n\u00e3o foram divulgados, n\u00e3o foi poss\u00edvel obter detalhes do estado de sa\u00fade.<\/p>\n\n\n\n<p>De acordo com a Pol\u00edcia Civil, o motorista da Kombi, que fugiu sem prestar socorro \u00e0s v\u00edtimas, ainda n\u00e3o foi identificado. A corpora\u00e7\u00e3o tamb\u00e9m n\u00e3o soube informar quantas pessoas ocupavam o ve\u00edculo.<\/p>\n\n\n\n<p>Um inqu\u00e9rito policial foi aberto para investigar o caso, registrado na 8\u00aa Delegacia Seccional de Pol\u00edcia, em Paulista, como acidente de tr\u00e2nsito com v\u00edtima fatal e omiss\u00e3o de socorro.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size\"><strong>Quem era Jamyli Magalh\u00e3es?<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamylii.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamylii.jpg?resize=738%2C536\" alt=\"\" class=\"wp-image-62283\" width=\"738\" height=\"536\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamylii.jpg?w=984&amp;ssl=1 984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamylii.jpg?resize=300%2C218&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamylii.jpg?resize=768%2C558&amp;ssl=1 768w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/a><figcaption><sub>Jamyli Magalh\u00e3es e Duda Morais formavam a Banda Adupla \u2014 Foto: Reprodu\u00e7\u00e3o\/Instagram<\/sub><\/figcaption><\/figure><\/div>\n\n\n\n<p>Jamyli Magalh\u00e3es, de 18 anos, estava come\u00e7ando a realizar o sonho de ser cantora profissionalmente. Ela e Duda Morais, jovem de Mossor\u00f3 (RN), tinham acabado de gravar um DVD e estavam se organizando para come\u00e7ar a fazer shows na Banda Adupla.<\/p>\n\n\n\n<p><em>&#8220;Estou destru\u00edda. N\u00e3o t\u00ednhamos come\u00e7ado os shows ainda, \u00edamos primeiro lan\u00e7ar as m\u00fasicas. Minhas expectativas estavam altas, pois fizemos um trabalho incr\u00edvel e, com certeza, seria sucesso&#8221;<\/em>, disse Duda por mensagem ao <strong>g1<\/strong>, neste domingo (16).<\/p>\n\n\n\n<p>As duas tinham se conhecido em julho de 2021, quando Duda veio ao Recife gravar um clipe musical. <em>&#8220;T\u00ednhamos um \u00f3timo relacionamento. [Ela era] sempre muito animada e com brincadeiras, toda apressadinha, fazendo todo mundo rir. [Guardo] muitas lembras e as m\u00fasicas que ela escreveu e compartilhou comigo&#8221;<\/em>, contou a cantora.<\/p>\n\n\n\n<p>Na redes sociais, Andressa Barbosa, m\u00e3e da jovem, disse que queria lembrar da filha cantando e feliz. <em>&#8220;Foi embora um peda\u00e7o de mim&#8221;<\/em>, escreveu.<\/p>\n\n\n\n<p>O cunhado, Jos\u00e9 J\u00fanior, disse que a fam\u00edlia est\u00e1 arrasada. Jamily tinha duas irm\u00e3s e um irm\u00e3o. Ela morava com a m\u00e3e perto do local do acidente. <em>&#8220;A m\u00e3e dela est\u00e1 muito mal, a ficha dela ainda n\u00e3o caiu. Est\u00e1 muito para baixo, sem acreditar, sem entender porque, porque uma pessoa t\u00e3o boa, com um brilho como o dela&#8221;<\/em>, relatou J\u00fanior.<\/p>\n\n\n\n<p>Segundo ele, a cunhada era uma pessoa muito pr\u00f3xima da fam\u00edlia. <em>&#8220;A alegria da casa era ela. [Vou lembrar do] o sorriso, a alegria. O jeito contagiante de brincar, sempre animada&#8221;<\/em>, disse.<\/p>\n\n\n\n<p>O enterro deve ocorrer na segunda-feira (17), no Cemit\u00e9rio Municipal de Paulista, no Grande Recife, segundo a fam\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtima foi Jamyli Magalh\u00e3es, da Banda Adupla, que estava come\u00e7ando a carreira musical. Segundo a Pol\u00edcia Civil, condutor do ve\u00edculo fugiu sem prestar socorro. Por g1 PE Uma cantora de brega de 18 anos morreu e pelo menos tr\u00eas pessoas ficaram feridas ap\u00f3s um acidente com uma Kombi na PE-22, no bairro de Maranguape II, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":62281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[8],"tags":[],"class_list":["post-62280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2022\/01\/jamyle-01.jpeg?fit=984%2C725&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=62280"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62280\/revisions"}],"predecessor-version":[{"id":62284,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/62280\/revisions\/62284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/62281"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=62280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=62280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=62280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}