{"id":51926,"date":"2020-12-13T12:07:34","date_gmt":"2020-12-13T15:07:34","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51926"},"modified":"2020-12-13T12:07:39","modified_gmt":"2020-12-13T15:07:39","slug":"cidadaos-tem-direito-a-chamar-a-policia-ao-ver-alguem-sem-mascara-de-protecao-na-rua","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/cidadaos-tem-direito-a-chamar-a-policia-ao-ver-alguem-sem-mascara-de-protecao-na-rua\/","title":{"rendered":"Cidad\u00e3os t\u00eam direito a chamar a pol\u00edcia ao ver algu\u00e9m sem m\u00e1scara de prote\u00e7\u00e3o na rua?"},"content":{"rendered":"\n<h5 class=\"has-text-align-center wp-block-heading\"><em>A advogada Dr\u00aa Tatiana Viola tira esta e outras d\u00favidas<\/em><\/h5>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"566\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?resize=800%2C566\" alt=\"\" class=\"wp-image-51927\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?resize=1024%2C724&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Diante do atual cen\u00e1rio de piora da primeira onda de Covid-19 no Pa\u00eds, ou mesmo de uma segunda onda, \u00e9 justo que quem segue as normas de prote\u00e7\u00e3o contra a Covid-19 continue correndo o risco de pagar pela displic\u00eancia alheia? Segundo a <strong>advogada Dr\u00aa Tatiana Viola de Queiroz<\/strong>, especialista em Direito \u00e0 Sa\u00fade e do Consumidor, isso n\u00e3o \u00e9 correto. Por isso, ela acredita que as pessoas precisam se mobilizar e cobrar o uso correto da m\u00e1scara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cO cidad\u00e3o tem, sim, o direito de chamar a pol\u00edcia ao ver algu\u00e9m sem m\u00e1scara de prote\u00e7\u00e3o ou utilizando-a de forma incorreta em lugares p\u00fablicos\u201d<\/em>, afirma a advogada consultora da loja M\u00e1scara Delivery Original.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infelizmente, ainda h\u00e1 quem n\u00e3o use corretamente a m\u00e1scara, continue participando de aglomera\u00e7\u00f5es e n\u00e3o fa\u00e7a a higieniza\u00e7\u00e3o das m\u00e3os, mesmo tendo consci\u00eancia da import\u00e2ncia destes cuidados. Por isso, a advogada insiste para que a popula\u00e7\u00e3o se mobilize em uma corrente do bem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segunda ela, n\u00e3o \u00e9 mais admiss\u00edvel que tantas pessoas continuem ignorando medidas simples e \u00e9ticas de autocuidado e cuidado com os pr\u00f3ximos, principalmente com os mais velhos, pessoas de baixa imunidade e que sofrem de comorbidades, e que sabidamente t\u00eam maior risco de complica\u00e7\u00f5es no caso de contra\u00edrem o novo coronav\u00edrus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cA informa\u00e7\u00e3o do que \u00e9 necess\u00e1rio fazer para se proteger e proteger os outros est\u00e1 amplamente disseminada nos meios profissionais e s\u00e9rios de comunica\u00e7\u00e3o. N\u00e3o d\u00e1 mais para aceitar tamanha falta de \u00e9tica e civilidade por tantos brasileiros. \u00c9 hora de o cidad\u00e3o saber o que fazer, quando tem o direito de cobrar os outros, ou melhor, de exigir\u201d<\/em>, afirma a Dr\u00aa Tatiana.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?resize=800%2C450\" alt=\"\" class=\"wp-image-51928\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-02.jpg?w=1600 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>A advogada esclarece os direitos e deveres dos cidad\u00e3os com rela\u00e7\u00e3o a este tema:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Como funciona a lei do uso da m\u00e1scara no Brasil? Quais s\u00e3o as diferen\u00e7as regionais?<\/strong> &#8211; O uso de m\u00e1scaras \u00e9 obrigat\u00f3rio no Brasil todo, como determina a Lei Federal 14.019\/2020, mas algumas cidades e Estados tamb\u00e9m sancionaram leis espec\u00edficas para as suas regi\u00f5es. Assim, as legisla\u00e7\u00f5es se somam e se houver lei local mais r\u00edgida, \u00e9 essa que deve ser obedecida.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Onde o uso da m\u00e1scara \u00e9 obrigat\u00f3rio por lei? E em quais locais?<\/strong> &#8211; \u00c9 obrigat\u00f3rio manter boca e nariz cobertos por m\u00e1scara de prote\u00e7\u00e3o individual, conforme a legisla\u00e7\u00e3o sanit\u00e1ria e na forma de regulamenta\u00e7\u00e3o estabelecida pelo Poder Executivo Federal, para circula\u00e7\u00e3o em espa\u00e7os p\u00fablicos e privados acess\u00edveis ao p\u00fablico, em vias p\u00fablicas e em transportes p\u00fablicos coletivos, bem como em ve\u00edculos de transporte remunerado privado individual de passageiros por aplicativo ou por meio de t\u00e1xis; \u00f4nibus, aeronaves ou embarca\u00e7\u00f5es de uso coletivo fretados.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante lembrar que a obriga\u00e7\u00e3o do uso de m\u00e1scara est\u00e1 dispensada no caso de pessoas com transtorno do espectro autista, com defici\u00eancia intelectual, com defici\u00eancias sensoriais ou com quaisquer outras defici\u00eancias que as impe\u00e7am de fazer o uso adequado de m\u00e1scara de prote\u00e7\u00e3o facial, conforme declara\u00e7\u00e3o m\u00e9dica, que pode ser obtida por meio digital, bem como no caso de crian\u00e7as com menos de 3 anos de idade.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"566\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-03.png?resize=800%2C566\" alt=\"\" class=\"wp-image-51929\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-03.png?resize=1024%2C724&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-03.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-03.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-03.png?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cidad\u00e3os e cidad\u00e3s t\u00eam o direito de chamar a pol\u00edcia ao ver algu\u00e9m sem m\u00e1scara na rua?<\/strong> &#8211; Sim, t\u00eam direito, pois a n\u00e3o utiliza\u00e7\u00e3o pode configurar crime de acordo com o artigo 268 do C\u00f3digo Penal que determina: <em>Infringir determina\u00e7\u00e3o do poder p\u00fablico, destinada a impedir introdu\u00e7\u00e3o ou propaga\u00e7\u00e3o de doen\u00e7a contagiosa, com o risco de pena de deten\u00e7\u00e3o, de um m\u00eas a um ano, e multa. O artigo 132 do C\u00f3digo Penal tamb\u00e9m configura como crime o ato de expor a vida ou a sa\u00fade de outrem a perigo direto e iminente, com pena de deten\u00e7\u00e3o de tr\u00eas meses a um ano<\/em>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cidad\u00e3os e cidad\u00e3s t\u00eam o direito de chamar a pol\u00edcia ao ver algu\u00e9m sem m\u00e1scara no seu condom\u00ednio ou no elevador do seu pr\u00e9dio?<\/strong> &#8211; Sim, tamb\u00e9m t\u00eam, pois a lei determina a obrigatoriedade da utiliza\u00e7\u00e3o das m\u00e1scaras em espa\u00e7os privados acess\u00edveis ao p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante ressaltar que configura crime de epidemia (art. 267 do C\u00f3digo Penal) quando determinada pessoa, ciente de estar contaminada pela Covid-19, promove deliberadamente a transmiss\u00e3o da doen\u00e7a a outros. Neste caso, h\u00e1 o risco de aplica\u00e7\u00e3o de pena de reclus\u00e3o de dez a quinze anos. E se desse fato se resulta morte, a pena \u00e9 aplicada em dobro.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cidad\u00e3os e cidad\u00e3s t\u00eam o direito de reclamar com uma pessoa que n\u00e3o usa m\u00e1scara na rua ou local p\u00fablico? Ou esta abordagem seria pass\u00edvel de puni\u00e7\u00e3o?<\/strong> &#8211; Com certeza t\u00eam, todos s\u00e3o respons\u00e1veis e qualquer cidad\u00e3o pode dar, inclusive, voz de pris\u00e3o para algu\u00e9m em flagrante delito. Inclusive, segundo o artigo 301 do C\u00f3digo Penal, qualquer cidad\u00e3o tem o poder de anunciar a pris\u00e3o de uma pessoa que cometa flagrante delito. N\u00e3o \u00e9 necess\u00e1ria a presen\u00e7a da autoridade no momento do flagrante, basta o simples an\u00fancio.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na pr\u00e1tica, tem acontecido a judicializa\u00e7\u00e3o do uso ou n\u00e3o uso de m\u00e1scaras?<\/strong> Infelizmente n\u00e3o, pois as pessoas ainda n\u00e3o perceberam que o n\u00e3o uso da m\u00e1scara \u00e9 algo grave e perigoso. Por\u00e9m, sua n\u00e3o utiliza\u00e7\u00e3o, de acordo com o exposto acima, configura-se crime, sim.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A advogada Dr\u00aa Tatiana Viola tira esta e outras d\u00favidas Diante do atual cen\u00e1rio de piora da primeira onda de Covid-19 no Pa\u00eds, ou mesmo de uma segunda onda, \u00e9 justo que quem segue as normas de prote\u00e7\u00e3o contra a Covid-19 continue correndo o risco de pagar pela displic\u00eancia alheia? Segundo a advogada Dr\u00aa Tatiana [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-51926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/12\/Mascara-01.png?fit=1280%2C905&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51926"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51926\/revisions"}],"predecessor-version":[{"id":51931,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51926\/revisions\/51931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/51927"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}