{"id":51360,"date":"2020-11-26T19:48:15","date_gmt":"2020-11-26T22:48:15","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51360"},"modified":"2020-11-26T19:48:21","modified_gmt":"2020-11-26T22:48:21","slug":"a-escolha-e-sua","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/a-escolha-e-sua\/","title":{"rendered":"A escolha \u00e9 sua!"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/06\/Reflex%C3%A3o-2.jpg?resize=570%2C408\" alt=\"\" class=\"wp-image-35191\" width=\"570\" height=\"408\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/06\/Reflex%C3%A3o-2.jpg?w=350&amp;ssl=1 350w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/06\/Reflex%C3%A3o-2.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/06\/Reflex%C3%A3o-2.jpg?resize=250%2C179&amp;ssl=1 250w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 ouviu alguma vez falar de livre-arb\u00edtrio? Livre-arb\u00edtrio quer dizer livre escolha, livre op\u00e7\u00e3o. Em todas as situa\u00e7\u00f5es da vida, sempre temos duas ou mais possibilidades para escolher. E a cada momento a vida nos exige decis\u00e3o. Sempre temos que optar entre uma ou outra atitude.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que abrimos os olhos pela manh\u00e3, estamos optando entre uma atitude ou outra. Ao ouvir o despertador, podemos escolher entre abrir a boca para lamentar por n\u00e3o ser nosso dia de folga ou para agradecer a Deus por mais um dia de oportunidades, no corpo f\u00edsico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao encontrarmos o nosso familiar que acaba de se levantar, podemos resmungar qualquer coisa, ficar calado, ou desejar, do fundo da alma, um bom dia. Quando chegamos ao local de trabalho, podemos optar entre ficar de bem com todos ou buscar o isolamento, ou ainda, contaminar o ambiente com mau humor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conta um m\u00e9dico, que trata de pacientes com c\u00e2ncer, que as atitudes das pessoas variam muito, mesmo em situa\u00e7\u00f5es parecidas. Diz ele que duas de suas pacientes, quase da mesma idade, tiveram que extirpar um seio por causa da doen\u00e7a. Uma delas ficou feliz por continuar viva e poder brincar com os netos, a outra optou por lamentar pelo seio que havia perdido, embora tamb\u00e9m tivesse os netos para se distrair.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando algu\u00e9m o ofende, voc\u00ea pode escolher por revidar, calar-se ou oferecer o tratamento oposto. A decis\u00e3o sempre \u00e9 sua. O que vale ressaltar \u00e9 que todas as a\u00e7\u00f5es ter\u00e3o uma rea\u00e7\u00e3o correspondente, como consequ\u00eancia. E essa a\u00e7\u00e3o \u00e9 de nossa total responsabilidade. E isso deve ser ensinado aos filhos desde cedo. Caso a crian\u00e7a escolha agredir seu colega e leve alguns arranh\u00f5es, dever\u00e1 saber que isso \u00e9 resultado da sua a\u00e7\u00e3o e, portanto, de sua inteira responsabilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tudo na vida est\u00e1 sujeito \u00e0 lei de causa e efeito: para uma a\u00e7\u00e3o positiva, um efeito positivo. Para uma a\u00e7\u00e3o infeliz, o resultado correspondente. Se voc\u00ea chega ao trabalho bem humorado, alegre, radiante, e encontra seu colega de mau humor, voc\u00ea pode decidir entre sintonizar na faixa dele ou fazer com que ele sintonize na sua. Voc\u00ea tem ainda outra possibilidade de escolha: ficar na sua. Todavia, da sua escolha depender\u00e1 o resto do dia. E os resultados lhe pertencem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jesus ensinou que a semeadura \u00e9 livre, mas a colheita \u00e9 obrigat\u00f3ria. Pois bem, n\u00f3s estamos semeando e colhendo o tempo todo. Se semeamos sementes de flores, colhemos flores. Se plantamos espinheiros, colheremos espinhos. N\u00e3o h\u00e1 outra sa\u00edda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas o que importa mesmo \u00e9 saber que a op\u00e7\u00e3o \u00e9 nossa. Somos livres para escolher, antes de semear. A\u00ed \u00e9 que est\u00e1 a justi\u00e7a divina. Mesmo as semeaduras que demoram bastante tempo para germinar, um dia ter\u00e3o seus frutos. S\u00e3o aqueles atos praticados no anonimato, na surdina, que aparentemente ficam impunes. Um dia eles aparecer\u00e3o e reclamar\u00e3o colheita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente, os atos de ren\u00fancia, de toler\u00e2ncia, de benevol\u00eancia, que tantas vezes parecem n\u00e3o dar resultados, um dia florescer\u00e3o e dar\u00e3o bons frutos e perfume agrad\u00e1vel. \u00c9 s\u00f3 deixar nas m\u00e3os do jardineiro divino, a quem chamamos de Criador.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>Pense nisso!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A hora seguinte ser\u00e1 o reflexo da hora atual. O dia de amanh\u00e3 trar\u00e1 os resultados do dia de hoje. \u00c9 assim que vamos construindo a nossa felicidade ou nosso infort\u00fanio, de acordo com a nossa livre escolha, com nosso livre-arb\u00edtrio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea j\u00e1 ouviu alguma vez falar de livre-arb\u00edtrio? Livre-arb\u00edtrio quer dizer livre escolha, livre op\u00e7\u00e3o. Em todas as situa\u00e7\u00f5es da vida, sempre temos duas ou mais possibilidades para escolher. E a cada momento a vida nos exige decis\u00e3o. Sempre temos que optar entre uma ou outra atitude. Desde que abrimos os olhos pela manh\u00e3, estamos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-51360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/pexels-photo-210205.jpeg?fit=1880%2C1251&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51360"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51360\/revisions"}],"predecessor-version":[{"id":51362,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51360\/revisions\/51362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/49849"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}