{"id":51313,"date":"2020-11-25T21:26:59","date_gmt":"2020-11-26T00:26:59","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51313"},"modified":"2020-11-25T21:27:03","modified_gmt":"2020-11-26T00:27:03","slug":"andorinha-registra-duas-mortes-por-coronavirus-nesta-quarta-feira-25","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/andorinha-registra-duas-mortes-por-coronavirus-nesta-quarta-feira-25\/","title":{"rendered":"Andorinha registra duas mortes por coronav\u00edrus nesta quarta-feira (25)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Prefeitura de Andorinha, por meio da Secretaria de Sa\u00fade, divulga nota informativa para confirmar mais duas mortes ocorridas no munic\u00edpio causadas pela Covid-19. Agora, s\u00e3o cinco \u00f3bitos por coronav\u00edrus, no total.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Confira os detalhes:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19-CincoObitos.jpg?resize=800%2C960\" alt=\"\" class=\"wp-image-51314\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19-CincoObitos.jpg?resize=853%2C1024&amp;ssl=1 853w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19-CincoObitos.jpg?resize=250%2C300&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19-CincoObitos.jpg?resize=768%2C922&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19-CincoObitos.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria Municipal de Sa\u00fade, que tem trabalhado efetivamente no combate ao coronav\u00edrus, alerta a popula\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Evite sair de casa;<\/li><li>Se necess\u00e1rio sair, use sempre a m\u00e1scara e evite levar a m\u00e3o ao rosto;<\/li><li>Higienize suas m\u00e3os ao entrar e sair de estabelecimentos comerciais;<\/li><li>Comerciantes devem redobrar a aten\u00e7\u00e3o com funcion\u00e1rios;<\/li><li>Caso algu\u00e9m apresente sintomas suspeitos do coronav\u00edrus, procure um posto de sa\u00fade mais pr\u00f3ximo de sua resid\u00eancia para uma avalia\u00e7\u00e3o m\u00e9dica.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Legenda:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Aguardando resultado<\/strong>&nbsp;\u2013 Pacientes sintom\u00e1ticos e contatos de casos positivos sintom\u00e1ticos, que se encaixam nos crit\u00e9rios de coleta do LACEN, para realiza\u00e7\u00e3o de exame RT-PCR.<\/li><li><strong>Confirmado<\/strong>&nbsp;\u2013 Pacientes que testaram positivo para Covid-19, seja por exame LACEN (RT-PCR) ou por Teste R\u00e1pido (Quantitativo de anticorpos produzidos contra o v\u00edrus \u2013 IgM e IgG);<\/li><li><strong>LPI<\/strong>&nbsp;\u2013 Local Prov\u00e1vel de Infec\u00e7\u00e3o Fora do Munic\u00edpio;<\/li><li><strong>Casos ativos<\/strong>&nbsp;\u2013 Pacientes confirmados com Covid-19, em isolamento domiciliar e monitorados pela Vigil\u00e2ncia Epidemiol\u00f3gica, em processo de cura;<\/li><li><strong>Monitoramento domiciliar<\/strong>&nbsp;\u2013 Pessoas que necessitam cumprir 14 dias de isolamento domiciliar e social, por retornarem de viagem de local que apresentam casos confirmados de Covid-19;]<\/li><li><strong>\u00d3bito:<\/strong>&nbsp;\u2013 Pacientes que evolu\u00edram para morte por complica\u00e7\u00f5es da Covid 19;<\/li><li><strong>Recuperados<\/strong>&nbsp;\u2013 Pacientes confirmados para COVID-19 que cumpriram o isolamento de 10 dias e n\u00e3o apresentam mais sintomas.<\/li><\/ul>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Veja o boletim epidemiol\u00f3gico atualizado:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"540\" height=\"642\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19_Boletim_25.11.2020.jpeg?resize=540%2C642\" alt=\"\" class=\"wp-image-51315\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19_Boletim_25.11.2020.jpeg?w=540&amp;ssl=1 540w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19_Boletim_25.11.2020.jpeg?resize=252%2C300&amp;ssl=1 252w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Andorinha, por meio da Secretaria de Sa\u00fade, divulga nota informativa para confirmar mais duas mortes ocorridas no munic\u00edpio causadas pela Covid-19. Agora, s\u00e3o cinco \u00f3bitos por coronav\u00edrus, no total. Confira os detalhes: A Secretaria Municipal de Sa\u00fade, que tem trabalhado efetivamente no combate ao coronav\u00edrus, alerta a popula\u00e7\u00e3o: Evite sair de casa; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":["post-51313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/PMA_Covid-19_Boletim_25.11.2020.jpeg?fit=540%2C642&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51313"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51313\/revisions"}],"predecessor-version":[{"id":51317,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51313\/revisions\/51317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/51315"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}