{"id":51230,"date":"2020-11-24T07:04:41","date_gmt":"2020-11-24T10:04:41","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51230"},"modified":"2020-11-24T07:04:45","modified_gmt":"2020-11-24T10:04:45","slug":"trabalhadores-com-reducao-de-jornada-terao-direito-a-13o-e-ferias-define-ministerio-da-economia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/trabalhadores-com-reducao-de-jornada-terao-direito-a-13o-e-ferias-define-ministerio-da-economia\/","title":{"rendered":"Trabalhadores com redu\u00e7\u00e3o de jornada ter\u00e3o direito a 13\u00ba e f\u00e9rias, define Minist\u00e9rio da Economia"},"content":{"rendered":"\n<h5 class=\"has-text-align-center wp-block-heading\"><em>Documento contempla trabalhadores de empresas que participam do Programa Emergencial de Manuten\u00e7\u00e3o do Emprego e da Renda (Bem)<\/em><\/h5>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/02\/carteiras-de-trababalho.jpg?resize=600%2C450\" alt=\"\" class=\"wp-image-7403\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/02\/carteiras-de-trababalho.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/02\/carteiras-de-trababalho.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/02\/carteiras-de-trababalho.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nota t\u00e9cnica da Secretaria Especial de Previd\u00eancia e Trabalho, \u00f3rg\u00e3o vinculado ao Minist\u00e9rio da Economia, estabelece que trabalhadores que tiveram corte em seus sal\u00e1rios ou na jornada de trabalho ter\u00e3o direito a 13\u00ba sal\u00e1rio e f\u00e9rias integrais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O documento contempla empregados de empresas que aderiram ao Programa Emergencial de Manuten\u00e7\u00e3o do Emprego e da Renda (Bem), iniciativa do Governo Federal que prev\u00ea a redu\u00e7\u00e3o da jornada de trabalho e a suspens\u00e3o de contratos por conta da pandemia do novo coronav\u00edrus.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a nota, o c\u00e1lculo do pagamento do 13\u00ba ser\u00e1 feito proporcionalmente de acordo com os meses trabalhados, desde que tenha havido ao menos 15 dias de trabalho. O valor integral do benef\u00edcio ter\u00e1 o mesmo valor do sal\u00e1rio do m\u00eas de dezembro. Se o trabalhador, por exemplo, ficou suspenso por um m\u00eas, ele receber\u00e1 11\/12 do total da folha de pagamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Ferreira, gestora administrativa de uma empresa que fornece produtos auditivos em Bras\u00edlia, explica que os efeitos econ\u00f4micos da pandemia fizeram com que a companhia reduzisse parte da carga hor\u00e1ria da equipe. Mesmo assim, o 13\u00ba da equipe est\u00e1 garantido. <em>\u201cApesar da diminui\u00e7\u00e3o na jornada de trabalho, o 13\u00ba ser\u00e1 pago de forma integral e isso ser\u00e1 de grande valia por conta da recess\u00e3o que estamos passando\u201d<\/em>, diz.\u00a0<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>F\u00e9rias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a nota, tamb\u00e9m n\u00e3o ser\u00e1 considerado no c\u00e1lculo das f\u00e9rias o per\u00edodo em que o trabalhador teve o contrato suspenso. S\u00f3 ter\u00e1 direito a f\u00e9rias trabalhadores que completaram 12 meses de trabalho. Contudo, segundo a advogada trabalhista Amanda Caroline, o benef\u00edcio poder\u00e1 ser concedido aos trabalhadores que tiveram a carga hor\u00e1ria reduzida.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cMesmo com a jornada reduzida, o trabalhador ter\u00e1 direito ao 13\u00ba e f\u00e9rias. Mas, no caso de suspens\u00e3o de trabalho, como ele n\u00e3o est\u00e1 trabalhando n\u00e3o \u00e9 poss\u00edvel incluir os meses de suspens\u00e3o no pagamento dessas verbas\u201d<\/em>, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria Especial de Previd\u00eancia e Trabalho afirma que publicou a <em>\u201cnota considerando o volume de questionamentos di\u00e1rios direcionados\u201d<\/em> ao \u00f3rg\u00e3o <em>\u201csobre os efeitos dos acordos de suspens\u00e3o de contrato de trabalho e de redu\u00e7\u00e3o proporcional de jornada e sal\u00e1rio nos c\u00e1lculos de 13\u00ba e f\u00e9rias\u201d<\/em>.\u00a0<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>13\u00ba sal\u00e1rio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m conhecido como gratifica\u00e7\u00e3o natalina, o 13\u00ba sal\u00e1rio \u00e9 pago a trabalhadores com carteira assinada, aposentados, pensionistas e servidores. O benef\u00edcio deve ser pago em duas parcelas: a primeira entre 1\u00ba de fevereiro e 30 de novembro; e a segunda at\u00e9 20 de dezembro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Documento contempla trabalhadores de empresas que participam do Programa Emergencial de Manuten\u00e7\u00e3o do Emprego e da Renda (Bem) Nota t\u00e9cnica da Secretaria Especial de Previd\u00eancia e Trabalho, \u00f3rg\u00e3o vinculado ao Minist\u00e9rio da Economia, estabelece que trabalhadores que tiveram corte em seus sal\u00e1rios ou na jornada de trabalho ter\u00e3o direito a 13\u00ba sal\u00e1rio e f\u00e9rias integrais. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-51230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2018\/02\/carteira_de_trabalho.jpg?fit=500%2C334&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51230"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51230\/revisions"}],"predecessor-version":[{"id":51232,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51230\/revisions\/51232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/22954"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}