{"id":5119,"date":"2015-10-24T12:46:23","date_gmt":"2015-10-24T14:46:23","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=5119"},"modified":"2015-10-24T12:46:23","modified_gmt":"2015-10-24T14:46:23","slug":"agentes-realizam-mutirao-de-limpeza-em-igara","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/agentes-realizam-mutirao-de-limpeza-em-igara\/","title":{"rendered":"Agentes realizam mutir\u00e3o de limpeza em Igara"},"content":{"rendered":"<p>Em fun\u00e7\u00e3o dos casos registrados de dengue, zika e chikungunya, os Agentes de Combate \u00e0s Endemias do munic\u00edpio de Senhor do Bonfim, v\u00eam intensificando as a\u00e7\u00f5es de combate ao mosquito Aedes aegypti.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5120\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?resize=800%2C600\" alt=\"mutir\u00e3o_igara1\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?w=1984&amp;ssl=1 1984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?resize=250%2C188&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara1.jpg?w=1600 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Dentro da campanha lan\u00e7ada desde ultimo dia 15 de outubro onde, o munic\u00edpio iniciou um mutir\u00e3o no Alto da Maravilha, informando que ser\u00e1 realizado em todas as regi\u00f5es da cidade onde o \u00edndice de infesta\u00e7\u00e3o registrou crescimento comparado ao ano anterior, um grande mutir\u00e3o envolvendo o trabalho da Vigil\u00e2ncia Epidemiol\u00f3gica, de 40 Agentes de Endemias, dois caminh\u00f5es, um trator p\u00e1 carregadeira e acompanhamento de parte da equipe de limpeza urbana do munic\u00edpio, foi realizado na \u00faltima\u00a0quinta-feira (22), no distrito de Igara, zona rural de Senhor do Bonfim.<\/p>\n<p>Uma imensa quantidade de lixo e poss\u00edveis criadouros do mosquito foram retirados das ruas do Bolo, Castro Alves, Mercado, Matadouro e Lagoa.<\/p>\n<p>A proposta desta mobiliza\u00e7\u00e3o \u00e9 retirar dos im\u00f3veis todo tipo de material que possa acumular \u00e1gua e se tornar um criadouro de larvas do Aedes aegypti, explica o Coordenador de Endemias, Jos\u00e9 Rodrigues. \u201cPor isso \u00e9 de suma import\u00e2ncia que toda a popula\u00e7\u00e3o assuma a responsabilidade de colocar para fora de suas moradias pneus velhos, garrafas e outros materiais inserv\u00edveis, no dia marcado pela equipe, para os pr\u00f3ximos mutir\u00f5es, conforme orienta\u00e7\u00e3o feita por meio dos panfletos distribu\u00eddos e do carro de som nos dias que antecedem as a\u00e7\u00f5es\u201d.<\/p>\n<p>Ao visitarem os terrenos baldios e quintais, os agentes de endemias realizam trabalho de inspe\u00e7\u00e3o em todo e qualquer material que possa acumular \u00e1gua. Ainda orientam os moradores sobre a\u00e7\u00f5es para evitar o foco do Aedes aegypti e sobre a import\u00e2ncia da limpeza domiciliar, principal atitude para evitar criadouros do mosquito.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-full wp-image-5121\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?resize=800%2C600\" alt=\"mutir\u00e3o_igara2\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?w=1984&amp;ssl=1 1984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?resize=250%2C188&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?w=1600 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>A Secretaria de Sa\u00fade, por meio do setor de Endemias mant\u00e9m servi\u00e7o permanente para esclarecer a popula\u00e7\u00e3o sobre as formas de preven\u00e7\u00e3o \u00e0 dengue no telefone 3541-8370.\u00a0Na pr\u00f3xima semana a Coordena\u00e7\u00e3o de vigil\u00e2ncia epidemiol\u00f3gica estar\u00e1 divulgando um novo cronograma contendo as datas e localidades onde ser\u00e3o realizados os pr\u00f3ximos mutir\u00f5es para que a popula\u00e7\u00e3o possa colaborar na luta contra o mosquito.<\/p>\n<p><em>*Fonte: Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em fun\u00e7\u00e3o dos casos registrados de dengue, zika e chikungunya, os Agentes de Combate \u00e0s Endemias do munic\u00edpio de Senhor do Bonfim, v\u00eam intensificando as a\u00e7\u00f5es de combate ao mosquito Aedes aegypti. Dentro da campanha lan\u00e7ada desde ultimo dia 15 de outubro onde, o munic\u00edpio iniciou um mutir\u00e3o no Alto da Maravilha, informando que ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,7,4],"tags":[],"class_list":["post-5119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-saude","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/mutir%C3%A3o_igara2.jpg?fit=1984%2C1488&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=5119"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5119\/revisions"}],"predecessor-version":[{"id":5122,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5119\/revisions\/5122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/5121"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=5119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=5119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=5119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}