{"id":51182,"date":"2020-11-22T11:00:39","date_gmt":"2020-11-22T14:00:39","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51182"},"modified":"2020-11-22T11:00:45","modified_gmt":"2020-11-22T14:00:45","slug":"tres-cidades-baianas-terao-mais-mulheres-que-homens-na-camara-de-vereadores","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/tres-cidades-baianas-terao-mais-mulheres-que-homens-na-camara-de-vereadores\/","title":{"rendered":"Tr\u00eas cidades baianas ter\u00e3o mais mulheres que homens na C\u00e2mara de Vereadores"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Mulheres-na-camara.jpg?resize=566%2C417\" alt=\"\" class=\"wp-image-51183\" width=\"566\" height=\"417\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Mulheres-na-camara.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Mulheres-na-camara.jpg?resize=300%2C221&amp;ssl=1 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se em 90 munic\u00edpios do estado n\u00e3o haver\u00e1 vereadoras a partir de 2021, tr\u00eas cidades tiveram um feito raro. Elas elegeram mais mulheres que homens para as C\u00e2maras de Vereadores. Segundo o Correio, todas as tr\u00eas t\u00eam menos de 30 mil habitantes. S\u00e3o os casos de Rodelas, na divisa com Pernambuco; Jo\u00e3o Dourado, no Centro-Norte; e Palmas de Monte Alto, no Sert\u00e3o Produtivo, Sudoeste baiano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das nove vagas para a C\u00e2mara Municipal de Rodelas, cinco ser\u00e3o de mulheres. Em Jo\u00e3o Dourado, seis das 11 vagas v\u00e3o ser ocupadas por mulheres. No munic\u00edpio, a maior vota\u00e7\u00e3o para a C\u00e2mara foi obtida por uma mulher, Kel do Riacho, que teve 1.135 votos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso de Palmas de Monte Alto ainda foi mais relevante. Com maioria de homens na popula\u00e7\u00e3o, tr\u00eas mulheres foram as mais votadas entre todos os candidatos ao Legislativo local. Patr\u00edcia do Rancho, Selma de Leot\u00e9rio e Rose da Barriguda somaram 2.140 em votos e ocuparam tr\u00eas das seis vagas conseguidas pelas mulheres em um total de 11 cadeiras da C\u00e2mara local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se em 90 munic\u00edpios do estado n\u00e3o haver\u00e1 vereadoras a partir de 2021, tr\u00eas cidades tiveram um feito raro. Elas elegeram mais mulheres que homens para as C\u00e2maras de Vereadores. Segundo o Correio, todas as tr\u00eas t\u00eam menos de 30 mil habitantes. S\u00e3o os casos de Rodelas, na divisa com Pernambuco; Jo\u00e3o Dourado, no Centro-Norte; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-51182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/09\/Politica.jpg?fit=1170%2C700&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51182"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51182\/revisions"}],"predecessor-version":[{"id":51185,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51182\/revisions\/51185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/49102"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}