{"id":51041,"date":"2020-11-17T11:55:17","date_gmt":"2020-11-17T14:55:17","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=51041"},"modified":"2020-11-17T11:55:23","modified_gmt":"2020-11-17T14:55:23","slug":"sucesso-nos-anos-80-markinhos-moura-fala-sobre-sexualidade-nunca-estive-no-armario","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/sucesso-nos-anos-80-markinhos-moura-fala-sobre-sexualidade-nunca-estive-no-armario\/","title":{"rendered":"Sucesso nos anos 80, Markinhos Moura fala sobre sexualidade: &#8216;Nunca estive no arm\u00e1rio&#8217;"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-01.jpg?resize=640%2C360\" alt=\"\" class=\"wp-image-51042\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-01.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-01.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption><em>Markinhos Moura tem hoje 53 anos &#8211; Foto: Reprodu\u00e7\u00e3o\/ Instagram<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Meu mel n\u00e3o diga adeus, eu tenho tanto medo, de ficar sem o seu amor, e pra sempre ser um ser s\u00f3\u2026&#8221;<\/em>. Quem viveu os anos 80 conhece bem os versos da m\u00fasica <strong>&#8220;Meu mel&#8221;<\/strong>, que fez seu int\u00e9rprete vender mais de 100 mil c\u00f3pias e peregrinar nos programas de TV da \u00e9poca, do &#8220;Cassino do Chacrinha&#8221; ao &#8220;Xou da Xuxa&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cantor por tr\u00e1s de um dos grandes hits da d\u00e9cada \u00e9 Markinhos Moura, hoje com 53 anos. Sempre se apresentando com um visual ousado, com brincos, roupas extravagantes, pulseiras, e uma voz andr\u00f3gina, o cantor se considera um pioneiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Eu usava camisetas decotadas para \u00e9poca. Eu era loiro, eu descoloria o cabelo, e fui um dos primeiros artistas depois do J\u00f4 Soares e do Benito di Paula, a usar brinco. Voc\u00ea imagina o quanto isso custou na \u00e9poca\u2026 Nunca tive a necessidade de falar disso. Era uma \u00e9poca que voc\u00ea n\u00e3o podia falar isso e eu vivia com um s\u00e9quito atr\u00e1s de mim, me policiando. Tinha muita gente que como eu, n\u00e3o podia se mostrar, como hoje, como depois poderia se mostrar. Eu nunca estive no arm\u00e1rio, eu sempre estive na frente do arm\u00e1rio, abrindo a porta pra quem quisesse entrar ou sair&#8221;<\/em>, diz Markinhos ao site <em>&#8220;Gay.blog.br&#8221;<\/em>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"448\" height=\"700\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-02.jpg?resize=448%2C700\" alt=\"\" class=\"wp-image-51043\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-02.jpg?w=448&amp;ssl=1 448w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-02.jpg?resize=192%2C300&amp;ssl=1 192w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/><figcaption><em>Markinhos Moura: sucesso nos anos 80 &#8211; Foto: Reprodu\u00e7\u00e3o<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Sem aposentadoria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Do estouro nacional para c\u00e1, ele ainda enfrentou uma s\u00edndrome do p\u00e2nico e diz que n\u00e3o conseguiu fazer um p\u00e9 de meia:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Ao contr\u00e1rio do que todo mundo acha, n\u00e3o ganhei muito dinheiro. Ganhei na \u00e9poca o que dava para me sustentar e ajudar a minha m\u00e3e, mas n\u00e3o deu tempo de eu comprar im\u00f3vel. E outra coisa, n\u00e3o se ganhava muito naquela \u00e9poca. Eu podia ter uma aposentadoria se as pessoas que tivessem comigo, tivesse me orientado desde aquela \u00e9poca a come\u00e7ar a pagar. Eu n\u00e3o tenho aposentadoria. Isso foi um erro muito grande, ent\u00e3o eu n\u00e3o ganhei dinheiro que desse pra eu juntar, pra eu ter avi\u00e3o, que as pessoas com um ano de carreira j\u00e1 tem um, n\u00e3o sei quantas casas, vai de f\u00e9rias para Londres, Paris etc. N\u00f3s n\u00e3o t\u00ednhamos isso, com raras exce\u00e7\u00f5es, a maioria n\u00e3o ganhava isso&#8221;<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prestes a voltar aos palcos com a pe\u00e7a <strong>&#8220;Angel&#8221;<\/strong>, que reestreia no pr\u00f3ximo dia 26 em S\u00e3o Paulo, ap\u00f3s a temporada ter sido interrompida pela pandemia, Markinhos Moura esteve nos \u00faltimos anos distante da m\u00eddia, mas nunca parou de cantar. Em breve, ele lan\u00e7a um novo \u00e1lbum, que estar\u00e1 dispon\u00edvel nas plataformas digitais: <em>&#8220;Rezo muito para Deus abrir novos caminhos, novas formas de express\u00e3o pra mim. Quero continuar cantando, mas cada vez mais, quero o ator mais em cena, mais presente&#8221;<\/em>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"448\" height=\"450\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-03.jpg?resize=448%2C450\" alt=\"\" class=\"wp-image-51044\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-03.jpg?w=448&amp;ssl=1 448w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-03.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-03.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/><figcaption><em>Markinhos Moura: sucesso nos anos 80 &#8211; Foto: Reprodu\u00e7\u00e3o<\/em><\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Meu mel n\u00e3o diga adeus, eu tenho tanto medo, de ficar sem o seu amor, e pra sempre ser um ser s\u00f3\u2026&#8221;. Quem viveu os anos 80 conhece bem os versos da m\u00fasica &#8220;Meu mel&#8221;, que fez seu int\u00e9rprete vender mais de 100 mil c\u00f3pias e peregrinar nos programas de TV da \u00e9poca, do &#8220;Cassino [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-51041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/MarkinhosMoura-02.jpg?fit=448%2C700&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=51041"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51041\/revisions"}],"predecessor-version":[{"id":51046,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/51041\/revisions\/51046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/51043"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=51041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=51041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=51041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}