{"id":50916,"date":"2020-11-12T08:55:08","date_gmt":"2020-11-12T11:55:08","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50916"},"modified":"2020-11-12T08:55:12","modified_gmt":"2020-11-12T11:55:12","slug":"propostas-buscam-regulamentar-candidaturas-e-mandatos-coletivos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/propostas-buscam-regulamentar-candidaturas-e-mandatos-coletivos\/","title":{"rendered":"Propostas buscam regulamentar candidaturas e mandatos coletivos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Urna-MandatoColetivo.jpg?resize=768%2C511\" alt=\"\" class=\"wp-image-50917\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Urna-MandatoColetivo.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Urna-MandatoColetivo.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Fen\u00f4meno na elei\u00e7\u00e3o passada, com alguns casos vencedores, as candidaturas coletivas &#8211; quando um grupo de pessoas concorre a uma vaga no Legislativo &#8211; voltaram a ocorrer este ano, mas ainda sem suporte legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo estudo da Rede de A\u00e7\u00e3o Pol\u00edtica pela Sustentabilidade, as duas primeiras candidaturas coletivas ocorreram em 1994, mas um aumento expressivo s\u00f3 foi acontecer nas elei\u00e7\u00f5es municipais de 2016, com 98 candidaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste ano, um levantamento do Portal Uol informa que s\u00f3 em S\u00e3o Paulo h\u00e1 pelo menos 34 candidaturas coletivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas, como explica o advogado Pablo Bismarck, integrante da Academia Brasileira de Direito Eleitoral e Pol\u00edtico, na hora de formalizar, a lei s\u00f3 permite que um dos integrantes da candidatura coletiva seja registrado e, caso eleito, tenha direito \u00e0 vaga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cA formaliza\u00e7\u00e3o \u00e9 igual a uma candidatura dita normal. O registro de candidatura \u00e9 feito no nome de uma pessoa, o candidato \u00e9 uma pessoa. Caso esse candidato seja eleito, somente ele ter\u00e1 direito a voto, direito a assento na casa legislativa, direito \u00e0 voz e direito \u00e0 vez\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e3o em an\u00e1lise na C\u00e2mara algumas propostas que t\u00eam o objetivo de regulamentar as candidaturas e os mandatos coletivos. Por exemplo, uma proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC 379\/17) da deputada licenciada Renata Abreu (Pode-SP), permite a exist\u00eancia de mandato coletivo para vereador, deputados estadual, distrital e federal e senador. A regulamenta\u00e7\u00e3o dever\u00e1 ser feita por lei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um projeto de lei (PL 4475\/20) estabelece regras para o registro de candidaturas coletivas ao Poder Legislativo e para a propaganda eleitoral delas. Segundo a proposta, no pedido de registro da candidatura, o candidato poder\u00e1 indicar o nome do grupo ou coletivo social que o apoia, que ser\u00e1 acrescido ao nome registrado por ele. Mas n\u00e3o pode ser registrado apenas o nome do coletivo, e n\u00e3o poder\u00e1 haver d\u00favida quanto \u00e0 identidade do candidato registrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o autor do projeto, deputado Jo\u00e3o Daniel (PT-SE), os mandatos coletivos fortalecem a ideia de uma democracia mais participativa e da pol\u00edtica como um projeto coletivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cN\u00f3s precisamos construir uma pol\u00edtica exatamente diferente do modelo tradicional. \u00c9 fundamental que cres\u00e7a e fortale\u00e7a a ideia e a import\u00e2ncia da pol\u00edtica como projeto coletivo, como projeto social, e n\u00e3o como projeto individual\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra proposta sobre o tema em an\u00e1lise na C\u00e2mara, de autoria do deputado Andr\u00e9 Figueiredo (PDT-CE), cria a figura dos coparlamentares, que compartilham, com o parlamentar, o poder decis\u00f3rio, dentro de um mandato coletivo. Entre outros pontos, a proposta estabelece que o pedido de registro de chapa de mandato coletivo dever\u00e1 ser composto da documenta\u00e7\u00e3o do candidato a parlamentar e dos candidatos a coparlamentar integrantes da respectiva chapa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fen\u00f4meno na elei\u00e7\u00e3o passada, com alguns casos vencedores, as candidaturas coletivas &#8211; quando um grupo de pessoas concorre a uma vaga no Legislativo &#8211; voltaram a ocorrer este ano, mas ainda sem suporte legal. Segundo estudo da Rede de A\u00e7\u00e3o Pol\u00edtica pela Sustentabilidade, as duas primeiras candidaturas coletivas ocorreram em 1994, mas um aumento expressivo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-50916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Urna-MandatoColetivo.jpg?fit=768%2C511&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50916"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50916\/revisions"}],"predecessor-version":[{"id":50919,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50916\/revisions\/50919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/50917"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}