{"id":50883,"date":"2020-11-11T08:28:59","date_gmt":"2020-11-11T11:28:59","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50883"},"modified":"2020-11-11T08:29:01","modified_gmt":"2020-11-11T11:29:01","slug":"sesi-bahia-abre-inscricoes-para-bolsas-de-estudos-de-ensino-medio-no-ano-letivo-de-2021","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/sesi-bahia-abre-inscricoes-para-bolsas-de-estudos-de-ensino-medio-no-ano-letivo-de-2021\/","title":{"rendered":"Sesi Bahia abre inscri\u00e7\u00f5es para bolsas de estudos de ensino m\u00e9dio no ano letivo de 2021"},"content":{"rendered":"\n<h5 class=\"has-text-align-center wp-block-heading\"><em>Para concorrer, estudante deve ter renda familiar de at\u00e9 dois sal\u00e1rios m\u00ednimos; inscri\u00e7\u00f5es s\u00e3o gratuitas<\/em><\/h5>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"570\" height=\"334\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/04\/SESI_Aluno.jpg?resize=570%2C334\" alt=\"\" class=\"wp-image-43388\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/04\/SESI_Aluno.jpg?w=570&amp;ssl=1 570w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/04\/SESI_Aluno.jpg?resize=300%2C176&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/04\/SESI_Aluno.jpg?resize=250%2C146&amp;ssl=1 250w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o Social da Ind\u00fastria (SESI Bahia) abriu inscri\u00e7\u00f5es para bolsas de estudo destinadas a estudantes do 1\u00ba ano do ensino m\u00e9dio para o ano letivo de 2021. Para concorrer, a renda familiar deve ser de at\u00e9 dois sal\u00e1rios m\u00ednimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es para o processo seletivo s\u00e3o gratuitas e devem ser realizadas, no <strong><em><a href=\"https:\/\/www.iuds.org.br\/informacoes\/2354\/\" target=\"_blank\" rel=\"noreferrer noopener\">site da institui\u00e7\u00e3o<\/a><\/em><\/strong>, at\u00e9 o dia 15 de novembro, ou at\u00e9 que o total de vagas seja atingido. S\u00e3o oferecidas 2.700 vagas para Salvador e um total de 2.300 inscri\u00e7\u00f5es para as unidades no interior do estado. No total, s\u00e3o oferecidas 475 bolsas nas escolas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As escolas de ensino m\u00e9dio da Rede SESI de educa\u00e7\u00e3o est\u00e3o na capital e nas cidades de Feira de Santana, Barreiras, Lu\u00eds Eduardo Magalh\u00e3es, Ilh\u00e9us\/Itabuna, Vit\u00f3ria da Conquista e Juazeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os candidatos dever\u00e3o fazer a uma prova online, que ser\u00e1 realizada no dia 6 de dezembro. O edital com todas as informa\u00e7\u00f5es est\u00e1 dispon\u00edvel nos sites da Escola SESI e do Instituto Universal de Desenvolvimento Social, empresa contratada para realizar a sele\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para concorrer, estudante deve ter renda familiar de at\u00e9 dois sal\u00e1rios m\u00ednimos; inscri\u00e7\u00f5es s\u00e3o gratuitas O Servi\u00e7o Social da Ind\u00fastria (SESI Bahia) abriu inscri\u00e7\u00f5es para bolsas de estudo destinadas a estudantes do 1\u00ba ano do ensino m\u00e9dio para o ano letivo de 2021. Para concorrer, a renda familiar deve ser de at\u00e9 dois sal\u00e1rios m\u00ednimos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-50883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/Sesi-Parceria.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50883"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50883\/revisions"}],"predecessor-version":[{"id":50885,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50883\/revisions\/50885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/36055"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}