{"id":50765,"date":"2020-11-06T07:36:08","date_gmt":"2020-11-06T10:36:08","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50765"},"modified":"2020-11-06T09:25:19","modified_gmt":"2020-11-06T12:25:19","slug":"jesus-nao-te-condena","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/jesus-nao-te-condena\/","title":{"rendered":"Jesus n\u00e3o te condena"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?resize=800%2C533\" alt=\"brown leafed tree selective focus photography\" class=\"wp-image-50766\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?w=1880&amp;ssl=1 1880w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/pexels-photo-1585892.jpeg?w=1600 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><em>Photo by Lina Kivaka on <a rel=\"nofollow\" href=\"https:\/\/www.pexels.com\/photo\/brown-leafed-tree-selective-focus-photography-1585892\/\">Pexels.com<\/a><\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Uma mulher que estava em adult\u00e9rio foi pega em flagrante &#8211; um s\u00e9rio erro para os padr\u00f5es da sociedade da \u00e9poca! Pela lei de Mois\u00e9s, ela deveria ser apedrejada. Mas qual foi a rea\u00e7\u00e3o de Jesus sobre o ato dela? Ele a condenou diante das outras pessoas? Sua resposta foi: <em>\u201cAquele que dentre v\u00f3s estiver sem pecado seja o primeiro que lhe atire pedra\u201d<\/em> (Jo\u00e3o 8:7).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que posicionamento surpreendente de Jesus! Esta foi uma grande demonstra\u00e7\u00e3o da Sua gra\u00e7a e do Seu amor!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jesus n\u00e3o veio para condenar o mundo, mas sim para salv\u00e1-lo. Nesta passagem, em apenas um ato, Ele d\u00e1 um show de sabedoria, faz aqueles acusadores repensarem as suas pr\u00f3prias vidas, salva e liberta aquela mulher, e lhe diz o que fazer daquele momento em diante: <em>\u201cV\u00e1 e n\u00e3o peques mais\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando temos um encontro com Jesus, nunca mais somos os mesmos. Por isso, se o Rei dos reis n\u00e3o nos condena jamais, n\u00e3o deixe que outros fa\u00e7am isso com voc\u00ea, e nem voc\u00ea mesmo se trate desta forma!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quantos anos perdemos da nossa vida remoendo nossas falhas antigas e, com isso, sem perceber, abrimos m\u00e3o de viver bem o nosso presente e de ter esperan\u00e7a nos dias \u00e0 frente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o caia nesta armadilha! D\u00ea um basta a esta condena\u00e7\u00e3o! Decida, hoje, desfrutar da maravilhosa gra\u00e7a de Deus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 esta gra\u00e7a que te faz andar em liberdade, desligando voc\u00ea da tristeza e da culpa pelos erros passados. A gra\u00e7a te oferece uma nova vida, transformada de dentro para fora pelo amor do Pai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saiba que os olhos de Deus n\u00e3o est\u00e3o mais naquilo que passou, mas apenas no seu presente e futuro, ansiando realizar os planos incr\u00edveis que Ele tem para voc\u00ea!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher que estava em adult\u00e9rio foi pega em flagrante &#8211; um s\u00e9rio erro para os padr\u00f5es da sociedade da \u00e9poca! Pela lei de Mois\u00e9s, ela deveria ser apedrejada. Mas qual foi a rea\u00e7\u00e3o de Jesus sobre o ato dela? Ele a condenou diante das outras pessoas? Sua resposta foi: \u201cAquele que dentre v\u00f3s estiver [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-50765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/pexels-photo-210205.jpeg?fit=1880%2C1251&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50765"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50765\/revisions"}],"predecessor-version":[{"id":50778,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50765\/revisions\/50778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/49849"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}