{"id":50761,"date":"2020-11-05T21:54:44","date_gmt":"2020-11-06T00:54:44","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50761"},"modified":"2020-11-05T21:54:48","modified_gmt":"2020-11-06T00:54:48","slug":"humorista-jotinha-morre-apos-falencia-de-multiplos-orgaos-em-decorrencia-da-covid-19-diz-secretario-de-saude-da-ba","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/humorista-jotinha-morre-apos-falencia-de-multiplos-orgaos-em-decorrencia-da-covid-19-diz-secretario-de-saude-da-ba\/","title":{"rendered":"Humorista Jotinha morre ap\u00f3s fal\u00eancia de m\u00faltiplos \u00f3rg\u00e3os em decorr\u00eancia da Covid-19, diz secret\u00e1rio de Sa\u00fade da BA"},"content":{"rendered":"\n<h5 class=\"has-text-align-center wp-block-heading\"><em>Jotinha estava em coma, internado em uma unidade de sa\u00fade particular de Santo Ant\u00f4nio de Jesus. Na tarde desta quinta (5), o perfil oficial do humorista divulgou que ele estava com Covid<\/em><\/h5>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"776\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha.jpg?resize=800%2C776\" alt=\"\" class=\"wp-image-50762\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha.jpg?w=984&amp;ssl=1 984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha.jpg?resize=300%2C291&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha.jpg?resize=768%2C745&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><em>Humorista ficou conhecido nacionalmente por seus bord\u00f5es e \u00e1udios publicados nas redes sociais \u2014 Foto: Instagram | Reprodu\u00e7\u00e3o<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Morreu aos 52 anos, no come\u00e7o da noite desta quinta-feira (5), o humorista <strong>Jos\u00e9 Luiz Almeida da Silva<\/strong>, mais conhecido como <strong>Jotinha<\/strong>. Segundo uma publica\u00e7\u00e3o feita pelo secret\u00e1rio de Sa\u00fade da Bahia, F\u00e1bio Vilas-Boas, nas redes sociais, o motivo da morte foi fal\u00eancia m\u00faltipla de \u00f3rg\u00e3os em consequ\u00eancia da Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda na publica\u00e7\u00e3o, o secret\u00e1rio disse: <em>&#8220;Meus sentimentos \u00e0 fam\u00edlia enlutada e a todos que o admiravam&#8221;<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do an\u00fancio feito pelo secret\u00e1rio, um v\u00eddeo postado no Instagram do humorista divulgou a not\u00edcia aos seguidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEu venho contar uma not\u00edcia que nenhum de voc\u00eas queria ouvir. E eu tamb\u00e9m n\u00e3o queria dar para voc\u00eas. Mas ele faleceu gente. Acabei de saber&#8221;<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jotinha estava em coma, internado em uma unidade de sa\u00fade particular de Santo Ant\u00f4nio de Jesus, no rec\u00f4ncavo da Bahia, desde ter\u00e7a-feira (3), quando apresentou problemas respirat\u00f3rios. Na tarde desta quinta, o perfil oficial do humorista divulgou que ele estava com Covid-19.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"715\" height=\"1024\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha-1.jpg?resize=715%2C1024\" alt=\"\" class=\"wp-image-50763\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha-1.jpg?resize=715%2C1024&amp;ssl=1 715w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha-1.jpg?resize=209%2C300&amp;ssl=1 209w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha-1.jpg?resize=768%2C1100&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha-1.jpg?w=984&amp;ssl=1 984w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><figcaption><em>Humorista Jotinha morre ap\u00f3s fal\u00eancia de m\u00faltiplos \u00f3rg\u00e3os, diz Secret\u00e1rio de sa\u00fade da BA \u2014 Foto: Reprodu\u00e7\u00e3o \/ Redes Sociais<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A postagem, que mostra o resultado do exame positivo para o novo coronav\u00edrus, foi seguida da legenda: <em>&#8220;Acabamos de receber o resultado do exame. Infelizmente, deu positivo para a Covid-19&#8221;<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na tarde desta quinta, F\u00e1bio Vilas-Boas havia afirmado que n\u00e3o tinha como transferir Jotinha para um hospital na capital baiana. O coment\u00e1rio foi em resposta a Tirullipa, que fez um apelo nas redes sociais para que as autoridades fizessem a transfer\u00eancia do humorista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Infelizmente, Tirullipa, a situa\u00e7\u00e3o cl\u00ednica do nosso Jotinha \u00e9 muito grave e n\u00e3o h\u00e1 condi\u00e7\u00f5es de remo\u00e7\u00e3o por UTI a\u00e9rea para Salvador. Felizmente, o Hospital Incar, onde est\u00e1 internado em Santo Ant\u00f4nio de Jesus, possui todos os recursos&#8221;<\/em>, escreveu o secret\u00e1rio em uma rede social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em mar\u00e7o de 2019, Jotinha sofreu um infarto e ficou internado em um hospital de El\u00edsio Medrado. Na \u00e9poca, o pr\u00f3prio Jotinha enviou os cl\u00e1ssicos \u00e1udios em grupos de amigos, informando que realizou exames e tranquilizando os f\u00e3s sobre o estado de sa\u00fade dele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Luiz Almeida Silva era natural de El\u00edsio Medrado, pr\u00f3ximo a Amargosa, no Rec\u00f4ncavo Baiano. Ele tinha mais de 1 milh\u00e3o de seguidores somente no Instagram e ganhou proje\u00e7\u00e3o na internet por causa do tom de voz, o jeito debochado de comentar sobre futebol e a maneira bem humorada de &#8220;cornetar&#8221; os amigos nos grupos de WhatsApp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jotinha estava em coma, internado em uma unidade de sa\u00fade particular de Santo Ant\u00f4nio de Jesus. Na tarde desta quinta (5), o perfil oficial do humorista divulgou que ele estava com Covid Morreu aos 52 anos, no come\u00e7o da noite desta quinta-feira (5), o humorista Jos\u00e9 Luiz Almeida da Silva, mais conhecido como Jotinha. Segundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-50761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/jotinha.jpg?fit=984%2C954&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50761"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50761\/revisions"}],"predecessor-version":[{"id":50764,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50761\/revisions\/50764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/50762"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}