{"id":5073,"date":"2015-10-22T19:40:46","date_gmt":"2015-10-22T21:40:46","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=5073"},"modified":"2015-10-22T19:40:47","modified_gmt":"2015-10-22T21:40:47","slug":"descaso-e-abandono-gameleira-do-dida-em-campo-formoso-pede-socorro","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/descaso-e-abandono-gameleira-do-dida-em-campo-formoso-pede-socorro\/","title":{"rendered":"DESCASO E ABANDONO: Gameleira do Dida em Campo Formoso pede socorro"},"content":{"rendered":"<p><em><strong>Popula\u00e7\u00e3o vem sofrendo com a falta de \u00e1gua a muito tempo. At\u00e9 crian\u00e7as s\u00e3o obrigadas a ajudar na busca pelo l\u00edquido t\u00e3o precioso<\/strong><\/em><\/p>\n<figure id=\"attachment_5074\" aria-describedby=\"caption-attachment-5074\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira1.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-5074 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira1.jpg?resize=800%2C600\" alt=\"gameleira1\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira1.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira1.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-5074\" class=\"wp-caption-text\">Popula\u00e7\u00e3o de Gameleira do Dida implora por \u00e1gua (Foto do leitor)<\/figcaption><\/figure>\n<p>Estamos em 2015. Vivemos o s\u00e9culo XXI. Mas, para os moradores do Povoado de Gameleira do Dida, zona rural do vizinho munic\u00edpio de Campo Formoso, parece que a civiliza\u00e7\u00e3o ainda \u00e9 algo desconhecido. L\u00e1, um dos recursos mais necess\u00e1rios \u00e0 sobreviv\u00eancia humana, \u00e9 muito dif\u00edcil de encontrar com o m\u00ednimo de qualidade: a \u00e1gua.<\/p>\n<p>O abastecimento de \u00e1gua que j\u00e1 \u00e9 prec\u00e1rio, ultimamente ficou pior. Contando com apenas dois po\u00e7os artesianos para servir toda a popula\u00e7\u00e3o, uma bomba utilizada para capta\u00e7\u00e3o da \u00e1gua queimou. Agora, os moradores t\u00eam que recorrer a dois reservat\u00f3rios, mas a \u00e1gua \u00e9 impr\u00f3pria para consumo humano, fato comprovado atrav\u00e9s de an\u00e1lises que j\u00e1 foram feitas por engenheiros.<\/p>\n<figure id=\"attachment_5077\" aria-describedby=\"caption-attachment-5077\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-5077 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg?resize=800%2C600\" alt=\"gameleira4\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-5077\" class=\"wp-caption-text\">Crian\u00e7as s\u00e3o for\u00e7adas a ajudar a fam\u00edlia na busca pelo precioso l\u00edquido (Foto do leitor)<\/figcaption><\/figure>\n<p>Ent\u00e3o, o jeito \u00e9 comprar. No entanto, por se tratar de uma comunidade carente, nem todos t\u00eam condi\u00e7\u00f5es de adquirir\u00a0o l\u00edquido. M\u00e1rio Leal, morador antigo do povoado, est\u00e1 apelando para as autoridades, atrav\u00e9s da imprensa, para que uma solu\u00e7\u00e3o seja encontrada para minimizar o sofrimento da popula\u00e7\u00e3o de Gameleira do Dida.<\/p>\n<figure id=\"attachment_5076\" aria-describedby=\"caption-attachment-5076\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira3.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-5076 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira3.jpg?resize=800%2C600\" alt=\"gameleira3\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira3.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira3.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira3.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-5076\" class=\"wp-caption-text\">\u00c1gua encontrada \u00e9 impr\u00f3pria para o consumo humano (Foto do leitor)<\/figcaption><\/figure>\n<p><em>*Eloilton Cajuhy &#8211; DRT 3621<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Popula\u00e7\u00e3o vem sofrendo com a falta de \u00e1gua a muito tempo. At\u00e9 crian\u00e7as s\u00e3o obrigadas a ajudar na busca pelo l\u00edquido t\u00e3o precioso Estamos em 2015. Vivemos o s\u00e9culo XXI. Mas, para os moradores do Povoado de Gameleira do Dida, zona rural do vizinho munic\u00edpio de Campo Formoso, parece que a civiliza\u00e7\u00e3o ainda \u00e9 algo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,11],"tags":[],"class_list":["post-5073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/gameleira4.jpg?fit=960%2C720&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=5073"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5073\/revisions"}],"predecessor-version":[{"id":5078,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/5073\/revisions\/5078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/5077"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=5073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=5073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=5073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}