{"id":50714,"date":"2020-11-04T07:41:12","date_gmt":"2020-11-04T10:41:12","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50714"},"modified":"2020-11-04T07:41:16","modified_gmt":"2020-11-04T10:41:16","slug":"policia-militar-registra-18-acidentes-na-operacao-finados","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/policia-militar-registra-18-acidentes-na-operacao-finados\/","title":{"rendered":"Pol\u00edcia Militar registra 18 acidentes na Opera\u00e7\u00e3o Finados"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Policia-Rodoviaria-BPRv-2020.jpg?resize=768%2C512\" alt=\"\" class=\"wp-image-50715\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Policia-Rodoviaria-BPRv-2020.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Policia-Rodoviaria-BPRv-2020.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption><em>Foto: Camila Souza\/Arquivo GOVBA<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A Opera\u00e7\u00e3o Finados 2020, realizada pela Pol\u00edcia Militar da Bahia (PMBA), foi conclu\u00edda nesta ter\u00e7a-feira (3), com um aumento de 16,67% no n\u00famero de acidentes em rela\u00e7\u00e3o ao ano passado. Houve o registro de 18 acidentes, que provocaram ferimentos leves em quatro pessoas, ferimentos graves em quatro e cinco v\u00edtimas fatais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No per\u00edodo das 8h de sexta-feira (30) \u00e0s 8h desta ter\u00e7a-feira (3), a PM abordou 3.325 pessoas e 2.550 ve\u00edculos, dos quais 673 foram autuados, 34 removidos e 710 autos extra\u00eddos. Foram recolhidos sete Carteiras Nacionais de Habilita\u00e7\u00e3o (CNH) e cinco Certificados de Registro de Licenciamento de Ve\u00edculo (CRLV). Tamb\u00e9m ocorreram 127 abordagens com condutores submetidos ao exame de alcoolemia, resultando em duas autua\u00e7\u00f5es por dirigir sob efeito de bebida alco\u00f3lica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na opera\u00e7\u00e3o, a PM empregou 21 postos rodovi\u00e1rios, 130 viaturas e 294 policiais militares que se revezaram diariamente, intensificando o policiamento rodovi\u00e1rio motorizado, principalmente nas rodovias de maior fluxo de tr\u00e1fego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As equipes do Batalh\u00e3o de Policiamento Rodovi\u00e1rio (BPRv) realizaram todas as a\u00e7\u00f5es obedecendo \u00e0s recomenda\u00e7\u00f5es da Secretaria da Sa\u00fade do Estado (Sesab), com uso de m\u00e1scara, \u00e1lcool 70%, \u00e1lcool em gel e luvas descart\u00e1veis durante as abordagens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Opera\u00e7\u00e3o Finados 2020, realizada pela Pol\u00edcia Militar da Bahia (PMBA), foi conclu\u00edda nesta ter\u00e7a-feira (3), com um aumento de 16,67% no n\u00famero de acidentes em rela\u00e7\u00e3o ao ano passado. Houve o registro de 18 acidentes, que provocaram ferimentos leves em quatro pessoas, ferimentos graves em quatro e cinco v\u00edtimas fatais. No per\u00edodo das 8h [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-50714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/11\/Policia-Rodoviaria-BPRv-2020.jpg?fit=768%2C512&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50714"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50714\/revisions"}],"predecessor-version":[{"id":50717,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50714\/revisions\/50717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/50715"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}