{"id":50689,"date":"2020-11-03T10:46:33","date_gmt":"2020-11-03T13:46:33","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50689"},"modified":"2020-11-03T10:46:39","modified_gmt":"2020-11-03T13:46:39","slug":"queda-de-energia-eletrica-afeta-abastecimento-de-agua-em-campo-formoso-antonio-goncalves-caem-e-saude","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/queda-de-energia-eletrica-afeta-abastecimento-de-agua-em-campo-formoso-antonio-goncalves-caem-e-saude\/","title":{"rendered":"Queda de energia el\u00e9trica afeta abastecimento de \u00e1gua em Campo Formoso, Ant\u00f4nio Gon\u00e7alves, Ca\u00e9m e Sa\u00fade"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/embasa-informa_2.jpg?resize=498%2C387\" alt=\"\" class=\"wp-image-16835\" width=\"498\" height=\"387\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/embasa-informa_2.jpg?w=360&amp;ssl=1 360w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/embasa-informa_2.jpg?resize=300%2C233&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/embasa-informa_2.jpg?resize=250%2C194&amp;ssl=1 250w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A Embasa informa que o fornecimento de \u00e1gua foi afetado desde ontem (02) nos munic\u00edpios de Campo Formoso, Ant\u00f4nio Gon\u00e7alves, Ca\u00e9m e Sa\u00fade por causa de uma queda de energia el\u00e9trica nas regi\u00f5es da Barragem do Aipim e de Pindoba\u00e7u.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Coelba j\u00e1 foi notificada e j\u00e1 trabalha pra solucionar o problema, cuja conclus\u00e3o permitir\u00e1 \u00e0 Embasa reiniciar os servi\u00e7os de capta\u00e7\u00e3o, tratamento, bombeamento, reserva\u00e7\u00e3o e distribui\u00e7\u00e3o de \u00e1gua nestes munic\u00edpios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Moradores cujos im\u00f3veis possuem reserva\u00e7\u00e3o adequada e suficiente poder\u00e3o sentir menores efeitos da interrup\u00e7\u00e3o, mas \u00e9 recomend\u00e1vel que todos economizem \u00e1gua neste per\u00edodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Embasa informa que o fornecimento de \u00e1gua foi afetado desde ontem (02) nos munic\u00edpios de Campo Formoso, Ant\u00f4nio Gon\u00e7alves, Ca\u00e9m e Sa\u00fade por causa de uma queda de energia el\u00e9trica nas regi\u00f5es da Barragem do Aipim e de Pindoba\u00e7u. A Coelba j\u00e1 foi notificada e j\u00e1 trabalha pra solucionar o problema, cuja conclus\u00e3o permitir\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":["post-50689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/embasa.jpg?fit=350%2C200&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50689"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50689\/revisions"}],"predecessor-version":[{"id":50691,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50689\/revisions\/50691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/3655"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}