{"id":50540,"date":"2020-10-28T21:02:45","date_gmt":"2020-10-29T00:02:45","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50540"},"modified":"2020-10-28T21:02:50","modified_gmt":"2020-10-29T00:02:50","slug":"bahia-registra-1-990-novos-casos-de-covid-19-nas-ultimas-24-horas","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/bahia-registra-1-990-novos-casos-de-covid-19-nas-ultimas-24-horas\/","title":{"rendered":"Bahia registra 1.990 novos casos de Covid-19 nas \u00faltimas 24 horas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/03\/coronavirus_5.jpg?resize=575%2C383\" alt=\"\" class=\"wp-image-42293\" width=\"575\" height=\"383\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/03\/coronavirus_5.jpg?w=360&amp;ssl=1 360w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/03\/coronavirus_5.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/03\/coronavirus_5.jpg?resize=250%2C167&amp;ssl=1 250w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Na Bahia, nas \u00faltimas 24 horas, foram registrados 1.990 casos de Covid-19 (taxa de crescimento de +0,6%) e 1.714 recuperados (+0,5%). Dos 349.711 casos confirmados desde o in\u00edcio da pandemia, 334.760 j\u00e1 s\u00e3o considerados recuperados e 7.405 encontram-se ativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O boletim epidemiol\u00f3gico contabiliza ainda 713.055 casos descartados e 84.321 em investiga\u00e7\u00e3o. Na Bahia, 28.760 profissionais da sa\u00fade foram confirmados para Covid-19.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>\u00d3bitos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O boletim epidemiol\u00f3gico de hoje contabiliza 27 \u00f3bitos que ocorreram em diversas datas. O n\u00famero total de \u00f3bitos por Covid-19 na Bahia desde o in\u00edcio da pandemia \u00e9 de 7.546, representando uma letalidade de 2,16%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Bahia, nas \u00faltimas 24 horas, foram registrados 1.990 casos de Covid-19 (taxa de crescimento de +0,6%) e 1.714 recuperados (+0,5%). Dos 349.711 casos confirmados desde o in\u00edcio da pandemia, 334.760 j\u00e1 s\u00e3o considerados recuperados e 7.405 encontram-se ativos. O boletim epidemiol\u00f3gico contabiliza ainda 713.055 casos descartados e 84.321 em investiga\u00e7\u00e3o. Na Bahia, 28.760 profissionais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":43990,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-50540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/05\/SESAB_BoletimCoronavirus.jpeg?fit=1280%2C853&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50540"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50540\/revisions"}],"predecessor-version":[{"id":50542,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50540\/revisions\/50542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/43990"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}