{"id":50373,"date":"2020-10-24T15:00:40","date_gmt":"2020-10-24T18:00:40","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=50373"},"modified":"2020-10-24T15:01:45","modified_gmt":"2020-10-24T18:01:45","slug":"inss-pagamento-de-beneficios-nao-sera-suspenso-por-falta-de-reabilitacao-profissional","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/inss-pagamento-de-beneficios-nao-sera-suspenso-por-falta-de-reabilitacao-profissional\/","title":{"rendered":"INSS: Pagamento de benef\u00edcios n\u00e3o ser\u00e1 suspenso por falta de reabilita\u00e7\u00e3o profissional"},"content":{"rendered":"\n<h5 class=\"has-text-align-center wp-block-heading\"><em>Os benefici\u00e1rios do INSS que ficarem impossibilitados de participar do Programa de Reabilita\u00e7\u00e3o Profissional n\u00e3o ter\u00e3o seus pagamentos suspensos nos meses de novembro e dezembro<\/em><\/h5>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?resize=768%2C460\" alt=\"\" class=\"wp-image-50374\" width=\"768\" height=\"460\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?resize=1024%2C613&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?resize=300%2C179&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?resize=768%2C459&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?w=1170&amp;ssl=1 1170w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption><em>Instituto Nacional do Seguro Social (INSS) &#8211; Foto: Ag\u00eancia Brasil<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Os benefici\u00e1rios do INSS que ficarem impossibilitados de participar do Programa de Reabilita\u00e7\u00e3o Profissional n\u00e3o ter\u00e3o seus pagamentos suspensos nos meses de novembro e dezembro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decis\u00e3o publicada em portaria no Di\u00e1rio Oficial da Uni\u00e3o visa as medidas de enfrentamento da pandemia da Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A reabilita\u00e7\u00e3o profissional \u00e9 obrigat\u00f3ria e visa proporcionar meios indicados para reingresso no mercado de trabalho ao benefici\u00e1rio incapacitado, parcial ou totalmente, para trabalhar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os benefici\u00e1rios do INSS que ficarem impossibilitados de participar do Programa de Reabilita\u00e7\u00e3o Profissional n\u00e3o ter\u00e3o seus pagamentos suspensos nos meses de novembro e dezembro Os benefici\u00e1rios do INSS que ficarem impossibilitados de participar do Programa de Reabilita\u00e7\u00e3o Profissional n\u00e3o ter\u00e3o seus pagamentos suspensos nos meses de novembro e dezembro. A decis\u00e3o publicada em portaria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-50373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2020\/10\/INSS-2020.jpg?fit=1170%2C700&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=50373"}],"version-history":[{"count":3,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50373\/revisions"}],"predecessor-version":[{"id":50377,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/50373\/revisions\/50377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/50374"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=50373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=50373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=50373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}