{"id":4879,"date":"2015-10-16T09:06:22","date_gmt":"2015-10-16T12:06:22","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4879"},"modified":"2015-10-16T09:06:22","modified_gmt":"2015-10-16T12:06:22","slug":"governo-do-estado-realiza-em-bonfim-encontro-de-comunicadores-do-centro-norte-da-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/governo-do-estado-realiza-em-bonfim-encontro-de-comunicadores-do-centro-norte-da-bahia\/","title":{"rendered":"Governo do estado realiza em Bonfim encontro de comunicadores do Centro-Norte da Bahia"},"content":{"rendered":"<figure id=\"attachment_4880\" aria-describedby=\"caption-attachment-4880\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4880 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg?resize=320%2C170\" alt=\"Andre Curvello\" width=\"320\" height=\"170\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg?w=320&amp;ssl=1 320w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg?resize=300%2C159&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg?resize=250%2C133&amp;ssl=1 250w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-4880\" class=\"wp-caption-text\">Jornalista Andr\u00e9 Curvello, Secret\u00e1rio de Comunica\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Como parte das a\u00e7\u00f5es de interioriza\u00e7\u00e3o da Comunica\u00e7\u00e3o Social, o Governo da Bahia participa de um encontro com profissionais e empresas do setor do Centro-Norte baiano, nesta sexta (16), a partir das 18h, em Senhor do Bonfim. Estar\u00e3o presentes o secret\u00e1rio estadual de Comunica\u00e7\u00e3o, jornalista Andr\u00e9 Curvello, e t\u00e9cnicos da Secom. O evento acontecer\u00e1 na C\u00e2mara de Vereadores. Na pauta, os objetivos e os desafios da comunica\u00e7\u00e3o de governo, bem como atendimento a jornalistas, radialistas, m\u00eddias, comunicadores, publicit\u00e1rios e empres\u00e1rios da \u00e1rea da comunica\u00e7\u00e3o.<\/p>\n<p>Para Andr\u00e9 Curvello a agenda ajuda a estreitar ainda mais a rela\u00e7\u00e3o institucional com os formadores de opini\u00e3o e empres\u00e1rios, bem como apresentar as diferentes \u00e1reas de atendimento da Secom a fim de facilitar o acesso dos profissionais de comunica\u00e7\u00e3o \u00e0s informa\u00e7\u00f5es de governo e a divulga\u00e7\u00e3o das realiza\u00e7\u00f5es da atual gest\u00e3o, al\u00e9m de promover um servi\u00e7o de melhor qualidade ao setor.<\/p>\n<p>O governo da Bahia tem buscado otimizar a presta\u00e7\u00e3o de servi\u00e7o \u00e0 m\u00eddia do interior do Estado, garantindo maior participa\u00e7\u00e3o dos profissionais e dos ve\u00edculos de comunica\u00e7\u00e3o nas a\u00e7\u00f5es desenvolvidas pela Secom. Tamb\u00e9m j\u00e1 foram direcionados mais recursos em publicidade regional como forma de incentivar e fomentar a atividade em cidades de pequeno, m\u00e9dio e grande portes, favorecendo o desenvolvimento local. Outra iniciativa positiva \u00e9 a contrata\u00e7\u00e3o de produtoras regionais para os conte\u00fados de publicidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte das a\u00e7\u00f5es de interioriza\u00e7\u00e3o da Comunica\u00e7\u00e3o Social, o Governo da Bahia participa de um encontro com profissionais e empresas do setor do Centro-Norte baiano, nesta sexta (16), a partir das 18h, em Senhor do Bonfim. Estar\u00e3o presentes o secret\u00e1rio estadual de Comunica\u00e7\u00e3o, jornalista Andr\u00e9 Curvello, e t\u00e9cnicos da Secom. O evento acontecer\u00e1 na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,4],"tags":[],"class_list":["post-4879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/Andre-Curvello.jpg?fit=320%2C170&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4879"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4879\/revisions"}],"predecessor-version":[{"id":4881,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4879\/revisions\/4881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4880"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}