{"id":4753,"date":"2015-10-11T20:43:49","date_gmt":"2015-10-11T23:43:49","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4753"},"modified":"2015-10-11T20:43:49","modified_gmt":"2015-10-11T23:43:49","slug":"papa-deve-vir-para-a-festa-de-nossa-senhora-aparecida-em-2017","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/papa-deve-vir-para-a-festa-de-nossa-senhora-aparecida-em-2017\/","title":{"rendered":"Papa deve vir para a festa de Nossa Senhora Aparecida em 2017"},"content":{"rendered":"<figure id=\"attachment_4754\" aria-describedby=\"caption-attachment-4754\" style=\"width: 380px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4754 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg?resize=380%2C280\" alt=\"papa2\" width=\"380\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg?resize=250%2C184&amp;ssl=1 250w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a><figcaption id=\"caption-attachment-4754\" class=\"wp-caption-text\">Foto: Eduardo Santill\u00e1n \/ Presidencia de la Rep\u00fablica<\/figcaption><\/figure>\n<p>Aparecida, no Vale do Para\u00edba, realiza neste fim de semana prolongado a Festa de Nossa Senhora que serve de preparativo para os 300 anos de aparecimento da imagem da santa a pescadores no Rio Para\u00edba do Sul.<\/p>\n<p>Para 2016 est\u00e1 prevista a inaugura\u00e7\u00e3o de um campan\u00e1rio composto por 13 sinos e aproximadamente 38 metros, desenhado pelo arquiteto Oscar Niemeyer, morto em 2012. A obra foi um dos \u00faltimos projetos do renomado profissional, que apesar de ateu, desenhou v\u00e1rias igrejas.<\/p>\n<p>Em 2017, durante a visita do Papa Francisco, deve ser inaugurada a c\u00fapula central do Santu\u00e1rio Nacional, que est\u00e1 fechada desde 2013 para receber 5 milh\u00f5es de pastilhas de vidro fabricadas em Veneza, na It\u00e1lia, com a forma\u00e7\u00e3o que simboliza a \u00e1rvore da vida e p\u00e1ssaros da fauna brasileira, remetendo aos peregrinos que visitam o espa\u00e7o religioso.<\/p>\n<p><em>*Bahia Not\u00edcias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aparecida, no Vale do Para\u00edba, realiza neste fim de semana prolongado a Festa de Nossa Senhora que serve de preparativo para os 300 anos de aparecimento da imagem da santa a pescadores no Rio Para\u00edba do Sul. Para 2016 est\u00e1 prevista a inaugura\u00e7\u00e3o de um campan\u00e1rio composto por 13 sinos e aproximadamente 38 metros, desenhado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,1],"tags":[],"class_list":["post-4753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/papa2.jpg?fit=380%2C280&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4753"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4753\/revisions"}],"predecessor-version":[{"id":4755,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4753\/revisions\/4755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4754"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}