{"id":4723,"date":"2015-10-10T22:21:21","date_gmt":"2015-10-11T01:21:21","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4723"},"modified":"2015-10-10T22:21:21","modified_gmt":"2015-10-11T01:21:21","slug":"lideres-da-oposicao-defendem-afastamento-de-eduardo-cunha","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/lideres-da-oposicao-defendem-afastamento-de-eduardo-cunha\/","title":{"rendered":"L\u00edderes da oposi\u00e7\u00e3o defendem afastamento de Eduardo Cunha"},"content":{"rendered":"<p><em><strong>Nota foi assinada pelo PSDB, Solidariedade, PSB, DEM, PPS e Minoria.\u00a0Documentos do Minist\u00e9rio P\u00fablico indicam recursos de Cunha no exterior<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-4476 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg?resize=300%2C300\" alt=\"eduardo_cunha\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/eduardo_cunha.jpg?resize=48%2C48&amp;ssl=1 48w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>L\u00edderes de partidos de oposi\u00e7\u00e3o na C\u00e2mara defenderam neste s\u00e1bado (10) o afastamento de Eduardo Cunha (PMDB-RJ) da Presid\u00eancia da C\u00e2mara dos Deputados, a partir da revela\u00e7\u00e3o de detalhes sobre contas que ele supostamente mantinha na Su\u00ed\u00e7a.\u00a0Por meio de nota \u00e0 imprensa, os l\u00edderes do PSDB, Solidariedade, PSB, DEM, PPS e Minoria na Casa (bloco que re\u00fane os oposicionistas) pedem que ele se afaste do cargo &#8220;at\u00e9 mesmo para que ele possa exercer, de forma adequada, o seu direito constitucional \u00e0 ampla defesa&#8221;.<\/p>\n<p>&#8220;Sobre as den\u00fancias contra o presidente da C\u00e2mara, Eduardo Cunha, noticiadas pela imprensa, os l\u00edderes Carlos Sampaio [PSDB-SP], Arthur Maia [SD-BA], Fernando Bezerra Filho [PSB-PE], Mendon\u00e7a Filho [DEM-PE], Rubens Bueno [PPS-PR] e Bruno Ara\u00fajo [PSDB-PE], respectivamente do PSDB, Solidariedade, PSB, DEM, PPS e Minoria, entendem que ele deve afastar-se do cargo, at\u00e9 mesmo para que possa exercer, de forma adequada, o seu direito constitucional \u00e0 ampla defesa&#8221;, diz a nota.<\/p>\n<p>Pouco depois do pedido de afastamento feito pelos l\u00edderes dos partidos de oposi\u00e7\u00e3o, a assessoria de imprensa do presidente da C\u00e2mara, Eduardo Cunha, divulgou nota \u00e0 imprensa na qual ele reafirma que permanecer\u00e1 no cargo.<\/p>\n<p>Mais cedo neste s\u00e1bado, em entrevista \u00e0 GloboNews por telefone, Cunha disse que n\u00e3o renunciar\u00e1 \u00e0 presid\u00eancia da C\u00e2mara apesar das novas revela\u00e7\u00f5es envolvendo contas atribu\u00eddas a ele na Sui\u00e7a.<br \/>\n&#8220;Pode pressionar, eu n\u00e3o renuncio. Sem a menor chance. Podem retirar apoio, fazer o que quiserem. Tenho amplo direito de defesa. N\u00e3o podem me tirar&#8221;, afirmou ele.<\/p>\n<p>Os l\u00edderes passaram a manh\u00e3 e a tarde deste s\u00e1bado conversando, por telefone, sobre a situa\u00e7\u00e3o do peemedebista, que em julho, declarou ades\u00e3o \u00e0 oposi\u00e7\u00e3o ao governo e deu diversos cargos de comando a oposicionistas em comiss\u00f5es e relatorias de projetos importantes na pauta da Casa.<br \/>\nAo G1, o l\u00edder do PPS, Rubens Bueno (PR), resumiu o tom das conversas. &#8220;N\u00e3o pode contaminar o processo de um presidente da Casa nesta situa\u00e7\u00e3o. Ontem foi um dia que pesou muito&#8221;, afirmou.<\/p>\n<p><em>*G1 Bras\u00edlia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota foi assinada pelo PSDB, Solidariedade, PSB, DEM, PPS e Minoria.\u00a0Documentos do Minist\u00e9rio P\u00fablico indicam recursos de Cunha no exterior L\u00edderes de partidos de oposi\u00e7\u00e3o na C\u00e2mara defenderam neste s\u00e1bado (10) o afastamento de Eduardo Cunha (PMDB-RJ) da Presid\u00eancia da C\u00e2mara dos Deputados, a partir da revela\u00e7\u00e3o de detalhes sobre contas que ele supostamente mantinha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,3],"tags":[],"class_list":["post-4723","post","type-post","status-publish","format-standard","hentry","category-noticias","category-politica"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4723"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4723\/revisions"}],"predecessor-version":[{"id":4724,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4723\/revisions\/4724"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}