{"id":4616,"date":"2015-10-07T09:03:30","date_gmt":"2015-10-07T12:03:30","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4616"},"modified":"2020-08-21T15:48:07","modified_gmt":"2020-08-21T18:48:07","slug":"07-de-outubro-dia-do-compositor-brasileiro","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/07-de-outubro-dia-do-compositor-brasileiro\/","title":{"rendered":"07 DE OUTUBRO &#8211; Dia do Compositor Brasileiro"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4617 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg?resize=300%2C240\" alt=\"dia-do-compositor\" width=\"300\" height=\"240\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg?resize=250%2C200&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg?w=757&amp;ssl=1 757w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Neste quesito, o Brasil conta com muitos representantes que justificam a cria\u00e7\u00e3o da data. Entre os grandes nomes, est\u00e1 Heitor Villa-Lobos, nascido em 1887, no Rio de Janeiro. Sua obra tamb\u00e9m foi importante para formar o conceito de nacionalismo musical e, ao mesmo tempo, representou a m\u00fasica brasileira em outros pa\u00edses.<\/p>\n<p>Al\u00e9m de Villa-Lobos, o Brasil tamb\u00e9m conta com grandes compositores como Chico Buarque, Gonzaguinha, Tom Jobim, Vin\u00edcius de Moraes, Paulinho da Viola, Nelson Cavaquinho, Geraldo Pereira, Alceu Valen\u00e7a, Cartola, Noel Rosa, Ivan Lins, Jo\u00e3o Gilberto, Caetano Veloso, Gilberto Gil, Lenine, Chico Science, Cazuza, Raul Seixas e muitos outros. (<em>*Metro 1<\/em>).<\/p>\n<p><strong>BLOG DO ELOILTON CAJUHY &#8211;\u00a0<\/strong>E esta data \u00e9 uma boa oportunidade de lembrarmos grandes compositores da m\u00fasica bonfinense: Luiz Moreira, Miguel Ara\u00fajo, C\u00e9sar Xisto, Daniel Gomes, Rog\u00e9rio Moreira, Wilson Guimar\u00e3es, Mauro Coelho, Zaca do Acordeon, Zecrinha, Binha Campelo, Jo\u00e3o Am\u00e9rico, Hyldon &#8211; autor de &#8220;Na Chuva, Na Fazenda&#8221;, L\u00facio Barbosa &#8211; autor do grande sucesso &#8220;Cidad\u00e3o&#8221;, gravado por S\u00edlvio Brito, Z\u00e9 Ramalho, Luiz Gonzaga e outros, e os saudosos Oswaldo Arag\u00e3o, Del Carneiro e Deny Barreto, dentre tantos outros. A todos, nossa homenagem neste dia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste quesito, o Brasil conta com muitos representantes que justificam a cria\u00e7\u00e3o da data. Entre os grandes nomes, est\u00e1 Heitor Villa-Lobos, nascido em 1887, no Rio de Janeiro. Sua obra tamb\u00e9m foi importante para formar o conceito de nacionalismo musical e, ao mesmo tempo, representou a m\u00fasica brasileira em outros pa\u00edses. Al\u00e9m de Villa-Lobos, o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[8,1],"tags":[],"class_list":["post-4616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/10\/dia-do-compositor.jpg?fit=757%2C606&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4616"}],"version-history":[{"count":3,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4616\/revisions"}],"predecessor-version":[{"id":48371,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4616\/revisions\/48371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4617"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}