{"id":4572,"date":"2015-10-05T09:13:28","date_gmt":"2015-10-05T12:13:28","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4572"},"modified":"2015-10-05T09:13:28","modified_gmt":"2015-10-05T12:13:28","slug":"governador-determina-suspensao-da-vistoria-veicular-periodica-para-licenciamento-de-automoveis","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/governador-determina-suspensao-da-vistoria-veicular-periodica-para-licenciamento-de-automoveis\/","title":{"rendered":"Governador determina suspens\u00e3o da vistoria veicular peri\u00f3dica para licenciamento de autom\u00f3veis"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/Rui-Costa2.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3031\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/Rui-Costa2.jpg?resize=380%2C280\" alt=\"Rui Costa2\" width=\"380\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/Rui-Costa2.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/Rui-Costa2.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/08\/Rui-Costa2.jpg?resize=250%2C184&amp;ssl=1 250w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a>O governador Rui Costa determinou a suspens\u00e3o imediata da obrigatoriedade de vistoria veicular peri\u00f3dica para licenciamento anual de autom\u00f3veis, conforme estabelece a Portaria n\u00ba 2045\/2012, do Departamento Estadual de Tr\u00e2nsito da Bahia (Detran-BA). A revoga\u00e7\u00e3o do procedimento tem validade a partir desta segunda-feira (5). Ele tamb\u00e9m determinou que a Procuradoria Geral do Estado (PGE) elabore parecer sobre a mat\u00e9ria, com o objetivo de fundamentar a decis\u00e3o final do Governo do Estado sobre a quest\u00e3o.<\/p>\n<p>Antes de embarcar para a primeira viagem oficial \u00e0 Europa, na tarde de domingo (4), o governador explicou que levou em considera\u00e7\u00e3o os questionamentos feitos pelo Minist\u00e9rio P\u00fablico da Bahia (MP-BA) e pela Associa\u00e7\u00e3o Baiana de Defesa e Prote\u00e7\u00e3o aos Condutores de Ve\u00edculos (ABCV) para aplicar a medida. \u201cDesta maneira, vamos garantir tamb\u00e9m a desonera\u00e7\u00e3o do cidad\u00e3o&#8221;, acrescentou Rui. Ele explicou ainda que a vistoria no modelo atual estar\u00e1 suspensa at\u00e9 parecer da PGE.<\/p>\n<p>Continuar\u00e1 obrigat\u00f3ria a realiza\u00e7\u00e3o de vistoria veicular para transfer\u00eancia de propriedade ou de domic\u00edlio intermunicipal ou interestadual do propriet\u00e1rio do ve\u00edculo, norma definida pelo Departamento Nacional de Tr\u00e2nsito (Denatran) e aplicada em todos os estados brasileiros.<\/p>\n<p>De acordo com o diretor-geral do Detran-BA, Mauricio Bacelar, \u201cal\u00e9m da suspender a vistoria que estava sendo realizada nos autom\u00f3veis com mais de cinco anos desde janeiro deste ano, n\u00f3s vamos consultar formalmente o Denatran [Departamento Nacional de Tr\u00e2nsito] para que o \u00f3rg\u00e3o federal emita parecer sobre a portaria, mesmo ciente de que \u00e9 compet\u00eancia do Detran estadual estabelecer as condi\u00e7\u00f5es de licenciamento\u201d.<\/p>\n<p>Publicada em dezembro de 2012, a Portaria 2045\/2012 tornou obrigat\u00f3ria a vistoria para o licenciamento anual para autom\u00f3veis com mais de 10 anos, a partir de janeiro de 2014; com mais de cinco anos, a partir de janeiro de 2015; e com mais de um ano, a partir de 1\u00ba de janeiro de 2016.<\/p>\n<p><em>*Secom-Bahia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Rui Costa determinou a suspens\u00e3o imediata da obrigatoriedade de vistoria veicular peri\u00f3dica para licenciamento anual de autom\u00f3veis, conforme estabelece a Portaria n\u00ba 2045\/2012, do Departamento Estadual de Tr\u00e2nsito da Bahia (Detran-BA). A revoga\u00e7\u00e3o do procedimento tem validade a partir desta segunda-feira (5). Ele tamb\u00e9m determinou que a Procuradoria Geral do Estado (PGE) elabore [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,1],"tags":[],"class_list":["post-4572","post","type-post","status-publish","format-standard","hentry","category-cotidiano","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4572"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4572\/revisions"}],"predecessor-version":[{"id":4573,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4572\/revisions\/4573"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}