{"id":4519,"date":"2015-10-03T11:11:54","date_gmt":"2015-10-03T14:11:54","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4519"},"modified":"2015-10-03T11:11:55","modified_gmt":"2015-10-03T14:11:55","slug":"carlos-brasileiro-esclarece-sobre-pedido-de-julgamento-de-suas-contas-na-camara","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/carlos-brasileiro-esclarece-sobre-pedido-de-julgamento-de-suas-contas-na-camara\/","title":{"rendered":"Carlos Brasileiro esclarece sobre pedido de julgamento de suas contas na C\u00e2mara"},"content":{"rendered":"<p>O ex-prefeito de Senhor do Bonfim, Carlos Brasileiro, emitiu nota de esclarecimento para falar sobre um pedido entregue \u00e0 C\u00e2mara Municipal de Senhor do Bonfim, solicitando que sejam colocadas em julgamento suas contas de 2001, que teve parecer pr\u00e9vio de rejei\u00e7\u00e3o pelo Tribunal de Contas dos Munic\u00edpios, em 2002.<\/p>\n<p><strong><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/07\/Carlos-Brasileiro.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2390\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/07\/Carlos-Brasileiro.jpg?resize=380%2C280\" alt=\"Carlos Brasileiro\" width=\"380\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/07\/Carlos-Brasileiro.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/07\/Carlos-Brasileiro.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/07\/Carlos-Brasileiro.jpg?resize=250%2C184&amp;ssl=1 250w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a>Confira o teor da nota de Brasileiro:<\/strong><\/p>\n<p><em><strong>&#8220;O\u00a0ex-deputado e ex-prefeito Carlos Brasileiro presta esclarecimentos para que a verdade seja estabelecida perante ao povo bonfinense.<\/strong><\/em><\/p>\n<p><em><strong>Cabe informar que, ao contr\u00e1rio do citado pelo cidad\u00e3o em evid\u00eancia, o ex-prefeito n\u00e3o \u00e9 \u201cficha suja\u201d. As falhas apontadas no parecer pr\u00e9vio do Tribunal de Contas dos Munic\u00edpios (TCM) das contas de 2001, julgadas em 2002, n\u00e3o trouxeram qualquer tipo de preju\u00edzo ao er\u00e1rio, n\u00e3o representaram desvio de recursos, falta de transfer\u00eancia, malversa\u00e7\u00e3o ou qualquer outro ato que desabone a conduta do ent\u00e3o gestor ou resulte em desvio de finalidade. <\/strong><\/em><\/p>\n<p><em><strong>V\u00e1rios juristas j\u00e1 ratificaram que a inelegibilidade s\u00f3 acontece nos casos em que as contas sejam rejeitadas por dolo, m\u00e1 f\u00e9 ou improbidade, o que inexiste no parecer do TCM em rela\u00e7\u00e3o \u00e0s contas de 2001 do ex-prefeito Carlos Brasileiro.<\/strong><\/em><\/p>\n<p><em><strong>O TCM apontou que a Prefeitura, na \u00e9poca, n\u00e3o teria cumprido o m\u00ednimo de investimento na sa\u00fade. Isto ocorreu, no entanto, porque o Tribunal n\u00e3o contabilizou o direcionamento de recursos para o Hospital Regional como sendo da \u00e1rea de sa\u00fade.<\/strong><\/em><\/p>\n<p><em><strong>Brasileiro lamenta que, passados 13 anos do julgamento pelo TCM, pessoas ainda tentem utilizar este argumento, buscando criar novos fatos, como forma de tentar bloque\u00e1-lo do processo democr\u00e1tico. Por duas vezes, a C\u00e2mara Municipal realizou o processo para vota\u00e7\u00e3o. Mas, a justi\u00e7a acatou a\u00e7\u00f5es movidas por Brasileiro, em fun\u00e7\u00e3o de v\u00e1rios erros de natureza processual.<\/strong><\/em><\/p>\n<p><em><strong>O povo bonfinense merece a verdade e que prevale\u00e7a na pol\u00edtica os m\u00e9todos justos, \u00e9ticos e dentro do Estado Democr\u00e1tico de Direito&#8221;.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito de Senhor do Bonfim, Carlos Brasileiro, emitiu nota de esclarecimento para falar sobre um pedido entregue \u00e0 C\u00e2mara Municipal de Senhor do Bonfim, solicitando que sejam colocadas em julgamento suas contas de 2001, que teve parecer pr\u00e9vio de rejei\u00e7\u00e3o pelo Tribunal de Contas dos Munic\u00edpios, em 2002. Confira o teor da nota de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,3,4],"tags":[],"class_list":["post-4519","post","type-post","status-publish","format-standard","hentry","category-noticias","category-politica","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4519"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4519\/revisions"}],"predecessor-version":[{"id":4520,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4519\/revisions\/4520"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}