{"id":4301,"date":"2015-09-25T18:38:58","date_gmt":"2015-09-25T21:38:58","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4301"},"modified":"2015-09-25T18:38:58","modified_gmt":"2015-09-25T21:38:58","slug":"servidores-do-inss-suspendem-greve-na-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/servidores-do-inss-suspendem-greve-na-bahia\/","title":{"rendered":"Servidores do INSS suspendem greve na Bahia"},"content":{"rendered":"<p><em><strong>Servidores devem voltar a trabalhar na ter\u00e7a ap\u00f3s assinatura de acordo.\u00a0Entre reivindica\u00e7\u00f5es de funcion\u00e1rios estava reajuste salarial de 27,5%<\/strong><\/em><\/p>\n<figure id=\"attachment_4302\" aria-describedby=\"caption-attachment-4302\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4302 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg?resize=620%2C465\" alt=\"inss_assembleia\" width=\"620\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg?w=620&amp;ssl=1 620w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-4302\" class=\"wp-caption-text\">Assembleia reuniu servidores na Bahia, que decidiram encerrar greve (Foto: J\u00e9ssica Smetak\/TV Bahia)<\/figcaption><\/figure>\n<p>Os servidores do INSS na Bahia decidiram suspender a greve da categoria em assembleia nesta sexta-feira (25), em Salvador, segundo informou ao G1 Ricardo Sampaio, coordenador do comando de greve baiano. A paralisa\u00e7\u00e3o no estado come\u00e7ou no dia 7 de julho, em ades\u00e3o \u00e0 greve nacional.<\/p>\n<p>Os servidores aceitaram a proposta de aumento do governo: 10,8%. Uma parte ser\u00e1 paga em agosto do ano que vem e outra em janeiro de 2017. Al\u00e9m da Bahia, a situa\u00e7\u00e3o j\u00e1 est\u00e1 definida nos estados do AC, AL, AM, AP, PE, PI, SE e SP. Com o fim da mobiliza\u00e7\u00e3o, a categoria na Bahia deve retomar as atividades na ter\u00e7a-feira (29), ap\u00f3s assinatura de acordo com o governo, que deve acontecer na segunda-feira (28).<\/p>\n<p>&#8220;Se o governo n\u00e3o cumprir o acordo, a gente retorna [para a greve]. A assinatura do acordo vai ser na segunda-feira [28] e os servidores voltam ao trabalho na ter\u00e7a [29], ap\u00f3s a assinatura. O acordo prev\u00ea tudo o que foi pedido na greve, mas, mesmo ap\u00f3s a assinatura, continuamos com a greve suspensa porque tem muita coisa em aberto, como a reestrutura\u00e7\u00e3o de carreira&#8221;, informou Ricardo Sampaio.<\/p>\n<p>Al\u00e9m dos servidores administrativos, os peritos do INSS tamb\u00e9m est\u00e3o em greve em todo o pa\u00eds. A paralisa\u00e7\u00e3o come\u00e7ou no dia 4 de setembro e, segundo a Associa\u00e7\u00e3o Nacional dos M\u00e9dicos Peritos em Previd\u00eancia Social, ainda n\u00e3o h\u00e1 previs\u00e3o de fim do movimento. A greve dos m\u00e9dicos do INSS na Bahia afeta 95% das per\u00edcias no estado.<\/p>\n<p><em>*G1 Bahia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servidores devem voltar a trabalhar na ter\u00e7a ap\u00f3s assinatura de acordo.\u00a0Entre reivindica\u00e7\u00f5es de funcion\u00e1rios estava reajuste salarial de 27,5% Os servidores do INSS na Bahia decidiram suspender a greve da categoria em assembleia nesta sexta-feira (25), em Salvador, segundo informou ao G1 Ricardo Sampaio, coordenador do comando de greve baiano. A paralisa\u00e7\u00e3o no estado come\u00e7ou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,1],"tags":[],"class_list":["post-4301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/inss_assembleia.jpg?fit=620%2C465&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4301"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4301\/revisions"}],"predecessor-version":[{"id":4303,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4301\/revisions\/4303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4302"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}