{"id":4292,"date":"2015-09-25T09:37:32","date_gmt":"2015-09-25T12:37:32","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4292"},"modified":"2015-09-25T09:37:32","modified_gmt":"2015-09-25T12:37:32","slug":"25-de-setembro-dia-do-radio-e-da-radiodifusao-e-dia-nacional-do-transito","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/25-de-setembro-dia-do-radio-e-da-radiodifusao-e-dia-nacional-do-transito\/","title":{"rendered":"25 DE SETEMBRO &#8211; Dia do R\u00e1dio e da Radiodifus\u00e3o e Dia Nacional do Tr\u00e2nsito"},"content":{"rendered":"<p><strong>&#8211; Dia do R\u00e1dio e da Radiodifus\u00e3o<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/radio.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-4293 alignright\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/radio.jpg?resize=200%2C140\" alt=\"radio\" width=\"200\" height=\"140\" \/><\/a>A primeira emissora de r\u00e1dio no Brasil, foi fundada em 20 de abril de 1923, tendo como fundador Edgar Roquete Pinto, na Academia Brasileira de Ci\u00eancias, a R\u00e1dio Sociedade do Rio de Janeiro. Logo depois veio a R\u00e1dio Clube do Brasil, fundada por Elba Dias.<\/p>\n<p>Mas, a primeira transmiss\u00e3o do R\u00e1dio foi no dia 07 de setembro de 1922, durante a exposi\u00e7\u00e3o comemorativa do centen\u00e1rio da independ\u00eancia. O discurso do ent\u00e3o Presidente da Rep\u00fablica, Epit\u00e1cio Pessoa, al\u00e9m de ser ouvido no recinto da exposi\u00e7\u00e3o, chegou tamb\u00e9m em Niter\u00f3i, Petr\u00f3polis e S\u00e3o Paulo, gra\u00e7as \u00e0 instala\u00e7\u00e3o de uma retransmissora no Corcovado e de aparelhos de recep\u00e7\u00e3o nesses locais.<\/p>\n<p>Hoje s\u00e3o milhares de r\u00e1dios espalhadas pelo pa\u00eds, levando alegria, entretenimento e informa\u00e7\u00e3o para um Brasil de audi\u00eancia e, principalmente, ao ouvinte que sempre fez do R\u00e1dio, seu grande companheiro.<\/p>\n<p><em>*www.toninholima.com.br<\/em><\/p>\n<p><strong>&#8211; Dia Nacional do Tr\u00e2nsito<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4294 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg?resize=300%2C199\" alt=\"transito\" width=\"300\" height=\"199\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg?resize=250%2C166&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg?w=380&amp;ssl=1 380w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A cria\u00e7\u00e3o do Dia Nacional do Tr\u00e2nsito ocorreu a partir da cria\u00e7\u00e3o do C\u00f3digo Nacional de Tr\u00e2nsito em 1997. O objetivo era estabelecer uma campanha intensificada de conscientiza\u00e7\u00e3o das pessoas sobre o seu comportamento utilizando ve\u00edculos ou agindo como pedestres. Geralmente, essa campanha \u00e9 desenvolvida na Semana Nacional de Conscientiza\u00e7\u00e3o no Tr\u00e2nsito.<\/p>\n<p>No Brasil, as estat\u00edsticas referentes aos acidentes de tr\u00e2nsito s\u00e3o alarmantes. Dados recentes divulgados pelo Observat\u00f3rio Nacional de Seguran\u00e7a Vi\u00e1ria referentes ao ano de 2013 asseguram que morrem mais pessoas nesse tipo de acidente do que, por exemplo, de c\u00e2ncer. A maioria desses acidentes est\u00e1 relacionada com infra\u00e7\u00f5es cometidas pelos motoristas e at\u00e9 pelos pedestres, dentre as quais, destacam-se:<\/p>\n<p>Uso do celular com o ve\u00edculo em movimento;<\/p>\n<p>Dirigir alcoolizado;<\/p>\n<p>Excesso de velocidade;<\/p>\n<p>A n\u00e3o utiliza\u00e7\u00e3o correta da sinaliza\u00e7\u00e3o do carro (seta, luz de alerta, far\u00f3is, etc.);<\/p>\n<p>N\u00e3o tomar dist\u00e2ncia segura em rela\u00e7\u00e3o ao ve\u00edculo da frente (algo comum nas rodovias);<\/p>\n<p>Falta de manuten\u00e7\u00e3o t\u00e9cnica do ve\u00edculo (motor, combust\u00edvel, \u00f3leo, freios, pneus e demais equipamentos e acess\u00f3rios do carro);<\/p>\n<p>A n\u00e3o utiliza\u00e7\u00e3o do cinto de seguran\u00e7a e outros itens de seguran\u00e7a;<\/p>\n<p>O desrespeito ou o desconhecimento da sinaliza\u00e7\u00e3o do tr\u00e2nsito;<\/p>\n<p>O desrespeito ou o desconhecimento das leis de tr\u00e2nsito.<\/p>\n<p>Ao longo dos \u00faltimos anos, o tr\u00e2nsito conheceu um aumento em seu n\u00famero total de acidentes que colocou o Brasil em quarto lugar no ranking de maior n\u00famero de mortes em acidentes de tr\u00e2nsito por ano, atr\u00e1s somente de China, \u00cdndia e Nig\u00e9ria.<\/p>\n<p>Em 2010, esse n\u00famero foi de 42.844 \u00f3bitos, perfazendo um total de 22 mortes para cada 100 mil habitantes. J\u00e1 em 2014, o n\u00famero pulou para 48.349, segundo estimativas elaboradas pelo Instituto Avante Brasil.<\/p>\n<p><em>*Brasil Escola<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Dia do R\u00e1dio e da Radiodifus\u00e3o A primeira emissora de r\u00e1dio no Brasil, foi fundada em 20 de abril de 1923, tendo como fundador Edgar Roquete Pinto, na Academia Brasileira de Ci\u00eancias, a R\u00e1dio Sociedade do Rio de Janeiro. Logo depois veio a R\u00e1dio Clube do Brasil, fundada por Elba Dias. Mas, a primeira [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,1],"tags":[],"class_list":["post-4292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/transito.jpg?fit=380%2C252&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4292"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4292\/revisions"}],"predecessor-version":[{"id":4295,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4292\/revisions\/4295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4294"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}